{"id":99289,"date":"2023-12-23T14:07:54","date_gmt":"2023-12-23T14:07:54","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2023\/12\/23\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad\/"},"modified":"2023-12-23T14:07:54","modified_gmt":"2023-12-23T14:07:54","slug":"mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2023\/12\/23\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad\/","title":{"rendered":"M\u00e1s de 700 empleados de Airbus sufren una intoxicaci\u00f3n grave despu\u00e9s de una cena de Navidad"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad.jpg\"><\/p>\n<div readability=\"32\">\n<p><span>Publicado:<\/span><time class=\"Timestamp-root Timestamp-isBlackColor \" datetime=\"2023-12-23T14:07:54+00:00\"> 23 dic 2023 14:07 GMT <\/time><\/p>\n<\/div>\n<div readability=\"33\">\n<p> De momento se desconoce la causa y los resultados de los an\u00e1lisis se dar\u00e1n a conocer la pr\u00f3xima semana. <\/p>\n<\/div>\n<div readability=\"60.796116504854\">\n<p>M\u00e1s de 700 empleados de Airbus Atlantic sufrieron&nbsp;<strong>s\u00edntomas gastrointestinales graves<\/strong> despu\u00e9s de una cena de Navidad celebrada en el comedor de la compa\u00f1\u00eda en Montoir-de-Bretagne, en el noroeste de Francia, <a href=\"https:\/\/www.20minutes.fr\/faits_divers\/4067961-20231222-loire-atlantique-plus-700-salaries-malades-apres-repas-noel-airbus\" target=\"_blank\" rel=\"noopener noreferrer\">informaron<\/a>&nbsp;el s\u00e1bado medios locales.<\/p>\n<p>\u00abM\u00e1s de 700 empleados declararon estar enfermos con signos cl\u00ednicos de v\u00f3mitos o diarrea\u00bb, comunic\u00f3 la Agencia Regional de Salud (ARS).<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-2.jpg 460w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"Mujer invita a sus suegros a comer hongos y el almuerzo termina con 3 personas muertas\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/mas-de-700-empleados-de-airbus-sufren-una-intoxicacion-grave-despues-de-una-cena-de-navidad-3.jpg\" alt=\"Mujer invita a sus suegros a comer hongos y el almuerzo termina con 3 personas muertas\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>Aunque la mayor\u00eda de los invitados experimentaron malestar gastrointestinal al d\u00eda siguiente o dos d\u00edas despu\u00e9s del evento, nadie estaba \u00abgravemente enfermo\u00bb, sostuvo por su parte el Departamento de Comunicaci\u00f3n de la empresa a\u00e9rea.<\/p>\n<p>Una empleada de la compa\u00f1\u00eda dijo que \u00abtuvo que cancelarlo todo\u00bb a causa de la intoxicaci\u00f3n, porque sufr\u00eda \u00abc\u00f3licos y dolores de cabeza como nunca\u00bb. \u00abFue <strong>peor que mi parto<\/strong>\u00ab, asever\u00f3 la mujer, <a href=\"https:\/\/www.ouest-france.fr\/economie\/entreprises\/airbus\/info-ouest-france-a-saint-nazaire-des-centaines-de-malades-apres-un-repas-de-noel-chez-airbus-1ae2dd44-a00a-11ee-9839-768f8ee105c7\" target=\"_blank\" rel=\"noopener noreferrer\">citada<\/a> por Ouest-France. \u00abNadie escap\u00f3\u00bb,&nbsp;<a href=\"https:\/\/www.lefigaro.fr\/nantes\/c-etait-pire-que-mon-accouchement-plus-de-700-convives-intoxiques-apres-un-repas-de-noel-geant-20231222\" target=\"_blank\" rel=\"noopener noreferrer\">coment\u00f3<\/a>&nbsp;otro empleado.<\/p>\n<p>Aunque todav\u00eda no se ha&nbsp;determinado la causa de la intoxicaci\u00f3n masiva, algunos de los afectados consideran que el responsable ser\u00eda el queso Rocamadour que se sirvi\u00f3 en la cena o el <strong>virus de la gastroenteritis<\/strong>, t\u00edpico de esta \u00e9poca del a\u00f1o. Por su parte, la ARS indic\u00f3 que los resultados de las muestras se esperan la pr\u00f3xima semana.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Publicado: 23 dic 2023 14:07 GMT De momento se desconoce la causa y los resultados de los an\u00e1lisis se dar\u00e1n a conocer la pr\u00f3xima semana. M\u00e1s de 700 empleados de Airbus Atlantic sufrieron&nbsp;s\u00edntomas gastrointestinales graves despu\u00e9s de una cena de Navidad celebrada en el comedor de la compa\u00f1\u00eda en Montoir-de-Bretagne, en el noroeste de Francia, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99290,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/99289"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=99289"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/99289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/99290"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=99289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=99289"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=99289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}