{"id":99285,"date":"2023-12-23T07:23:05","date_gmt":"2023-12-23T07:23:05","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/fitness\/vacuum-abdominal-ejercicio-meter-tripa-funciona-facil-si-eres-constante-20231223080944-nt.html"},"modified":"2023-12-23T07:23:05","modified_gmt":"2023-12-23T07:23:05","slug":"vacuum-abdominal-el-ejercicio-facil-de-meter-la-tripa-hacia-dentro-que-funciona-sin-apenas-esfuerzo","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2023\/12\/23\/vacuum-abdominal-el-ejercicio-facil-de-meter-la-tripa-hacia-dentro-que-funciona-sin-apenas-esfuerzo\/","title":{"rendered":"Vacuum abdominal, el ejercicio f\u00e1cil de meter la tripa hacia dentro que funciona sin apenas esfuerzo"},"content":{"rendered":"<p><!-- AUTHOR --> <\/p>\n<div class=\"voc-author-timesocial \"> <!-- AUTHOR --> <\/p>\n<div class=\"voc-author-timesocial__signature\"> <!-- IMAGE AUTHOR --> <picture class=\"voc-image-signature\"> <img class=\"voc-image-signature__img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2023\/12\/vacuum-abdominal-el-ejercicio-facil-de-meter-la-tripa-hacia-dentro-que-funciona-sin-apenas-esfuerzo.jpg\" alt=\"Tamara Vila\"> <\/picture> <!-- INFO AUTHOR --> <\/p>\n<div class=\"voc-author-timesocial__info\">\n<div class=\"voc-author-info\"> <author> <a title=\"TAMARA VILA\" href=\"https:\/\/www.mujerhoy.com\/autor\/tamara-vila-4527.html\" class=\"voc-author\">TAMARA VILA <\/a> <\/author> <time datetime=\"2023-12-23T07:23:05Z\" data-timestamp>Publicado \u00b7 <span data-voc-date-modified-short>23 de diciembre de 2023, 08:23 h<\/span><\/time> <\/div><\/div><\/div><\/div>\n<p> <!-- COMPONENTS --> <\/p>\n<p class=\"voc-paragraph\">No pienses mal: a pesar de su nombre, el <strong>vacuum abdominal <\/strong>no es un procedimiento quir\u00fargico ni una tarea dom\u00e9stica. De hecho, es un tipo de contracci\u00f3n abdominal que se utiliza desde hace d\u00e9cadas en la fisioterapia y el mundo del culturismo. Si bien puede ayudar a <a data-voc-vtm-id=\"in-text-traffic\" href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/aleteo-de-piernas-flutter-kicks-ejericcio-trabaja-abdominales-fortalece-core-20230419133822-nt.html\">fortalecer tu n\u00facleo<\/a> de manera muy sencilla, debes asegurarte de hacerlo correctamente.\n<\/p>\n<p class=\"voc-paragraph\">El ejercicio de vacuum abdominal es una <strong>contracci\u00f3n isom\u00e9trica del transverso del abdomen<\/strong>, que es el m\u00fasculo abdominal m\u00e1s profundo. Este ejercicio tambi\u00e9n se conoce como aspiraci\u00f3n del est\u00f3mago, vaciado del est\u00f3mago o maniobra de tracci\u00f3n abdominal. El transverso del abdomen se coloca horizontalmente (transversal) alrededor del abdomen, casi como un cors\u00e9. Ejercitarlo te ayudar\u00e1 a tener una figura m\u00e1s delgada y vientre plano. \u00a1Y es supersencillo y c\u00f3mo de realizar! Lo puedes hacer en cualquier lugar y en cualquier momento.\n<\/p>\n<p class=\"voc-paragraph\">Dado que el transverso del abdomen se encuentra ubicado profundamente en el n\u00facleo, a algunas personas le puede resultar dif\u00edcil contraerlo o incluso sentirlo. El ejercicio de vacuum abdominal se desarroll\u00f3 para ayudar a las personas a practicar la contracci\u00f3n y el <strong>fortalecimiento del transverso del abdomen<\/strong>. Cuando m\u00e1s fuerte sea este m\u00fasculo y m\u00e1s capaz seas de usarlo, mejor proteger\u00e1s y <a data-voc-vtm-id=\"in-text-traffic\" href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/mejores-ejercicios-prevenir-dolor-espalda-hombros-50-anos-consejos-expertos-20231110090116-nt.html\">sostendr\u00e1s tu columna<\/a> durante el ejercicio y los movimientos cotidianos.\n<\/p>\n<p><h3 class=\"voc-detail__title\"> C\u00f3mo se hace el ejercicio de vacuum abdominal<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Hay muchas formas de hacer el ejercicio de vacuum abdominal, as\u00ed que solo tienes que elegir aquella que mejor se adapta a ti. Una de ellas es <strong>acostada en dec\u00fabito supino<\/strong>. Esta es la versi\u00f3n m\u00e1s conocida y estudiada del ejercicio. Para empezar, te acuestas en el suelo con la columna neutra, las rodillas dobladas y los pies planos.\n<\/p>\n<p class=\"voc-paragraph\">Opcionalmente, puedes poner dos dedos y colocarlos en la parte superior de los huesos de la cadera. Luego, mu\u00e9velos unos dos cent\u00edmetros hacia adentro y hacia abajo. Esto puede resultar \u00fatil para sentir c\u00f3mo se contrae el transverso del abdomen. Respira profundamente por la nariz y exhala lentamente por la boca con los labios fruncidos. Intenta imaginar que est\u00e1s <strong>liberando aire lentamente <\/strong>de un neum\u00e1tico. <\/p>\n<p class=\"voc-paragraph\">Mientras exhalas, <strong>contrae tus abdominales inferiores<\/strong>. Deber\u00edas sentir que el transverso del abdomen se contrae en los dedos. Te puede ser \u00fatil imaginar que empujas el ombligo hacia la parte posterior de la columna. Recuerda contraer los m\u00fasculos abdominales mientras haces esto.\n<\/p>\n<p class=\"voc-paragraph\">Contin\u00faa respirando normalmente mientras sostienes el abdomen. <strong>No debes contener la respiraci\u00f3n<\/strong>, lo cual es una se\u00f1al de que no est\u00e1s contrayendo el transverso del abdomen y est\u00e1s \u00abaspirando\u00bb. Intenta mantener esta posici\u00f3n durante al menos 20 a 30 segundos. Repite 2 o 3 veces.\n<\/p>\n<p><h3 class=\"voc-detail__title\"> Otras formas de hacer el vacuum abdominal<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Tambi\u00e9n puedes hacer <strong>el vacuum abdominal de pie<\/strong>, que es otra forma popular de practicarlo. Ponte erguida con las manos en las caderas, respira profundamente por la nariz y exhala lentamente por la boca con los labios fruncidos. Mientras exhalas,<br \/>\n<strong> contrae lentamente los abdominales inferiores<\/strong>. Respira normalmente mientras mantienes la posici\u00f3n durante al menos 20 a 30 segundos y repite 2 o 3 veces. A algunas personas les resulta \u00fatil colocar la palma de la mano sobre los abdominales inferiores como se\u00f1al para atraerlos hacia adentro.\n<\/p>\n<div class=\"voc-detail__cmp\">\n<div class=\"voc-article-container\">\n<article class=\"voc-article voc-article--cmp-photo-text\" readability=\"26\">\n<div class=\"voc-img-container\" readability=\"7\"> <picture>\n<div class=\"voc-horizontal voc-img-icon-link\"> <img class=\"lazy adsviu_analyse\" loading=\"lazy\" data-original=\"\/\/static1.mujerhoy.com\/www\/multimedia\/202312\/13\/media\/cortadas\/fitness-mancuernas-kslC-U210985551980sOH-624x385@MujerHoy.jpg\" alt=\"Mujer haciendo ejercicio con mancuernas. \/\" width=\"624\" height=\"385\"> <\/div>\n<\/picture>\n<p class=\"figure-caption \"> Mujer haciendo ejercicio con mancuernas. \/ \/ <span class=\"voc-photo-author\"> unplash <\/span> <\/p>\n<\/p><\/div>\n<\/article><\/div>\n<\/div>\n<p class=\"voc-paragraph\">La tercera opci\u00f3n es hacer<br \/>\n<strong> vacuum abdominal de rodillas<\/strong>. Ponte en posici\u00f3n de mesa con las rodillas debajo de las caderas y las mu\u00f1ecas debajo de los hombros. Aseg\u00farate de que tu espalda est\u00e9 plana y en posici\u00f3n neutra. Opcionalmente, empuja tu est\u00f3mago hacia adentro y hacia afuera un poco para ayudarte a acostumbrarte a esta posici\u00f3n.\n<\/p>\n<p class=\"voc-paragraph\">Respira profundamente por la nariz y exhala por la boca con los labios fruncidos. Durante la exhalaci\u00f3n, contrae lentamente los abdominales inferiores (imagina que empujas el ombligo hacia la columna). En esta posici\u00f3n, tambi\u00e9n puedes imaginar que <strong>tu vientre es levantado hacia el techo<\/strong>. Respira normalmente y mant\u00e9n esta posici\u00f3n durante 20 a 30 segundos. Repite 2 o 3 veces.\n<\/p>\n<p class=\"voc-paragraph\">La cuarta opci\u00f3n propuesta es hacer el vacuum abdominal es la <strong>versi\u00f3n boca abajo<\/strong>. Acu\u00e9state as\u00ed en el suelo con las piernas estiradas y los brazos extendidos m\u00e1s all\u00e1 de la cabeza con las palmas hacia abajo. Respira profundamente y exhala lentamente por la boca con los labios fruncidos mientras contraes los abdominales inferiores. Esto es <strong>un poco m\u00e1s dif\u00edcil que otras versiones<\/strong>. Contin\u00faa respirando y mant\u00e9n esta posici\u00f3n durante 20 a 30 segundos. Como siempre, repite 2 o 3 veces.\n<\/p>\n<p> <!-- TOPICS --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>TAMARA VILA Publicado \u00b7 23 de diciembre de 2023, 08:23 h No pienses mal: a pesar de su nombre, el vacuum abdominal no es un procedimiento quir\u00fargico ni una tarea dom\u00e9stica. De hecho, es un tipo de contracci\u00f3n abdominal que se utiliza desde hace d\u00e9cadas en la fisioterapia y el mundo del culturismo. Si bien [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":99286,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/99285"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=99285"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/99285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/99286"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=99285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=99285"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=99285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}