{"id":56830,"date":"2022-11-08T18:34:00","date_gmt":"2022-11-08T18:34:00","guid":{"rendered":"https:\/\/somoscordobeses.com\/2022\/11\/08\/lo-celso-se-perdera-el-mundial-de-qatar-por-lesion\/"},"modified":"2022-11-08T18:34:00","modified_gmt":"2022-11-08T18:34:00","slug":"lo-celso-se-perdera-el-mundial-de-qatar-por-lesion","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2022\/11\/08\/lo-celso-se-perdera-el-mundial-de-qatar-por-lesion\/","title":{"rendered":"Lo Celso se perder\u00e1 el Mundial de Qatar por lesi\u00f3n"},"content":{"rendered":"<div>\n<div>\n<p>Se termin\u00f3 la agon\u00eda de la Selecci\u00f3n Argentina y no fue con final feliz: Giovani Lo Celso no podr\u00e1 participar del Mundial de Qatar 2022.<\/p>\n<p>El mediocampista, de 26 a\u00f1os,&nbsp;se someti\u00f3 a nuevos estudios m\u00e9dicos por el desgarro <strong>del b\u00edceps femoral de su pierna derecha<\/strong> el domingo 30 de octubre en el encuentro con <strong>Villarreal <\/strong>ante <strong>Athletic Bilbao<\/strong>,&nbsp;&nbsp;y el parte confirm\u00f3 que ser\u00e1 intervenido quir\u00fargicamente.<\/p>\n<h2>El momento de la lesi\u00f3n de Gio Lo Celso<\/h2>\n<p>El ex<strong> Rosario Central<\/strong>, no quer\u00eda operarse pero <strong>Tottenham<\/strong> (due\u00f1o del pase) desde que se conoci\u00f3 la lesi\u00f3n, pero el jugador y el <em>Submarino Amarillo <\/em>pretend\u00edan otras alternativas. Pero finalmente todas las partes&nbsp;tendr\u00e1 que pasar por el quir\u00f3fano y tendr\u00eda para dos meses de recuperaci\u00f3n.<\/p>\n<blockquote>\n<p>\u2014 442 (@442) November 8, 2022<\/p>\n<\/blockquote>\n<p>Lo Celso, que estuvo en la Copa del Mundo de Rusia 2018, pero no disput\u00f3 ning\u00fan minuto en la misma,&nbsp;<strong>era una pieza clave en el conjunto nacional en el ciclo de Lionel Scaloni, ya que est\u00e1 entre los tres jugadores con m\u00e1s asistencias y completaba el pod\u00eda con m\u00e1s partidos jugados (35).<\/strong><\/p>\n<h2>Las alternativas de Scaloni para el mediocampo de Argentina en Qatar 2022<\/h2>\n<p>Enzo Fern\u00e1ndez<\/p>\n<p>Exequiel Palacios<\/p>\n<p>Guido Rodr\u00edguez<\/p>\n<p>Papu G\u00f3mez<\/p>\n<p>Alexis Mac Allister<\/p>\n<h2>Los 28 nombres que Lionel Scaloni tiene en la cabeza para Qatar 2022<\/h2>\n<p><strong>Arqueros<\/strong><\/p>\n<ul>\n<li>Emiliano \u201cDibu\u201d Mart\u00ednez<\/li>\n<li>Franco Armani<\/li>\n<li>Ger\u00f3nimo Rulli<\/li>\n<\/ul>\n<p><strong>Defensores<\/strong><\/p>\n<ul>\n<li>Nahuel Molina<\/li>\n<li>Gonzalo Montiel<\/li>\n<li>Cristian Romero<\/li>\n<li>Germ\u00e1n Pezzella<\/li>\n<li>Nicol\u00e1s Otamendi<\/li>\n<li>Lisandro Mart\u00ednez<\/li>\n<li>Marcos Acu\u00f1a<\/li>\n<li>Nicol\u00e1s Tagliafico.<\/li>\n<li>Juan Foyth<\/li>\n<\/ul>\n<p><strong>Mediocampistas<\/strong><\/p>\n<ul>\n<li>Rodrigo De Paul<\/li>\n<li>Leandro Paredes<\/li>\n<li>Alexis Mac Allister<\/li>\n<li>Guido Rodr\u00edguez<\/li>\n<li>Alejandro Papu G\u00f3mez<\/li>\n<li>Enzo Fern\u00e1ndez<\/li>\n<li>Exequiel Palacios<\/li>\n<\/ul>\n<p><strong>Delanteros<\/strong><\/p>\n<ul>\n<li>\u00c1ngel Di Mar\u00eda<\/li>\n<li>Lautaro Mart\u00ednez<\/li>\n<li>Juli\u00e1n \u00c1lvarez<\/li>\n<li>Nicol\u00e1s Gonz\u00e1lez<\/li>\n<li>Joaqu\u00edn Correa<\/li>\n<li>Paulo Dybala<\/li>\n<li>Lionel Messi<\/li>\n<li>\u00c1ngel Correa.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<nav class=\"navigation post-navigation\" role=\"navigation\" aria-label=\"Continue Reading\">\n<h2 class=\"screen-reader-text\">Continue Reading<\/h2>\n<\/nav>\n","protected":false},"excerpt":{"rendered":"<p>Se termin\u00f3 la agon\u00eda de la Selecci\u00f3n Argentina y no fue con final feliz: Giovani Lo Celso no podr\u00e1 participar del Mundial de Qatar 2022. El mediocampista, de 26 a\u00f1os,&nbsp;se someti\u00f3 a nuevos estudios m\u00e9dicos por el desgarro del b\u00edceps femoral de su pierna derecha el domingo 30 de octubre en el encuentro con Villarreal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":56831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/56830"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=56830"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/56830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/56831"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=56830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=56830"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=56830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}