{"id":4903,"date":"2020-12-05T19:25:04","date_gmt":"2020-12-05T19:25:04","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/cristiano-ronaldo-dybala-cuadrado-reactivo-juventus-clasico-turines-duelo-barcelona_0_ACK78rRj7.html"},"modified":"2020-12-05T19:25:04","modified_gmt":"2020-12-05T19:25:04","slug":"ni-cristiano-ronaldo-ni-dybala-cuadrado-reactivo-a-la-juventus-en-el-clasico-turines-antes-del-duelo-contra-barcelona","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/ni-cristiano-ronaldo-ni-dybala-cuadrado-reactivo-a-la-juventus-en-el-clasico-turines-antes-del-duelo-contra-barcelona\/","title":{"rendered":"Ni Cristiano Ronaldo ni Dybala: Cuadrado reactiv\u00f3 a la Juventus en el cl\u00e1sico turin\u00e9s antes del duelo contra Barcelona"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ni-cristiano-ronaldo-ni-dybala-cuadrado-reactivo-a-la-juventus-en-el-clasico-turines-antes-del-duelo-contra-barcelona.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ni-cristiano-ronaldo-ni-dybala-cuadrado-reactivo-a-la-juventus-en-el-clasico-turines-antes-del-duelo-contra-barcelona-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Sufri\u00f3 <a href=\"https:\/\/www.clarin.com\/tema\/juventus.html\" class=\"slug automatic\" alt=\"juventus\" title=\"juventus\" target=\"_blank\" rel=\"noopener noreferrer\">Juventus<\/a> en su presentaci\u00f3n por la&nbsp;d\u00e9cima fecha de la <a href=\"https:\/\/www.clarin.com\/tema\/serie-a.html\" class=\"slug automatic\" alt=\"serie-a\" title=\"serie-a\" target=\"_blank\" rel=\"noopener noreferrer\">Serie A<\/a>. La pas\u00f3 mal, pero el rumbo del partido cambi\u00f3 luego de dos centros milim\u00e9tricos del colombiano Juan Cuadrado, que result\u00f3 vital para el 2-1 sobre <a href=\"https:\/\/www.clarin.com\/tema\/torino.html\" class=\"slug automatic\" alt=\"torino\" title=\"torino\" target=\"_blank\" rel=\"noopener noreferrer\">Torino<\/a> en el cl\u00e1sico de <a href=\"https:\/\/www.clarin.com\/tema\/turin.html\" class=\"slug automatic\" alt=\"turin\" title=\"turin\" target=\"_blank\" rel=\"noopener noreferrer\">Tur\u00edn<\/a>, la \u00faltima parada de los de Andrea Pirlo&nbsp;antes de visitar al <a href=\"https:\/\/www.clarin.com\/tema\/barcelona.html\" class=\"slug automatic\" alt=\"barcelona\" title=\"barcelona\" target=\"_blank\" rel=\"noopener noreferrer\">Barcelona<\/a> de <a href=\"https:\/\/www.clarin.com\/tema\/lionel-messi.html\" class=\"slug automatic\" alt=\"lionel-messi\" title=\"lionel-messi\" target=\"_blank\" rel=\"noopener noreferrer\">Lionel Messi<\/a> por la <a href=\"https:\/\/www.clarin.com\/tema\/champions-league.html\" class=\"slug automatic\" alt=\"champions-league\" title=\"champions-league\" target=\"_blank\" rel=\"noopener noreferrer\">Champions League<\/a>.<\/p>\n<p>Ante la falta de precisi\u00f3n de <a href=\"https:\/\/www.clarin.com\/tema\/cristiano-ronaldo.html\" class=\"slug automatic\" alt=\"cristiano-ronaldo\" title=\"cristiano-ronaldo\" target=\"_blank\" rel=\"noopener noreferrer\">Cristiano Ronaldo<\/a> y de <a href=\"https:\/\/www.clarin.com\/tema\/paulo-dybala.html\" class=\"slug automatic\" alt=\"paulo-dybala\" title=\"paulo-dybala\" target=\"_blank\" rel=\"noopener noreferrer\">Paulo Dybala<\/a>, fue Cuadrado la soluci\u00f3n para los bianconeri. Dos env\u00edos medidos al \u00e1rea del colombiano terminaron en los goles que dieron la vuelta a la ventaja inicial del Torino, que se hab\u00eda adelantado a los nueve minutos de juego gracias a un c\u00f3rner ejecutado por el argentino <a href=\"https:\/\/www.clarin.com\/tema\/cristian-ansaldi.html\" class=\"slug automatic\" alt=\"cristian-ansaldi\" title=\"cristian-ansaldi\" target=\"_blank\" rel=\"noopener noreferrer\">Cristian Ansaldi<\/a> que fue capitalizado, tras una bola suelta, por el camerun\u00e9s Nicolas N&#8217;Koulou.<\/p>\n<p>Juventus cerc\u00f3 a su rival pero no encontr\u00f3 la forma de marcar. Estuvo desacertado el campe\u00f3n, al que se le anul\u00f3 un gol, revisado por el <a href=\"https:\/\/www.clarin.com\/tema\/var.html\" class=\"slug automatic\" alt=\"var\" title=\"var\" target=\"_blank\" rel=\"noopener noreferrer\">VAR<\/a>, en el minuto 12 del complemento. Fue luego un zapatazo lejano de Cuadrado que pas\u00f3 por delante de Leonardo Bonucci, en fuera de juego.<\/p>\n<p>Sin embargo, la Vecchia Signora no se dio por vencida y apenas pasada la media hora del segundo tiempo se encontr\u00f3 con el 1-1 parcial gracias a un cabezazo del estadounidense Weston McKennie, que siete minutos antes hab\u00eda sustituido al franc\u00e9s Adrien Rabiot.<\/p>\n<p>La remontada fue en el 89, al borde del final. En otro pase de Cuadrado que conect\u00f3 de cabeza Bonucci para darle el triunfo a la Juventus.<\/p>\n<p>El cuadro de Andrea Pirlo, que el martes visita al Barcelona en la \u00faltima jornada de la Champions League, es segundo en la Serie A a tres puntos del <a href=\"https:\/\/www.clarin.com\/tema\/milan.html\" class=\"slug automatic\" alt=\"milan\" title=\"milan\" target=\"_blank\" rel=\"noopener noreferrer\">Mil\u00e1n<\/a>, que el domingo visita al <a href=\"https:\/\/www.clarin.com\/tema\/sampdoria.html\" class=\"slug automatic\" alt=\"sampdoria\" title=\"sampdoria\" target=\"_blank\" rel=\"noopener noreferrer\">Sampdoria<\/a> sin la presencia de <a href=\"https:\/\/www.clarin.com\/tema\/zlatan-ibrahimovic.html\" class=\"slug automatic\" alt=\"zlatan-ibrahimovic\" title=\"zlatan-ibrahimovic\" target=\"_blank\" rel=\"noopener noreferrer\">Zlatan Ibrahimovic<\/a>.<\/p>\n<p><opta-widget sport=\"football\" widget=\"timeline\" competition=\"21\" season=\"2020\" match=\"2137455\" template=\"normal\" live=\"true\" orientation=\"horizontal\" vertical_timebar_height=\"260\" show_match_header=\"true\" show_score=\"true\" show_crests=\"true\" show_assists=\"all\" show_team_formation=\"true\" show_clock=\"true\" show_period_dividers=\"true\" show_halftime_score=\"false\" show_date=\"true\" date_format=\"dddd D MMMM YYYY\" show_attendance=\"true\" show_images=\"true\" show_referee=\"true\" show_venue=\"true\" show_cards=\"all\" show_goals=\"true\" show_penalties_missed=\"true\" show_subs=\"false\" show_goals_combined=\"false\" show_shootouts=\"false\" show_competition_name=\"true\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_live=\"true\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"heatmap\" competition=\"21\" season=\"2020\" match=\"2137455\" preselected_player template=\"normal\" live=\"true\" show_maps=\"all\" orientation=\"horizontal\" side=\"both\" dimension=\"2D\" one_direction=\"false\" show_match_header=\"true\" show_score=\"true\" show_halftime_score=\"false\" show_crests=\"false\" show_team_formation=\"true\" show_competition_name=\"true\" show_date=\"true\" date_format=\"dddd D MMMM YYYY\" show_team_sheets=\"true\" show_subs=\"true\" show_position=\"true\" show_timecontrols=\"true\" show_timecontrols_buttons=\"true\" show_timecontrols_bar=\"true\" show_tooltips=\"false\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"matchstats\" competition=\"21\" season=\"2020\" match=\"2137455\" template=\"lineups\" live=\"true\" side=\"both\" column_count=\"1\" side_by_side=\"true\" show_match_header=\"true\" show_score=\"true\" show_halftime_score=\"false\" show_crests=\"false\" show_team_formation=\"true\" show_competition_name=\"true\" show_date=\"false\" date_format=\"dddd D MMMM YYYY\" order_by=\"position\" group_by_position=\"false\" show_position=\"true\" show_images=\"false\" show_key=\"false\" show_starters=\"true\" show_goalkeepers=\"true\" show_defenders=\"true\" show_midfielders=\"true\" show_forwards=\"true\" show_subs=\"true\" show_unused_subs=\"false\" show_managers=\"true\" show_captain=\"false\" show_match_events=\"true\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_live=\"false\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"goal_replay\" competition=\"21\" season=\"2020\" match=\"2137455\" template=\"normal\" live=\"true\" animation=\"true\" orientation=\"horizontal\" panning=\"narrow\" plot_events=\"5\" show_direction_of_play=\"false\" show_match_header=\"true\" show_popup_events=\"all\" show_score=\"true\" show_halftime_score=\"false\" show_crests=\"false\" show_images=\"false\" show_team_formation=\"true\" show_competition_name=\"true\" show_date=\"true\" show_events=\"true\" show_events_bar=\"true\" date_format=\"dddd D MMMM YYYY\" show_tooltips=\"false\" competition_naming=\"full\" team_naming=\"full\" player_naming=\"full\" show_live=\"false\" show_logo=\"false\" show_title=\"true\" breakpoints=\"450, 700\"><\/opta-widget><opta-widget sport=\"football\" widget=\"standings\" competition=\"21\" season=\"2020\" match=\"2137455\" team template=\"normal\" live=\"true\" default_nav=\"1\" side=\"combined\" data_detail=\"default\" show_key=\"false\" show_crests=\"false\" points_in_first_column=\"false\" lose_before_draw=\"false\" show_form=\"0\" competition_naming=\"full\" team_naming=\"full\" date_format=\"dddd D MMMM YYYY\" sorting=\"true\" show_live=\"false\" show_relegation_average=\"true\" show_logo=\"false\" show_title=\"true\" breakpoints=\"400\"><\/opta-widget><\/p>\n<p>Fuente: EFE<\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sufri\u00f3 Juventus en su presentaci\u00f3n por la&nbsp;d\u00e9cima fecha de la Serie A. La pas\u00f3 mal, pero el rumbo del partido cambi\u00f3 luego de dos centros milim\u00e9tricos del colombiano Juan Cuadrado, que result\u00f3 vital para el 2-1 sobre Torino en el cl\u00e1sico de Tur\u00edn, la \u00faltima parada de los de Andrea Pirlo&nbsp;antes de visitar al Barcelona [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4903"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=4903"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/4904"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=4903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=4903"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=4903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}