{"id":4885,"date":"2020-12-05T07:29:55","date_gmt":"2020-12-05T07:29:55","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/moscu-empieza-la-vacunacion-contra-el-coronavirus\/"},"modified":"2020-12-05T07:29:55","modified_gmt":"2020-12-05T07:29:55","slug":"moscu-empieza-la-vacunacion-contra-el-coronavirus","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/moscu-empieza-la-vacunacion-contra-el-coronavirus\/","title":{"rendered":"Mosc\u00fa empieza la vacunaci\u00f3n contra el coronavirus"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus.jpg\"><\/p>\n<div readability=\"34\">\n<p> Est\u00e1 disponible en un primer momento para los trabajadores de la salud, de la educaci\u00f3n y de los servicios sociales. <\/p>\n<\/div>\n<div readability=\"59\">\n<p>La vacunaci\u00f3n contra el coronavirus con el f\u00e1rmaco ruso Sputnik V ha comenzado este 5 de diciembre en Mosc\u00fa.<\/p>\n<p>Por el momento, se han abierto 70 puntos donde se puede recibir la inyecci\u00f3n, pero las autoridades moscovitas prometen que 100 m\u00e1s empezar\u00e1n a funcionar antes de fin de a\u00f1o.<\/p>\n<p>La vacunaci\u00f3n, que es gratuita y tiene car\u00e1cter voluntario, se lleva a cabo en dos etapas y la segunda inyecci\u00f3n se aplicar\u00e1 21 d\u00edas despu\u00e9s de la primera.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-2.jpg 460w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"Putin ordena empezar la vacunaci\u00f3n gratuita a gran escala contra el coronavirus con la Sputnik V la pr\u00f3xima semana\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/moscu-empieza-la-vacunacion-contra-el-coronavirus-3.jpg\" alt=\"Putin ordena empezar la vacunaci\u00f3n gratuita a gran escala contra el coronavirus con la Sputnik V la pr\u00f3xima semana\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>Est\u00e1 disponible en un primer momento para los trabajadores de la salud, de la educaci\u00f3n y de los servicios sociales, quienes deben registrarse en un portal especial. Para ser inoculada, una persona debe tener entre 18 y 60 a\u00f1os y no padecer enfermedades cr\u00f3nicas.<\/p>\n<p>La inyecci\u00f3n se suministra solo a los candidatos que no participaron en los ensayos cl\u00ednicos de cualquier vacuna contra el coronavirus, no recibieron inoculaciones durante los \u00faltimos 30 d\u00edas y no tuvieron infecci\u00f3n respiratoria durante las \u00faltimas 2 semanas. La vacunaci\u00f3n est\u00e1 prohibida para embarazadas y madres lactantes.<\/p>\n<p><strong><em>Si te ha gustado, \u00a1comp\u00e1rtelo con tus amigos!<\/em><\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 disponible en un primer momento para los trabajadores de la salud, de la educaci\u00f3n y de los servicios sociales. La vacunaci\u00f3n contra el coronavirus con el f\u00e1rmaco ruso Sputnik V ha comenzado este 5 de diciembre en Mosc\u00fa. Por el momento, se han abierto 70 puntos donde se puede recibir la inyecci\u00f3n, pero las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4885"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=4885"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/4886"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=4885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=4885"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=4885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}