{"id":4883,"date":"2020-12-05T07:48:36","date_gmt":"2020-12-05T07:48:36","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos\/"},"modified":"2020-12-05T07:48:36","modified_gmt":"2020-12-05T07:48:36","slug":"ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos\/","title":{"rendered":"EE.UU. cancela cinco programas de intercambio cultural con China y los tacha de \u00abpropagand\u00edsticos\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos.jpg\"><\/p>\n<div readability=\"35\">\n<p> Seg\u00fan los funcionarios estadounidenses, solo los miembros del Partido Comunista de China se benefician de esos programas, a los que \u00abel pueblo chino\u00bb no tiene manera de acceder. <\/p>\n<\/div>\n<div readability=\"84.263657957245\">\n<p>Washington puesto fin este viernes a cinco programas de intercambio cultural con China, <a href=\"https:\/\/www.state.gov\/termination-of-prc-funded-propaganda-programs\/\" target=\"_blank\" rel=\"noopener noreferrer\">comunica<\/a>&nbsp;el Departamento de Estado de EE.UU.<\/p>\n<p>Se trata concretamente del Programa de viajes educativos a China para responsables de pol\u00edticas; el Programa de amistad entre EE.UU. y China; el Programa de intercambio de liderazgo entre EE.UU. y China; el Programa de intercambio transpac\u00edfico entre EE.UU. y China; y el Programa educativo y cultural de Hong Kong.<\/p>\n<p>El comunicado reconoce que los programas mencionados funcionan conforme a la Ley de intercambio mutuo educativo y cultural, introducida en EE.UU. en 1961.&nbsp;No obstante, los tilda de <strong>\u00abprogramas propagand\u00edsticos fundados por el Partido Comunista de China\u00bb<\/strong>.<\/p>\n<p>\u00abProporcionan un acceso cuidadosamente seleccionado a los funcionarios del Partido Comunista de China, no al pueblo chino, que no disfruta de la libertad de expresi\u00f3n y reuni\u00f3n\u00bb, se\u00f1ala el texto, que caracteriza los programas en cuesti\u00f3n como \u00abunidireccionales\u00bb y <strong>\u00abno mutuamente beneficiosos<\/strong>\u00ab, asevera el texto.<\/p>\n<h3>Sanciones al final de la era Trump&nbsp;<\/h3>\n<h3><\/h3>\n<p>Este mi\u00e9rcoles,&nbsp;Washington&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/375580-eeuu-prohibir-importacion-algodon-empresa-china\" target=\"_blank\" rel=\"noopener noreferrer\">prohibi\u00f3<\/a>&nbsp;la importaci\u00f3n de algod\u00f3n producido por una compa\u00f1\u00eda china, alegando que esta utiliza \u00abtrabajo forzoso, incluido el trabajo de convictos\u00bb en la regi\u00f3n de Sinkiang. Al d\u00eda siguiente, el Pent\u00e1gono <a href=\"https:\/\/actualidad.rt.com\/actualidad\/375713-departamento-defensa-eeuu-cuatro-companias-chinas\" target=\"_blank\" rel=\"noopener noreferrer\">incluy\u00f3<\/a> a cuatro compa\u00f1\u00edas chinas en su lista negra. El viernes, el secretario de Estado de EE.UU., Mike Pompeo, <a href=\"https:\/\/actualidad.rt.com\/actualidad\/375829-eeuu-sanciona-ciudadanos-chinos-actividades-influencia\" target=\"_blank\" rel=\"noopener noreferrer\">anunci\u00f3<\/a> restricciones de visados para cuatro ciudadanos chinos supuestamente involucrados en&nbsp;\u00abactividades de la influencia coercitiva\u00bb.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-2.jpg 460w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"Qu\u00e9 pasos podr\u00eda tomar Trump para dificultar la pol\u00edtica exterior de Biden y frustrar su agenda\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/ee-uu-cancela-cinco-programas-de-intercambio-cultural-con-china-y-los-tacha-de-propagandisticos-3.jpg\" alt=\"Qu\u00e9 pasos podr\u00eda tomar Trump para dificultar la pol\u00edtica exterior de Biden y frustrar su agenda\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>En noviembre&nbsp;desde la Administraci\u00f3n de Donald Trump <a href=\"https:\/\/actualidad.rt.com\/actualidad\/374267-pasos-podria-tomar-trump-dificultar-politica-biden\" target=\"_blank\" rel=\"noopener noreferrer\">se filtr\u00f3<\/a> que, tras perder en las presidenciales del 3 de noviembre, el actual inquilino de la Casa Blanca planeaba promulgar una&nbsp;serie de \u00abpol\u00edticas de l\u00ednea dura\u00bb contra China para&nbsp;hacer \u00abpol\u00edticamente insostenible\u00bb que su rival y sucesor, Joe Biden, cambie de rumbo&nbsp;respecto a la naci\u00f3n asi\u00e1tica. No obstante, personas&nbsp;cercanas al equipo de transici\u00f3n de Biden durante una conversaci\u00f3n con CNN&nbsp;tacharon&nbsp;de \u00aben gran medida ineficaz\u00bb la&nbsp;pol\u00edtica de Trump en China y sugirieron que las sanciones adicionales podr\u00edan darle ventaja a Biden en sus negociaciones con Pek\u00edn.<\/p>\n<p>Por su parte, China ha criticado repetidamente las sanciones de la Administraci\u00f3n de Trump contra sus entidades. A inicios de noviembre, el viceministro de Exteriores del pa\u00eds asi\u00e1tico, Le Yucheng,&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/372358-china-espera-nueva-administracion-eeuu-relacion-sin-confrontacion\" target=\"_blank\" rel=\"noopener noreferrer\">expres\u00f3<\/a>&nbsp;su esperanza de que el nuevo Gabinete liderado por Biden coopere con Pek\u00edn y se adhiera al principio de respeto mutuo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan los funcionarios estadounidenses, solo los miembros del Partido Comunista de China se benefician de esos programas, a los que \u00abel pueblo chino\u00bb no tiene manera de acceder. Washington puesto fin este viernes a cinco programas de intercambio cultural con China, comunica&nbsp;el Departamento de Estado de EE.UU. Se trata concretamente del Programa de viajes educativos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4884,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4883"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=4883"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/4884"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=4883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=4883"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=4883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}