{"id":4862,"date":"2020-12-05T06:01:07","date_gmt":"2020-12-05T06:01:07","guid":{"rendered":"https:\/\/www.perfil.com\/noticias\/espectaculos\/el-cine-de-genero-es-uno-de-los-que-mejor-funcionan.phtml"},"modified":"2020-12-05T06:01:07","modified_gmt":"2020-12-05T06:01:07","slug":"el-cine-de-genero-es-uno-de-los-que-mejor-funcionan","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/el-cine-de-genero-es-uno-de-los-que-mejor-funcionan\/","title":{"rendered":"\u201cEl cine de g\u00e9nero es uno de los que mejor funcionan\u201d"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/el-cine-de-genero-es-uno-de-los-que-mejor-funcionan.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/el-cine-de-genero-es-uno-de-los-que-mejor-funcionan-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<aside class=\"relatedPost\">\n<h3>M\u00e1s noticias de espectaculos<\/h3>\n<\/aside>\n<p>El Buenos Aires Rojo Sangre no frena, jam\u00e1s, su marcha: como buen zombi, el festival de g\u00e9nero m\u00e1s importante de Argentina, ha logrado imponer su pedigr\u00ed, eso de ser el festival m\u00e1s antiguo de cine fant\u00e1stico de Latinoam\u00e9rica. Desde el pasado jueves hasta el domingo 13 de diciembre, el festival podr\u00e1 disfrutarse desde Flixxo, el canal oficial del evento en Youtube. Cada t\u00edtulo de programaci\u00f3n, hablamos de hasta cien cortometrajes y 34 largos, estar\u00e1 disponible por 72 horas despu\u00e9s de su \u201cestreno\u201d. Tambi\u00e9n se usar\u00e1 la plataforma Cont.ar para una competencia especial y sus documentales.<\/p>\n<p>Uno de los artistas que estrenar\u00e1 su film en el festival es Alejandro Ib\u00e1\u00f1ez Nauta, con su \u00f3pera prima, Urub\u00fa. Ib\u00e1\u00f1ez Nauta es parte de un legado m\u00edtico del g\u00e9nero: es hijo de Chicho Ib\u00e1\u00f1ez Serrador, el creador y responsable de milagros como Historias para no dormir y \u00bfQui\u00e9n puede matar a un ni\u00f1o?, y nieto del popular Narciso Iba\u00f1ez Menta, el nacionalizado argentino que gener\u00f3 cl\u00e1sicos como El hombre que volvi\u00f3 de la muerte y El pulpo negro. &nbsp;<\/p>\n<p>\u2014\u00bfQu\u00e9 dir\u00edas define a tu legado familiar y su v\u00ednculo con el contar historias?<\/p>\n<p>\u2014Mi familia ha estado ligada al mundo del espect\u00e1culo durante muchas generaciones. Tanto mi abuelo, Narciso Ib\u00e1\u00f1ez Menta, como mi abuela, Pepita Serrador, proven\u00edan de familias dedicadas al mundo del teatro. Mi padre se cri\u00f3 entre bastidores. Este conocimiento profundo de todos los aspectos de la producci\u00f3n de un espect\u00e1culo le ayud\u00f3 posteriormente en su carrera como director y creador. &nbsp;&nbsp;<\/p>\n<p>Este legado ha sido muy beneficioso en algunos aspectos, me he criado asistiendo a rodajes y he conocido a gente con much\u00edsimo talento desde mi infancia, pero tambi\u00e9n supone una gran presi\u00f3n a la hora de desarrollar mi carrera como director, en tanto que siempre se va a comparar mi trabajo con el suyo. De aqu\u00ed, que en mis trabajos anteriores me dedicase al mundo del documental.<\/p>\n<p>\u2014\u00bfC\u00f3mo das este paso entonces a tu primer largo?<\/p>\n<p>\u2014En los \u00faltimos a\u00f1os, ante el deterioro de la salud de mi padre, naci\u00f3 un deseo de realizar un proyecto que nos permitiese trabajar juntos. Esta pel\u00edcula es un homenaje a mi padre, con el que siempre he compartido la pasi\u00f3n por el cine de g\u00e9nero. En Urub\u00fa hay muchos gui\u00f1os a sus pel\u00edculas, y a la hora de hacerla, me he basado mucho en sus ense\u00f1anzas. Aunque mi padre pudo ver algunas secuencias durante la fase de montaje, por desgracia su salud no le permiti\u00f3 colaborar activamente, que es lo que a m\u00ed me hubiese gustado. Me queda la satisfacci\u00f3n de que sus comentarios fueron muy positivos, pero tengo una gran pena porque falleci\u00f3 un par de semanas antes de que terminase la posproducci\u00f3n y nunca pudo ver la pel\u00edcula completa.<\/p>\n<p>\u2014\u00bfQu\u00e9 cre\u00e9s la industria del terror representa a nivel global? &nbsp;<\/p>\n<p>\u2014El cine de g\u00e9nero es uno de los que mejor funcionan a nivel internacional. Yo creo que el miedo es una de las emociones b\u00e1sicas del ser humano y se comparte a pesar de las diferencias culturales. Y esto hace que las pel\u00edculas de terror tengan buenos recorridos comerciales sin necesidad del tir\u00f3n de grandes estrellas medi\u00e1ticas y presupuestos desorbitados. Esto implica que es uno de los g\u00e9neros que permite mayor experimentaci\u00f3n y libertad creativa a los directores.<\/p>\n<p>En particular, el cine de g\u00e9nero espa\u00f1ol tiene una salud excelente. De hecho, Espa\u00f1a es una potencia mundial. Directores como J. Bayona, Paco Plaza, Jaume Balaguer\u00f3, Rodrigo Cortes\u2026 son aut\u00e9nticos referentes a nivel mundial. Por cierto, todos ellos se han declarado disc\u00edpulos de mi padre. Todos hemos crecido asustados por sus pel\u00edculas y sus Historias para no dormir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s noticias de espectaculos El Buenos Aires Rojo Sangre no frena, jam\u00e1s, su marcha: como buen zombi, el festival de g\u00e9nero m\u00e1s importante de Argentina, ha logrado imponer su pedigr\u00ed, eso de ser el festival m\u00e1s antiguo de cine fant\u00e1stico de Latinoam\u00e9rica. Desde el pasado jueves hasta el domingo 13 de diciembre, el festival podr\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4863,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4862"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=4862"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/4863"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=4862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=4862"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=4862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}