{"id":4860,"date":"2020-12-05T06:09:57","date_gmt":"2020-12-05T06:09:57","guid":{"rendered":"https:\/\/www.perfil.com\/noticias\/deportes\/un-modelo-que-se-derrumba-a-pedazos.phtml"},"modified":"2020-12-05T06:09:57","modified_gmt":"2020-12-05T06:09:57","slug":"un-modelo-que-se-derrumba-a-pedazos","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2020\/12\/05\/un-modelo-que-se-derrumba-a-pedazos\/","title":{"rendered":"Un modelo que se derrumba a pedazos"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/un-modelo-que-se-derrumba-a-pedazos.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2020\/12\/un-modelo-que-se-derrumba-a-pedazos-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<aside class=\"relatedPost\">\n<h3>M\u00e1s noticias de deportes<\/h3>\n<\/aside>\n<p>Le hacen un homenaje a Maradona pero no se nota. Se quedan est\u00e1ticos cuando el aut\u00e9ntico reconocimiento a Diego llega de los jugadores neozelandeses. Asumen que se equivocaron y salen a pedir disculpas. Aparecen viejos tuits de tres jugadores, uno es el capit\u00e1n, con frases mis\u00f3ginas, xen\u00f3fobas y racistas. Vuelven a pedir disculpas. La UAR los separa del plantel. Dos d\u00edas despu\u00e9s se arrepiente y les levanta la sanci\u00f3n. Pero el entrenador no los incluye en el equipo que este s\u00e1bado juega ante Australia. Todo ocurri\u00f3 en tres d\u00edas. Tres d\u00edas de furia felina. Ni un guionista de Netflix hubiera imaginado semejantes desprolijidades.&nbsp;<\/p>\n<p>Estas barbaridades protagonizadas por Los Pumas expusieron de una vez y para siempre las paradojas y contradicciones que hasta estos d\u00edas ocultaban debajo de la alfombra. Este grupo de jugadores que canta el himno a los gritos y embarra la camiseta, qued\u00f3 al desnudo. El modelo Puma, que hasta hace unos d\u00edas se exhib\u00eda como una referencia, como un modelo a seguir, se cay\u00f3 a pedazos.<\/p>\n<p>C\u00f3digos. Todos los que alguna vez corrieron detr\u00e1s de una ovalada se enorgullecen de los valores de tan noble deporte. La lista est\u00e1 repleta de frases con destino de tarjeta navide\u00f1a: solidaridad, respeto, disciplina, juego limpio. Son normas que regulan el comportamiento de los jugadores, dentro y fuera de la cancha. Hay un eslogan que las resume: el rugby no solo propone formar buenos jugadores, tambi\u00e9n apuesta a formar buenas personas.<\/p>\n<p>Ac\u00e1 es cuando la realidad se lleva puesta las buenas intenciones. Cuando los jugadores de Los Pumas eligieron a Pablo Matera de capit\u00e1n, pusieron como l\u00edder del plantel a un jugador con rasgos racistas y homof\u00f3bicos, y antecedentes de patotero. Esto que se conoci\u00f3 esta semana desenmascara a un capit\u00e1n que milita valores opuestos a los del deporte que practica.<\/p>\n<p>Otro de los rasgos m\u00e1s distintivos de los rugbiers es que no discuten los fallos de la autoridad. A diferencia de lo que suele ocurrir en otros deportes, donde los reclamos llegan hasta l\u00edmites insoportables, en el rugby se respetan las decisiones de las personas que est\u00e1n en una posici\u00f3n de mando, est\u00e9n o no de acuerdo. Todo muy loable, si no fuera porque los jugadores de Los Pumas amenazaron con no jugar el partido de este s\u00e1bado si la UAR no le levantaba las sanciones a Matera, Petti y Socino, los tres jugadores que fueron expuestos por sus tuits xen\u00f3fobos.<\/p>\n<p>Los Pumas cierran filas. Si esos valores que sostienen los aplican, solo ocurre puertas adentro. Pueden ser solidarios, tolerantes y respetuosos, pero \u00fanicamente con sus compa\u00f1eros. Como en otros \u00e1mbitos, ac\u00e1 tampoco hay derrame. Todo es parte de la \u00e8lite. Una cuesti\u00f3n de clase.<\/p>\n<p>La Uni\u00f3n que no une. Como si los lamentables episodios protagonizados por Los Pumas no hubiesen alcanzado, la Uni\u00f3n Argentina de Rugby (UAR) tuvo que salir a la cancha, y se pusieron m\u00e1s nerviosos que el juvenil antes de patear el quinto penal. A los dirigentes de la federaci\u00f3n que regula el rugby no se les cay\u00f3 una idea para homenajear a Maradona, tarde y mal reconocieron que se hab\u00edan equivocado, despu\u00e9s fue permeable a las presiones de los sponsors y sancion\u00f3 a tres los jugadores de los tuits escandalosos, hasta que dos d\u00edas despu\u00e9s fue permeable al reclamo del plantel e indult\u00f3 a los jugadores. Idas y vueltas, titubeos, grieta. Ni en la AFA lo hubieran hecho mejor.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s noticias de deportes Le hacen un homenaje a Maradona pero no se nota. Se quedan est\u00e1ticos cuando el aut\u00e9ntico reconocimiento a Diego llega de los jugadores neozelandeses. Asumen que se equivocaron y salen a pedir disculpas. Aparecen viejos tuits de tres jugadores, uno es el capit\u00e1n, con frases mis\u00f3ginas, xen\u00f3fobas y racistas. Vuelven a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4861,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4860"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=4860"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/4860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/4861"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=4860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=4860"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=4860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}