{"id":195067,"date":"2026-07-15T14:56:49","date_gmt":"2026-07-15T14:56:49","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/07\/15\/detras-de-esta-independencia-del-banco-central-milei-esta-pensando-en-una-liberacion-total-del-cepo\/"},"modified":"2026-07-15T14:56:49","modified_gmt":"2026-07-15T14:56:49","slug":"detras-de-esta-independencia-del-banco-central-milei-esta-pensando-en-una-liberacion-total-del-cepo","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/07\/15\/detras-de-esta-independencia-del-banco-central-milei-esta-pensando-en-una-liberacion-total-del-cepo\/","title":{"rendered":"\u201cDetr\u00e1s de esta independencia del Banco Central, Milei est\u00e1 pensando en una liberaci\u00f3n total del cepo\u00bb"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/07\/detras-de-esta-independencia-del-banco-central-milei-esta-pensando-en-una-liberacion-total-del-cepo.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>El director de LP Consulting, <strong>Leonardo Piazza<\/strong>, analiz\u00f3 para Canal E que la propuesta del Gobierno para avanzar con una reforma de la Carta Org\u00e1nica del <a target=\"_blank\" href=\"https:\/\/perfil.com\/noticias\/economia\/el-banco-central-compro-us-532-millones-el-monto-mas-alto-del-ano-a40.phtml\" rel=\"noopener noreferrer\">Banco Central<\/a> abri\u00f3 un nuevo debate sobre la independencia de la autoridad monetaria, la eliminaci\u00f3n definitiva del financiamiento al Tesoro y el futuro del esquema cambiario.<\/p>\n<p>Leonardo Piazza explic\u00f3 que la independencia del Banco Central responde a un principio adoptado por gran parte del mundo luego de la Segunda Guerra Mundial. \u00abSeparar lo fiscal de lo monetario\u00bb, afirm\u00f3, implica que \u00ablas cuentas p\u00fablicas las maneje el presidente y la parte monetaria que la manejan los bancos centrales, <strong>que sean independientes del poder pol\u00edtico<\/strong>\u00ab.<\/p>\n<h2><strong>Las limitaciones del Banco Central m\u00e1s all\u00e1 de su libertad<\/strong><\/h2>\n<p>Seg\u00fan desarroll\u00f3, un Banco Central verdaderamente independiente \u00ab<strong>no podr\u00eda financiar<\/strong> el Estado P\u00fablico\u00bb y \u00ab<strong>tampoco podr\u00eda poner medidas<\/strong> de control cambiario, o sea, el cepo\u00bb. En ese sentido, sostuvo que, tras el saneamiento del balance de la entidad, \u00abse podr\u00eda estar en condiciones de <strong>iniciar una propuesta de la que est\u00e1 iniciando el Gobierno<\/strong>\u00ab.<\/p>\n<p>Para respaldar su an\u00e1lisis, Piazza compar\u00f3 la experiencia argentina con la peruana entre 2010 y 2025. All\u00ed destac\u00f3 que, \u00abla inflaci\u00f3n media anual que nosotros tuvimos <strong>fue el 66%<\/strong> y la inflaci\u00f3n en Per\u00fa<strong> fue el 3,5% en ese periodo<\/strong>\u00ab.<\/p>\n<p>Adem\u00e1s, remarc\u00f3 la diferencia en materia de crecimiento econ\u00f3mico e inversi\u00f3n. \u00abFijate, en contraposici\u00f3n, porque nosotros lo relacionamos con el crecimiento del PBI, <strong>el 3% en Argentina y el 26% en Per\u00fa<\/strong>\u00ab, mientras que \u00abla tasa de inversi\u00f3n en Argentina <strong>es el 17,8%<\/strong> y la tasa de inversi\u00f3n en Per\u00fa <strong>fue el 25%<\/strong>\u00ab.<\/p>\n<h2><strong>Se estima una evoluci\u00f3n del programa econ\u00f3mico a ra\u00edz de las reformas al BCRA<\/strong><\/h2>\n<p>El entrevistado consider\u00f3 que detr\u00e1s de la reforma del Banco Central podr\u00edan aparecer nuevas medidas econ\u00f3micas. \u00abYo creo que detr\u00e1s de esta independencia del Banco Central, <strong>MIlei est\u00e1 pensando en una liberaci\u00f3n del cepo total<\/strong>\u00ab, se\u00f1al\u00f3. Tambi\u00e9n sostuvo que el Gobierno podr\u00eda avanzar hacia \u00ab<strong>un sistema multimoneda<\/strong>, que el d\u00f3lar sea moneda legal, de curso legal\u00bb.<\/p>\n<p>No obstante, aclar\u00f3 que la iniciativa deber\u00eda complementarse con otros cambios estructurales. \u00abPara que esto tenga \u00e9xito, <strong>deber\u00eda tambi\u00e9n haber una reforma tributaria<\/strong>, fundamentalmente con el tratamiento que hay con impuestos provinciales y municipales\u00bb, afirm\u00f3.<\/p>\n<div class=\"article__tags\">\n<p>En esta Nota<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El director de LP Consulting, Leonardo Piazza, analiz\u00f3 para Canal E que la propuesta del Gobierno para avanzar con una reforma de la Carta Org\u00e1nica del Banco Central abri\u00f3 un nuevo debate sobre la independencia de la autoridad monetaria, la eliminaci\u00f3n definitiva del financiamiento al Tesoro y el futuro del esquema cambiario. Leonardo Piazza explic\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":195068,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/195067"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=195067"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/195067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/195068"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=195067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=195067"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=195067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}