{"id":187533,"date":"2026-03-23T18:32:49","date_gmt":"2026-03-23T18:32:49","guid":{"rendered":"https:\/\/www.escribiendocine.com\/noticias\/2026\/03\/23\/21636-critica-de-conadepianos-la-historia-del-nunca-mas-contada-por-sus-trabajadores-conadep-desde-adentro"},"modified":"2026-03-23T18:32:49","modified_gmt":"2026-03-23T18:32:49","slug":"critica-de-conadepianos-la-historia-del-nunca-mas-contada-por-sus-trabajadores-conadep-desde-adentro","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/23\/critica-de-conadepianos-la-historia-del-nunca-mas-contada-por-sus-trabajadores-conadep-desde-adentro\/","title":{"rendered":"Cr\u00edtica de \u201cConadepianos, la historia del &#8216;Nunca M\u00e1s&#8217; contada por sus trabajadores\u201d: CONADEP desde adentro"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/critica-de-conadepianos-la-historia-del-nunca-mas-contada-por-sus-trabajadores-conadep-desde-adentro.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div readability=\"15.218181818182\">\n<div class=\"col-xs-12 col-sm-6 col-md-12 col-lg-3 no-padding col-der\" readability=\"7\">\n<p> <span class=\"fecha\">lunes 23 de marzo de 2026 <\/span> <\/p>\n<\/p><\/div><\/div>\n<div readability=\"57\">\n<p>A 50 a\u00f1os del golpe de Estado del 24 de marzo de 1976, la memoria hist\u00f3rica vuelve a ocupar un lugar central en el debate p\u00fablico argentino. En ese contexto aparece <strong>Conadepianos, la historia del Nunca M\u00e1s contada por sus trabajadores<\/strong> (2026), documental dirigido por Alejandro Cohen Arazi (<strong>C\u00e1ncer de m\u00e1quina<\/strong> y <strong>El cad\u00e1ver insepulto<\/strong>), que propone una mirada singular sobre uno de los hitos fundamentales de la recuperaci\u00f3n democr\u00e1tica: el trabajo de la CONADEP.<\/p>\n<p>Creada en 1983 por el presidente Ra\u00fal Alfons\u00edn, la Comisi\u00f3n Nacional sobre la Desaparici\u00f3n de Personas (CONADEP) tuvo la misi\u00f3n de investigar los cr\u00edmenes cometidos durante la dictadura militar. Su trabajo culmin\u00f3 en 1984 con la publicaci\u00f3n del informe \u201cNunca M\u00e1s\u201d, documento que reuni\u00f3 miles de testimonios sobre secuestros, torturas y desapariciones forzadas.<\/p>\n<p>El documental recupera la experiencia cotidiana de quienes trabajaron en la comisi\u00f3n: investigadores, administrativos y profesionales que debieron organizar una maquinaria institucional in\u00e9dita para registrar las denuncias de las v\u00edctimas. A trav\u00e9s de entrevistas y relatos personales, los protagonistas reconstruyen c\u00f3mo se cre\u00f3 la CONADEP y c\u00f3mo se organiz\u00f3 su funcionamiento: tanto los m\u00e9todos para recibir y sistematizar testimonios de sobrevivientes y familiares; como las tensiones internas y los obst\u00e1culos pol\u00edticos que enfrentaron.<\/p>\n<p>La pel\u00edcula sit\u00faa la investigaci\u00f3n en el clima pol\u00edtico de los primeros a\u00f1os de democracia, cuando el aparato represivo a\u00fan no hab\u00eda desaparecido del todo. En ese escenario, el trabajo de la CONADEP implicaba riesgos, presiones y conflictos. El documental utiliza material de archivo, im\u00e1genes hist\u00f3ricas y registros televisivos para reconstruir ese momento clave: las denuncias p\u00fablicas, las audiencias, la presentaci\u00f3n del informe y el impacto pol\u00edtico que gener\u00f3. Todo este proceso desembocar\u00e1 en el Juicio a las Juntas Militares de 1985, posible en gran medida gracias a la documentaci\u00f3n reunida por la comisi\u00f3n.<\/p>\n<p>As\u00ed, <strong>Conadepianos, la historia del Nunca M\u00e1s contada por sus trabajadores<\/strong> nos recuerda que detr\u00e1s de los grandes procesos hist\u00f3ricos existen personas concretas que sostienen el trabajo cotidiano de la memoria. Los testimonios de los ex trabajadores revelan la convicci\u00f3n \u00e9tica de que documentar esos cr\u00edmenes era una forma de construir justicia.<\/p>\n<p>En el marco de las conmemoraciones por los 50 a\u00f1os del golpe de Estado, <strong>Conadepianos, la historia del Nunca M\u00e1s contada por sus trabajadores<\/strong> permite entender c\u00f3mo se construy\u00f3 uno de los documentos fundamentales de la democracia argentina. El informe \u201cNunca M\u00e1s\u201d fue el primer gran paso institucional para reconocer el terrorismo de Estado y sentar las bases del proceso de memoria, verdad y justicia que marcar\u00eda la historia del pa\u00eds. Al rescatar la voz de quienes participaron en esa tarea, el documental recuerda que la memoria tambi\u00e9n es una construcci\u00f3n colectiva.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/V_4abPgzjVs\" width=\"560\" height=\"314\" allowfullscreen=\"allowfullscreen\">[embedded content]<\/iframe><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>lunes 23 de marzo de 2026 A 50 a\u00f1os del golpe de Estado del 24 de marzo de 1976, la memoria hist\u00f3rica vuelve a ocupar un lugar central en el debate p\u00fablico argentino. En ese contexto aparece Conadepianos, la historia del Nunca M\u00e1s contada por sus trabajadores (2026), documental dirigido por Alejandro Cohen Arazi (C\u00e1ncer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187534,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187533"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187533"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187534"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187533"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}