{"id":187485,"date":"2026-03-24T01:07:57","date_gmt":"2026-03-24T01:07:57","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/marchesin-lesionado-pierde-debut-boca-copa-llega-superclasico_0_DXIw96flXo.html"},"modified":"2026-03-24T01:07:57","modified_gmt":"2026-03-24T01:07:57","slug":"marchesin-lesionado-se-pierde-el-debut-de-boca-en-la-copa-llega-al-superclasico","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/24\/marchesin-lesionado-se-pierde-el-debut-de-boca-en-la-copa-llega-al-superclasico\/","title":{"rendered":"Marches\u00edn lesionado: se pierde el debut de Boca en la Copa, \u00bfllega al Supercl\u00e1sico?"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/marchesin-lesionado-se-pierde-el-debut-de-boca-en-la-copa-llega-al-superclasico.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/marchesin-lesionado-se-pierde-el-debut-de-boca-en-la-copa-llega-al-superclasico-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"element-body-0\" readability=\"63\">\n<p>Iban 28 minutos del segundo tiempo y <strong>Agust\u00edn Marches\u00edn<\/strong> sali\u00f3 r\u00e1pido para anticipar a <strong>Nicol\u00e1s Guerra<\/strong> con un pelotazo. Sin embargo, el delantero no pudo detener la marcha y el arquero vol\u00f3 por el aire. Se reincorpor\u00f3 r\u00e1pidamente y corri\u00f3 hasta su \u00e1rea. No obstante, el dolor se hizo persistente. A tal punto, que pidi\u00f3 el cambio. Fue reemplazado por Leandro Brey a ocho del final y este lunes qued\u00f3 claro que la lesi\u00f3n es m\u00e1s grave de lo esperado.<\/p>\n<\/div>\n<div id=\"element-body-1\" readability=\"68\">\n<p>El n\u00famero uno de Boca sufri\u00f3 un desgarro en el aductor de la pierna derecha, lo que le demandar\u00e1 21 d\u00edas de recuperaci\u00f3n, justo en la previa del debut de la Libertadores, que ser\u00e1 el martes 7 de abril a las 21.30 frente a Universidad Cat\u00f3lica en Santiago de Chile. Marches\u00edn, que lleva 51 partidos disputados bajo los tres palos xeneizes, <strong>se perder\u00e1 el choque con Talleres, el mencionado duelo con los trasandinos<\/strong>, el cl\u00e1sico con Independiente y llegar\u00e1 al l\u00edmite para el segundo encuentro de la Copa, el 14 frente a Barcelona de Guayaquil. Ser\u00e1 en la semana del Supercl\u00e1sico con River que se llevar\u00e1 a cabo el 19 en el Monumental.<\/p>\n<\/div>\n<div id=\"element-body-2\" readability=\"66\">\n<p>En este contexto, el arco ser\u00e1 de Brey (23 a\u00f1os), quien no ataja desde el 24 de febrero. Entonces, fue titular en la Copa Argentina contra Gimnasia de Chivilcoy (victoria 2 a 0). Previo a este partido, entr\u00f3 en el final del partido con Aldosivi, el 31 de agosto del a\u00f1o pasado (tambi\u00e9n triunfo 2 a 0) y jug\u00f3 de entrada ante Rosario Central (1 a 1), el 14 de septiembre en Arroyito. Angel Di Mar\u00eda le marc\u00f3 un gol ol\u00edmpico.<\/p>\n<\/div>\n<div id=\"element-body-3\" readability=\"25.271375464684\">\n<blockquote class=\"twitter-tweet\" readability=\"6.8921933085502\">\n<p lang=\"es\" dir=\"ltr\">NO VA M\u00c1S: Marches\u00edn se esforz\u00f3 para evitar el descuento de Instituto ante Boca y pidi\u00f3 el cambio por una molestia f\u00edsica.<\/p>\n<p>\ud83d\udcfa ESPN Premium | Suscribite al Pack F\u00fatbol en <a href=\"https:\/\/t.co\/7jYILYACXi\">https:\/\/t.co\/7jYILYACXi<\/a> <a href=\"https:\/\/t.co\/oTpZrw48uy\">pic.twitter.com\/oTpZrw48uy<\/a><\/p>\n<p>\u2014 SportsCenter (@SC_ESPN) <a href=\"https:\/\/twitter.com\/SC_ESPN\/status\/2035880746762535109?ref_src=twsrc%5Etfw\">March 23, 2026<\/a><\/p><\/blockquote><\/div>\n<div id=\"element-body-4\" readability=\"62\">\n<p><strong>En el banco estar\u00e1 Javier Garc\u00eda<\/strong>, un hist\u00f3rico de 39 a\u00f1os que aporta mucho m\u00e1s desde su manejo del vestuario que en la cancha. Su \u00faltimo partido fue el 10 de marzo de 2024 en la victoria ante Racing (4 a 2). Jug\u00f3 73 minutos y fue sustuido, justamente, por el propio Brey.<\/p>\n<\/div>\n<div id=\"element-body-5\" readability=\"62\">\n<p>M\u00e1s all\u00e1 de la lesi\u00f3n, hay otro tema que ocupa a Marches\u00edn, de 38 a\u00f1os reci\u00e9n cumplidos: la renovaci\u00f3n de su contrato, que vence en diciembre. Juan Rom\u00e1n Riquelme todav\u00eda no tom\u00f3 una decisi\u00f3n al respecto. El presidente suele tomarse su tiempo para negociar.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Iban 28 minutos del segundo tiempo y Agust\u00edn Marches\u00edn sali\u00f3 r\u00e1pido para anticipar a Nicol\u00e1s Guerra con un pelotazo. Sin embargo, el delantero no pudo detener la marcha y el arquero vol\u00f3 por el aire. Se reincorpor\u00f3 r\u00e1pidamente y corri\u00f3 hasta su \u00e1rea. No obstante, el dolor se hizo persistente. A tal punto, que pidi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187485"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187485"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187486"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187485"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}