{"id":187481,"date":"2026-03-23T22:40:04","date_gmt":"2026-03-23T22:40:04","guid":{"rendered":"https:\/\/somoscordobeses.com\/2026\/03\/23\/los-documentos-que-exhiben-la-planificacion-de-la-represion-en-la-unc-a-50-anos-del-golpe\/"},"modified":"2026-03-23T22:40:04","modified_gmt":"2026-03-23T22:40:04","slug":"los-documentos-que-exhiben-la-planificacion-de-la-represion-en-la-unc-a-50-anos-del-golpe","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/23\/los-documentos-que-exhiben-la-planificacion-de-la-represion-en-la-unc-a-50-anos-del-golpe\/","title":{"rendered":"Los documentos que exhiben la planificaci\u00f3n de la represi\u00f3n en la UNC, a 50 a\u00f1os del golpe"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/los-documentos-que-exhiben-la-planificacion-de-la-represion-en-la-unc-a-50-anos-del-golpe.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Cientos y miles de documentos y archivos hacen referencia a la manera en que era planificada la represi\u00f3n por las fuerzas militares durante la d\u00e9cada de 1970 en Argentina. Durante los \u00faltimos d\u00edas, incluso la SIDE desclasific\u00f3 documentos, y todo indica que nuevas revelaciones podr\u00edan darse a conocer.<\/p>\n<p>En este marco, y a horas de cumplirse medio siglo del \u00faltimo golpe c\u00edvico-militar, la Universidad de C\u00f3rdoba publica memorandos reservados que describen c\u00f3mo se organizaba la represi\u00f3n en la casa de altos estudios. Estos materiales resultaron fundamentales tanto para el desarrollo de los juicios por terrorismo de Estado como para la investigaci\u00f3n cient\u00edfica y la reconstrucci\u00f3n de lo ocurrido en esos a\u00f1os oscuros.<\/p>\n<figure data-tadevel-template=\"web\/multimedia\" data-type=\"photo\"><figcaption>\n<p>Foto, gentileza: Nicol\u00e1s Fortini \/ UNCIENCIA.<\/p>\n<\/figcaption><\/figure>\n<p>Ana Carol Sol\u00eds, docente de la Escuela de Historia e investigadora del <strong>Centro de Investigaciones de la Facultad de Filosof\u00eda y Humanidades de la UNC<\/strong>, estudia desde hace a\u00f1os los memorandos reservados de la Polic\u00eda Federal, delegaci\u00f3n C\u00f3rdoba (PF-DC), preservados en el Archivo Provincial de la Memoria. Estos documentos evidencian la coordinaci\u00f3n interna que hab\u00eda entre la delegaci\u00f3n local de la Polic\u00eda Federal, el Tercer Cuerpo del Ej\u00e9rcito, el Departamento de Informaciones (D2) y otras dependencias que formaban la denominada \u201ccomunidad informativa\u201d.<\/p>\n<p>Seg\u00fan los documentos analizados, esta articulaci\u00f3n fue especialmente activa entre 1975 y 1978. Los registros dan cuenta de diversas pr\u00e1cticas represivas y destacan el lugar que ocupaba la Universidad Nacional de C\u00f3rdoba como posible \u201cfoco de surgimiento del enemigo subversivo\u201d.<\/p>\n<p>Pod\u00e9s acceder al art\u00edculo completo en el portal de <strong>UNCiencia<\/strong>.<\/p>\n<figure data-html data-tadevel-template=\"web\/multimedia\" data-type=\"rich\" data-url=\"https:\/\/www.cba24n.com.ar\/cordoba\/daniel-passerini-participo-del-homenaje-a-los-trabajadores-municipales-desaparecidos_a69c1a9d560aa260802ae7c7d\"><figcaption>\n<p>Daniel Passerini particip\u00f3 del homenaje a los trabajadores municipales desaparecidos<\/p>\n<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cientos y miles de documentos y archivos hacen referencia a la manera en que era planificada la represi\u00f3n por las fuerzas militares durante la d\u00e9cada de 1970 en Argentina. Durante los \u00faltimos d\u00edas, incluso la SIDE desclasific\u00f3 documentos, y todo indica que nuevas revelaciones podr\u00edan darse a conocer. En este marco, y a horas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187481"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187481"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187482"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187481"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}