{"id":187237,"date":"2026-03-21T17:41:44","date_gmt":"2026-03-21T17:41:44","guid":{"rendered":"https:\/\/somoscordobeses.com\/2026\/03\/21\/cuenta-atras-para-semana-santa-malaga-y-huelva-aceleran-la-recuperacion-de-sus-playas-tras-los-temporales\/"},"modified":"2026-03-21T17:41:44","modified_gmt":"2026-03-21T17:41:44","slug":"cuenta-atras-para-semana-santa-malaga-y-huelva-aceleran-la-recuperacion-de-sus-playas-tras-los-temporales","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/21\/cuenta-atras-para-semana-santa-malaga-y-huelva-aceleran-la-recuperacion-de-sus-playas-tras-los-temporales\/","title":{"rendered":"Cuenta atr\u00e1s para Semana Santa: M\u00e1laga y Huelva aceleran la recuperaci\u00f3n de sus playas tras los temporales"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/cuenta-atras-para-semana-santa-malaga-y-huelva-aceleran-la-recuperacion-de-sus-playas-tras-los-temporales.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Las secuelas del tren de borrascas siguen muy presentes en la costa andaluza, pero la cuenta atr\u00e1s para <strong>Semana Santa<\/strong> ya obliga a acelerar los trabajos. El <strong>Gobierno de Espa\u00f1a<\/strong> comenzar\u00e1 el pr\u00f3ximo <strong>lunes 23 de marzo<\/strong> las <strong>obras de emergencia en las playas de M\u00e1laga<\/strong>, al tiempo que varios municipios del litoral de <strong>Huelva<\/strong> intensifican labores de limpieza, reparaci\u00f3n de accesos y aportes de arena para llegar en las mejores condiciones posibles al arranque de la temporada tur\u00edstica.<\/p>\n<p>Seg\u00fan ha informado el <strong>subdelegado del Gobierno en M\u00e1laga, Javier Salas<\/strong>, el Ejecutivo invertir\u00e1 <strong>1,3 millones de euros<\/strong> en actuaciones de emergencia a trav\u00e9s de la <strong>Demarcaci\u00f3n de Costas<\/strong> para adecuar las playas malague\u00f1as tras los da\u00f1os ocasionados por los temporales del pasado mes de febrero. A ello se suma, ha recordado, el paquete de <strong>2.000 millones de euros<\/strong> recogido en el <strong>Real Decreto-ley 5\/2026<\/strong>, destinado a ayudas para ayuntamientos con infraestructuras y servicios municipales afectados en el litoral.<\/p>\n<p>Salas ha defendido que el Gobierno act\u00faa \u201cen una doble vertiente\u201d: por un lado, con la recuperaci\u00f3n del estado natural de las playas mediante <strong>aporte de arena<\/strong> para corregir las basculaciones de poniente; y por otro, con apoyo econ\u00f3mico a los municipios que hayan sufrido da\u00f1os en instalaciones y servicios costeros. \u201cYa est\u00e1n contratados los trabajos y el lunes dar\u00e1n comienzo\u201d, ha subrayado.<\/p>\n<p>El subdelegado tambi\u00e9n ha puesto en valor la respuesta estatal ante los temporales y ha enmarcado estas actuaciones en una estrategia m\u00e1s amplia de protecci\u00f3n del <strong>dominio p\u00fablico mar\u00edtimo-terrestre<\/strong>, especialmente frente a una <strong>erosi\u00f3n litoral<\/strong> agravada por los efectos del <strong>cambio clim\u00e1tico<\/strong>. En esa l\u00ednea, ha recordado que el pasado a\u00f1o se ejecut\u00f3 en la provincia de M\u00e1laga \u201cel mayor contrato de mantenimiento de la historia\u201d, con <strong>2,1 millones de euros<\/strong> financiados con fondos <strong>Next Generation<\/strong>, y ha cifrado en <strong>4,5 millones de euros<\/strong> las inversiones en obras de emergencia realizadas entre <strong>2022, 2023 y 2024<\/strong>, a las que ahora se suman los <strong>1,3 millones<\/strong> de 2026.<\/p>\n<h3>Da\u00f1os millonarios en Huelva antes de la campa\u00f1a tur\u00edstica<\/h3>\n<p>En paralelo, la costa de <strong>Huelva<\/strong> afronta tambi\u00e9n una intensa carrera contrarreloj para que las playas est\u00e9n listas en una de las fechas con mayor afluencia de visitantes. Este a\u00f1o, sin embargo, el esfuerzo de los ayuntamientos ha sido mayor por el impacto acumulado de los \u00faltimos temporales.<\/p>\n<p>Uno de los puntos m\u00e1s castigados ha sido <strong>Matalasca\u00f1as<\/strong>. La borrasca <strong>Francis<\/strong> afect\u00f3 el pasado enero a parte del paseo mar\u00edtimo y su reparaci\u00f3n se estima en <strong>12,5 millones de euros<\/strong>, seg\u00fan las valoraciones t\u00e9cnicas trasladadas por el Ayuntamiento. En el conjunto del municipio, los da\u00f1os ascienden ya a <strong>20 millones de euros<\/strong>.<\/p>\n<p>El Consistorio mantiene una obra de emergencia en el paseo para garantizar su funcionalidad, aunque no estar\u00e1 terminada hasta, al menos, julio. Mientras tanto, ha reforzado las tareas de <strong>limpieza<\/strong>, retirada de enseres, mejora de accesos y <strong>cribado intensivo de la arena<\/strong>. A ello se suma el proyecto estatal para la aportaci\u00f3n de <strong>70.000 metros c\u00fabicos de arena<\/strong> en la playa de Matalasca\u00f1as, unos trabajos retrasados por los temporales y que concluir\u00e1n en verano, aunque gran parte del litoral presenta ya una imagen aceptable de cara a Semana Santa.<\/p>\n<p>Otra de las zonas m\u00e1s afectadas ha sido <strong>Punta Umbr\u00eda<\/strong>, especialmente <strong>El Portil<\/strong>, donde se han registrado p\u00e9rdidas de arena, da\u00f1os en construcciones y episodios de especial tensi\u00f3n durante el paso de la borrasca <strong>Leonardo<\/strong>, cuando varios vecinos tuvieron que ser desalojados. El Ayuntamiento ha activado una obra de emergencia para proteger la primera l\u00ednea de playa y trabaja adem\u00e1s en la retirada de arena acumulada en caminos, la limpieza extraordinaria del frente costero y la recuperaci\u00f3n de accesos y servicios.<\/p>\n<p>El alcalde de Punta Umbr\u00eda, <strong>Jos\u00e9 Carlos Hern\u00e1ndez Cansino<\/strong>, ha advertido de que la situaci\u00f3n en El Portil obliga a seguir actuando \u201ccon mucha precauci\u00f3n\u201d por la presi\u00f3n del mar sobre la costa. Tambi\u00e9n ha reclamado al Gobierno medidas estructurales, al lamentar que en algunos tramos \u201cno haya playa cada vez que sube la marea ni cuando hay temporales\u201d. El municipio asegura haber invertido ya <strong>m\u00e1s de dos millones de euros<\/strong> en este n\u00facleo, incluyendo tambi\u00e9n el asfaltado de calles da\u00f1adas.<\/p>\n<h3>Aportes de arena y limpieza en Isla Cristina, Ayamonte, Cartaya y Lepe<\/h3>\n<p>En <strong>Isla Cristina<\/strong>, el alcalde <strong>Jenaro Orta<\/strong> ha se\u00f1alado que, aunque el municipio cuenta con m\u00e1s de diez kil\u00f3metros de litoral y los da\u00f1os se concentran en una parte \u201cm\u00ednima\u201d, se ha actuado en la <strong>Playa Central<\/strong> y el <strong>Camino de Santana<\/strong>, adem\u00e1s de levantar una escollera en la zona de levante para frenar nuevos efectos de los temporales. El Ayuntamiento ha desarrollado durante estas semanas trabajos de <strong>limpieza<\/strong>, desbroce, reparaci\u00f3n de pasarelas, aportaci\u00f3n de arena y refuerzo de personal.<\/p>\n<p>Adem\u00e1s, se ha confirmado una actuaci\u00f3n urgente que permitir\u00e1 aportar <strong>m\u00e1s de 16.000 metros c\u00fabicos de arena<\/strong> en las pr\u00f3ximas semanas, previsiblemente despu\u00e9s de Semana Santa, con la vista puesta en que las playas lleguen en condiciones \u00f3ptimas a la temporada alta.<\/p>\n<p>En <strong>Ayamonte<\/strong>, y en especial en <strong>Isla Canela<\/strong>, se est\u00e1n retirando restos vegetales como ca\u00f1as, ramas y troncos acumulados tras la borrasca Leonardo y los desembalses de varios pantanos durante febrero. Los trabajos, iniciados en <strong>San Bruno<\/strong> y extendidos hasta <strong>Punta del Moral<\/strong>, incluyen tambi\u00e9n la reposici\u00f3n de vallados y nuevas tareas de adecuaci\u00f3n para la campa\u00f1a de Semana Santa.<\/p>\n<p>Tambi\u00e9n <strong>Cartaya<\/strong> ha reconocido da\u00f1os \u201cimportantes\u201d en <strong>pasarelas<\/strong> y <strong>accesos<\/strong>, junto a la falta de arena en algunas zonas, por lo que prepara una reposici\u00f3n de entradas para facilitar la llegada a la playa.<\/p>\n<p>En <strong>Mazag\u00f3n<\/strong>, compartida por <strong>Palos de la Frontera<\/strong> y <strong>Moguer<\/strong>, la incidencia ha sido menor y se abordar\u00e1 un acondicionamiento habitual para estas fechas. Entre las intervenciones previstas figura la mejora del acceso desde la playa del <strong>Parador<\/strong>, con retirada de residuos y compactaci\u00f3n de arena para reforzar la seguridad de los usuarios.<\/p>\n<p>Por su parte, <strong>Lepe<\/strong> activar\u00e1 en <strong>La Antilla<\/strong> el dispositivo del <strong>Plan de Playas<\/strong> al <strong>60%<\/strong> desde el <strong>Viernes de Dolores<\/strong> hasta el <strong>Domingo de Resurrecci\u00f3n<\/strong>, operativo que continuar\u00e1 todos los fines de semana hasta el <strong>15 de junio<\/strong>, cuando funcionar\u00e1 al cien por cien. La concejala de Playas y Turismo, <strong>Elena V\u00e9lez<\/strong>, ha explicado que habr\u00e1 vigilancia de <strong>Protecci\u00f3n Civil<\/strong>, aseos p\u00fablicos en funcionamiento y trabajos continuos de mantenimiento, poda y limpieza. En este enclave, los temporales no han provocado un castigo tan severo como en otros puntos de la costa.<\/p>\n<p>Con la <strong>Semana Santa<\/strong> a las puertas, el estado de las playas se ha convertido en una prioridad para administraciones y ayuntamientos. La recuperaci\u00f3n del litoral no solo afecta a la imagen tur\u00edstica de Andaluc\u00eda, sino tambi\u00e9n a la seguridad, la econom\u00eda local y la capacidad de respuesta ante futuros temporales, en un contexto en el que la <strong>erosi\u00f3n costera<\/strong> deja de ser un problema puntual para convertirse en un desaf\u00edo cada vez m\u00e1s estructural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las secuelas del tren de borrascas siguen muy presentes en la costa andaluza, pero la cuenta atr\u00e1s para Semana Santa ya obliga a acelerar los trabajos. El Gobierno de Espa\u00f1a comenzar\u00e1 el pr\u00f3ximo lunes 23 de marzo las obras de emergencia en las playas de M\u00e1laga, al tiempo que varios municipios del litoral de Huelva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187237"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187237"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187238"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187237"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}