{"id":187117,"date":"2026-02-07T08:17:54","date_gmt":"2026-02-07T08:17:54","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/fitness\/entrenamiento-tut-tiempo-bajo-tension-clave-aumentar-fuerza-sin-pesas-20260207152639-nt.html"},"modified":"2026-02-07T08:17:54","modified_gmt":"2026-02-07T08:17:54","slug":"entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/07\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas\/","title":{"rendered":"Entrenamiento TUT (tiempo bajo tensi\u00f3n): la clave para aumentar tu fuerza sin pesas"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p><!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial \">\n<!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial__signature \">\n<!-- IMAGE AUTHOR -->\n<picture class=\"voc-image-signature\">\n<img class=\"voc-image-signature__img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas.jpg\" alt=\"Tamara Vila\">\n<\/picture>\n<!-- INFO AUTHOR --> <\/div><\/div>\n<p><!-- COMPONENTS --><\/p>\n<p class=\"voc-paragraph\">Si est\u00e1s empezando en el mundo del fitness, uno de los conceptos clave que debes comenzar a asimilar cuanto antes es el del entrenamiento TUT (por las siglas en ingl\u00e9s de time under tensi\u00f3n), que es precisamente eso: la cantidad de tiempo que un m\u00fasculo o grupo muscular espec\u00edfico est\u00e1 activo y bajo tensi\u00f3n durante un ejercicio. Algo clave para <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/trabajar-fuerza-sin-levantar-pesas-entrenadora-profesional-lara-cid-20250331080524-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"aumentar tu fuerza sin pesas\" data-mrf-link=\"www.mujerhoy.com\">aumentar tu fuerza sin pesas<\/a>.<\/p>\n<p class=\"voc-paragraph\">Si alguna vez has escuchado a un instructor hablar del &#8216;tiempo bajo tensi\u00f3n&#8217; como la raz\u00f3n de que te ardan las piernas al <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/como-hacer-sentadilla-perfecta-tips-errores-beneficios-gluteos-core-perfectos-20240316081845-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"hacer unas sentadillas\" data-mrf-link=\"www.mujerhoy.com\">hacer unas sentadillas<\/a> o el core en una repetici\u00f3n de flexiones extremadamente lenta, puede que no te entusiasme saber m\u00e1s sobre el principio del entrenamiento. Pero comprenderlo te ayudar\u00e1 a apreciar su naturaleza y a aprender a usarlo para obtener grandes beneficios. <\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/postura-en-v-sentada-ejercicio-fuerza-core-20260111114301-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Postura en V sentada, el ejercicio de fuerza para tener un core de diez\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-1.jpg\" alt=\"Postura en V sentada, el ejercicio de fuerza para tener un core de diez\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/entrenadora-portia-page-recomienda-mejores-ejercicios-mejorar-fuerza-aumentar-metabolismo-20260107105717-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"La entrenadora Portia Page recomienda los tres mejores ejercicios para mejorar fuerza y acelerar el metabolismo\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-2.jpg\" alt=\"La entrenadora Portia Page recomienda los tres mejores ejercicios para mejorar fuerza y acelerar el metabolismo\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">El tiempo bajo tensi\u00f3n (TUT) se refiere al tiempo total que se dedica a realizar un ejercicio donde el m\u00fasculo produce tensi\u00f3n. \u00bfY cu\u00e1ndo est\u00e1 exactamente un m\u00fasculo bajo tensi\u00f3n? Para responder a la cuesti\u00f3n, es \u00fatil comprender los tres tipos de contracciones que realiza un m\u00fasculo durante el ejercicio: <strong>conc\u00e9ntrica, isom\u00e9trica y exc\u00e9ntrica<\/strong>. La conc\u00e9ntrica es cuando un m\u00fasculo se acorta, la isom\u00e9trica es cuando no hay cambios en la longitud muscular y la exc\u00e9ntrica es cuando el m\u00fasculo se alarga. <\/p>\n<p class=\"voc-paragraph\">Un ejemplo: <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/curl-biceps-barra-ejercicio-atleta-brazos-mas-tonificados-fuertes-20250310070904-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"el curl de b\u00edceps\" data-mrf-link=\"www.mujerhoy.com\">el curl de b\u00edceps<\/a>. El movimiento ascendente de este ejercicio es la contracci\u00f3n o fase conc\u00e9ntrica. Bajar el peso es la fase exc\u00e9ntrica del movimiento, cuando el b\u00edceps se alarga. Finalmente, imagina sostener una mancuerna a mitad de una flexi\u00f3n con el codo doblado a 90 grados. Tu b\u00edceps trabaja para sostener el peso, pero el m\u00fasculo no cambia de longitud: eso es una contracci\u00f3n isom\u00e9trica.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nUn m\u00fasculo bajo tensi\u00f3n<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Un m\u00fasculo est\u00e1 bajo tensi\u00f3n durante las tres contracciones. El tiempo bajo tensi\u00f3n representa el tiempo total empleado en todas estas fases para una serie o sesi\u00f3n de entrenamiento. Por lo tanto, varios factores determinan el <strong>tiempo bajo tensi\u00f3n<\/strong> en un entrenamiento: el tiempo total de ejercicio, el n\u00famero de repeticiones y series que realizas (es decir, el volumen de entrenamiento) y finalmente el tiempo que dura cada repetici\u00f3n.<\/p>\n<p class=\"voc-paragraph\">Puedes jugar con los tres factores para aumentar el tiempo de uso en cualquier entrenamiento. Sin embargo, cuando se habla de &#8216;entrenamiento bajo tensi\u00f3n&#8217;, a menudo se refiere a jugar con el tiempo empleado en cada repetici\u00f3n. El tiempo bajo tensi\u00f3n se puede manipular f\u00e1cilmente <strong>aumentando o disminuyendo el tiempo<\/strong> empleado en cualquiera de las tres fases de contracci\u00f3n. <\/p>\n<p><h3 class=\"v-cmp-suh\">\nLos beneficios del entrenamiento TUT<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">En pocas palabras, jugar con el tiempo bajo tensi\u00f3n <strong>a\u00f1ade variedad a tus entrenamientos<\/strong> y los hace m\u00e1s desafiantes. Aumentar el TUT puede ayudar a aumentar la dificultad de tu carga de trabajo y tu fuerza general sin tener que cambiar necesariamente el peso que usas. Y puede ser especialmente \u00fatil para quienes no tienen mucho equipo disponible o que quieren desafiarse a s\u00ed mismas sin la necesidad de emplear pesas inc\u00f3modas. <\/p>\n<p class=\"voc-paragraph\">El tiempo bajo tensi\u00f3n es un gran concepto para aplicarlo a los entrenamientos con peso corporal, lo cual es ideal cuando viajas y no tienes pesas a tu disposici\u00f3n. Ajustar el tiempo bajo tensi\u00f3n dentro de la serie es una buena manera de crear variedad en el entrenamiento y <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/entrenamiento-avanzado-resistencia-mejores-tips-para-trabajar-musculo-fuerza-20231112094813-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"desafiar la resistencia y la fuerza muscular\" data-mrf-link=\"www.mujerhoy.com\">desafiar la resistencia y la fuerza muscular<\/a>.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-418\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-3.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Mujer haciendo ejercicio al aire libre.\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nMujer haciendo ejercicio al aire libre.<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nINSTAGRAM @ALO<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-418\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-418\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-3.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Si te sientes estancada en tus entrenamientos, especialmente en cuanto a tu progreso de fuerza, a\u00f1adir el est\u00edmulo del tiempo bajo tensi\u00f3n puede darle a tu cuerpo el impulso que necesita para seguir adapt\u00e1ndose. Tambi\u00e9n puede ayudarte a <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/marimi-garcia-experta-mujer-deporte-entrenamiento-fuerza-autonomas-fuertes-a-los-50-20250802190800-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"entrenar tu fortaleza mental\" data-mrf-link=\"www.mujerhoy.com\">entrenar tu fortaleza mental<\/a>. El TUT no solo es una excelente manera de variar tu entrenamiento, sino que tambi\u00e9n te ofrece un desaf\u00edo mental para bajar el ritmo.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nEntrenamiento TUT y crecimiento muscular<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Si aumentar el tiempo bajo tensi\u00f3n te supone el mismo reto que levantar pesas m\u00e1s pesadas, sin duda te ayuda a desarrollar tus m\u00fasculos. <strong>La hipertrofia<\/strong> es el proceso de aumentar el tama\u00f1o, la densidad y la forma de los m\u00fasculos esquel\u00e9ticos, a menudo mediante entrenamiento de resistencia. <\/p>\n<p class=\"voc-paragraph\">Un alto volumen de entrenamiento (28-30 series por m\u00fasculo por semana) suele ser mejor para inducir el crecimiento muscular que un volumen menor (6-10 series por m\u00fasculo por semana). Adem\u00e1s, un alto volumen de entrenamiento tiende a resultar en un <strong>mayor tiempo de uso del m\u00fasculo<\/strong> (TUT) en general.<\/p>\n<p class=\"voc-paragraph\">Sin embargo, si se analiza con m\u00e1s detalle el tiempo bajo tensi\u00f3n por repetici\u00f3n o durante cada fase del movimiento, <strong>el beneficio es menos claro<\/strong>. Ni las repeticiones lentas ni las r\u00e1pidas parecen marcar la diferencia en la hipertrofia, seg\u00fan estudios. Sin embargo, puede ser beneficioso adoptar un enfoque de mitad y mitad. <\/p>\n<p class=\"voc-paragraph\">Las investigaciones demuestran que los movimientos exc\u00e9ntricos favorecen m\u00e1s la hipertrofia, algo que avalar\u00eda la teor\u00eda de que el tiempo exc\u00e9ntrico bajo tensi\u00f3n puede ayudar a <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/metodo-2-2-2-entrenamiento-viral-ganar-mas-musculo-fuerza-a-los-40-20260106183253-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"promover el crecimiento muscular\" data-mrf-link=\"www.mujerhoy.com\">promover el crecimiento muscular<\/a>. Aunque a\u00fan no hay evidencia cient\u00edfica definitiva que lo demuestre, parece ser que el mejor ritmo para la hipertrofia podr\u00eda ser una combinaci\u00f3n de un movimiento m\u00e1s lento en la fase exc\u00e9ntrica con un movimiento m\u00e1s r\u00e1pido durante la fase conc\u00e9ntrica. Por ejemplo, para un curl de b\u00edceps, esto consistir\u00eda en bajar el peso lentamente y volverlo a subir r\u00e1pidamente.<\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/giro-columna-pilates-ganar-fuerza-core-movilidad-espalda-20260110193843-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Giro de columna de Pilates, el ejercicio perfecto para ganar fuerza en el core y movilidad en la espalda\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-4.jpg\" alt=\"Giro de columna de Pilates, el ejercicio perfecto para ganar fuerza en el core y movilidad en la espalda\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/crunch-oblicuo-sentada-ejercicio-facil-endurecer-abdominalesa-50-20260110192839-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Crunch oblicuo sentada, el ejercicio f\u00e1cil para endurecer abdominales y conseguir un vientre plano a los 50\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/entrenamiento-tut-tiempo-bajo-tension-la-clave-para-aumentar-tu-fuerza-sin-pesas-5.jpg\" alt=\"Crunch oblicuo sentada, el ejercicio f\u00e1cil para endurecer abdominales y conseguir un vientre plano a los 50\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s empezando en el mundo del fitness, uno de los conceptos clave que debes comenzar a asimilar cuanto antes es el del entrenamiento TUT (por las siglas en ingl\u00e9s de time under tensi\u00f3n), que es precisamente eso: la cantidad de tiempo que un m\u00fasculo o grupo muscular espec\u00edfico est\u00e1 activo y bajo tensi\u00f3n durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187118,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187117"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187117"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187118"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187117"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}