{"id":187004,"date":"2026-03-17T03:17:21","date_gmt":"2026-03-17T03:17:21","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/17\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran\/"},"modified":"2026-03-17T03:17:21","modified_gmt":"2026-03-17T03:17:21","slug":"ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/17\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran\/","title":{"rendered":"EE.UU. revela el n\u00famero de soldados suyos heridos en el conflicto con Ir\u00e1n"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran.jpg\"><\/p>\n<p>El n\u00famero de soldados estadounidenses heridos en el conflicto&nbsp;con Ir\u00e1n ha ascendido <strong>a cerca de 200<\/strong>, seg\u00fan&nbsp;comunic\u00f3 este lunes&nbsp;el Comando Central del Ej\u00e9rcito&nbsp;de EE.UU., <a href=\"https:\/\/www.reuters.com\/world\/middle-east\/number-us-troops-wounded-war-against-iran-rises-about-200-2026-03-16\/\" target=\"_blank\" rel=\"noopener noreferrer\">recoge<\/a> Reuters.<\/p>\n<p>Se detall\u00f3 que hubo&nbsp;efectivos heridos en <strong>Kuwait, Arabia Saudita, Emiratos \u00c1rabes Unidos, Jordania, Bar\u00e9in, Irak e Israel<\/strong>.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 Card-default \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-2.jpg, https:\/\/actualidad.rt.com\/actualidad\/460, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"IM\u00c1GENES SATELITALES muestran el da\u00f1o provocado a una base de EE.UU. por ataques iran\u00edes\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-revela-el-numero-de-soldados-suyos-heridos-en-el-conflicto-con-iran-3.jpg\" alt=\"IM\u00c1GENES SATELITALES muestran el da\u00f1o provocado a una base de EE.UU. por ataques iran\u00edes\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>La gran mayor\u00eda de los&nbsp;afectados presentaron lesiones leves&nbsp;y&nbsp;180 de ellos ya se han reincorporado al servicio. Mientras, en otros&nbsp;<strong>10 casos se trata de lesiones graves<\/strong>,&nbsp;indic\u00f3 el comando.<\/p>\n<p>Desde el inicio de la agresi\u00f3n de Washington y Tel Aviv contra la Rep\u00fablica Isl\u00e1mica, las autoridades del pa\u00eds norteamericano han confirmado <strong>la muerte de 13&nbsp;soldados<\/strong>. Siete de esos militares murieron en ataques&nbsp;contra las&nbsp;instalaciones del pa\u00eds norteamericano en&nbsp;Kuwait y&nbsp;Arabia Saudita, mientras que otros seis <a href=\"https:\/\/esrt.space\/actualidad\/592646-morir-militares-eeuu-avion-cisterna-irak\" target=\"_blank\" rel=\"noopener noreferrer\">fallecieron<\/a> la semana pasada&nbsp;al estrellarse en Irak un avi\u00f3n de reabastecimiento de combustible KC-135.<\/p>\n<h3><strong>Agresi\u00f3n contra Ir\u00e1n<\/strong><strong><\/strong><\/h3>\n<ul>\n<li><a href=\"https:\/\/esrt.space\/actualidad\/589438-israel-lanzar-ataque-teheran\" target=\"_blank\" rel=\"noopener noreferrer\">Israel<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/esrt.space\/actualidad\/589465-trump-confirma-agresion-eeuu-iran\" target=\"_blank\" rel=\"noopener noreferrer\">EE.UU.<\/a>&nbsp;iniciaron una agresi\u00f3n conjunta contra Ir\u00e1n la madrugada del s\u00e1bado 28 de febrero con el objetivo declarado de&nbsp;<strong>\u00abeliminar las amenazas\u00bb<\/strong>&nbsp;de la Rep\u00fablica Isl\u00e1mica.<\/li>\n<li>Los bombardeos causaron la muerte del&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/442388-fallece-lider-supremo-iran-ali-jamenei\" target=\"_blank\" rel=\"noopener noreferrer\">ayatol\u00e1<\/a>&nbsp;<strong>Al\u00ed Jamene\u00ed<\/strong>&nbsp;y de varios altos cargos militares.&nbsp;<strong>Mojtab\u00e1 Jamene\u00ed<\/strong>, hijo del fallecido l\u00edder supremo iran\u00ed, fue elegido como su sucesor.<\/li>\n<li>En respuesta a la ofensiva, Teher\u00e1n&nbsp;ha lanzado numerosas oleadas de misiles bal\u00edsticos y drones contra&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/591893-iran-anunciar-ataques-refineria-petroleo\" target=\"_blank\" rel=\"noopener noreferrer\">Israel<\/a>&nbsp;y contra bases estadounidenses en pa\u00edses de Oriente Medio.<\/li>\n<li>Asimismo,&nbsp;<strong>bloque\u00f3 casi por completo el estrecho de Ormuz<\/strong>, ruta mar\u00edtima por donde circula alrededor de 20 % de todo el petr\u00f3leo que se comercia en el mundo.&nbsp;La situaci\u00f3n ha disparado los precios del crudo.<\/li>\n<li>El nuevo l\u00edder supremo&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/591691-nuevo-lider-supremo-iran-dirigirse-nacion\" target=\"_blank\" rel=\"noopener noreferrer\">se dirigi\u00f3<\/a>&nbsp;a la naci\u00f3n, por primera vez desde su nombramiento, a trav\u00e9s de un mensaje en el que promete vengar cada una de las muertes sufridas por el pueblo iran\u00ed. Adem\u00e1s,&nbsp;<strong>calific\u00f3 de \u00abfundamental\u00bb seguir bloqueando el estrecho de Ormuz<\/strong>, al tiempo que asever\u00f3 que se sopesa abrir otros frentes \u00abdonde el enemigo tiene poca experiencia y ser\u00e1 extremadamente vulnerable\u00bb.<\/li>\n<li>Mientras tanto, Washington sigue afirmando que est\u00e1 ganando el conflicto y que la ofensiva terminar\u00e1 \u00abmuy pronto\u00bb, ya que \u00abno queda nada que atacar\u00bb. Por su parte, las Fuerzas Armadas&nbsp;iran\u00edes&nbsp;informaron de m\u00e1s de<em> 50 oleadas de ataques contra los art\u00edfices de la agresi\u00f3n.<\/em><\/li>\n<\/ul>\n<p><strong><em>Trump arremete contra la OTAN sobre Ir\u00e1n, mientras intenta resolver la crisis energ\u00e9tica:&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/593162-trump-hablando-iran-resolver-crisis-energetica\" target=\"_blank\" rel=\"noopener noreferrer\">MINUTO A MINUTO<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero de soldados estadounidenses heridos en el conflicto&nbsp;con Ir\u00e1n ha ascendido a cerca de 200, seg\u00fan&nbsp;comunic\u00f3 este lunes&nbsp;el Comando Central del Ej\u00e9rcito&nbsp;de EE.UU., recoge Reuters. Se detall\u00f3 que hubo&nbsp;efectivos heridos en Kuwait, Arabia Saudita, Emiratos \u00c1rabes Unidos, Jordania, Bar\u00e9in, Irak e Israel. La gran mayor\u00eda de los&nbsp;afectados presentaron lesiones leves&nbsp;y&nbsp;180 de ellos ya se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187004"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=187004"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/187004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/187005"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=187004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=187004"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=187004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}