{"id":186779,"date":"2026-03-12T12:38:10","date_gmt":"2026-03-12T12:38:10","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/bienestar\/summit-internacional-obesidad-londres-declaracion-expertos-20260312125533-nt.html"},"modified":"2026-03-12T12:38:10","modified_gmt":"2026-03-12T12:38:10","slug":"dr-busch-director-medico-internacional-en-el-primer-summit-hablemos-de-peso-tratar-la-obesidad-requiere-empatia-y-compromiso-a-largo-plazo","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/12\/dr-busch-director-medico-internacional-en-el-primer-summit-hablemos-de-peso-tratar-la-obesidad-requiere-empatia-y-compromiso-a-largo-plazo\/","title":{"rendered":"Dr. Busch, director m\u00e9dico internacional, en el primer Summit &#8216;Hablemos de peso&#8217;: \u00abTratar la obesidad requiere empat\u00eda y compromiso a largo plazo\u00bb"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p><!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial \">\n<!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial__signature \">\n<!-- IMAGE AUTHOR -->\n<picture class=\"voc-image-signature\">\n<img class=\"voc-image-signature__img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/dr-busch-director-medico-internacional-en-el-primer-summit-hablemos-de-peso-tratar-la-obesidad-requiere-empatia-y-compromiso-a-largo-plazo.jpg\" alt=\"Patricia Mart\u00edn\">\n<\/picture>\n<!-- INFO AUTHOR --> <\/div><\/div>\n<p><!-- COMPONENTS --><\/p>\n<p class=\"voc-paragraph\">En los \u00faltimos a\u00f1os la idea de seguir<strong> una vida saludable y <\/strong>de cuidarnos, no solo por fuera, si no tambi\u00e9n por dentro, ha cobrado importancia dentro de nuestra sociedad. Cuidar de nuestra alimentaci\u00f3n o hacer ejercicio se han convertido en clave de nuestro d\u00eda a d\u00eda, y todos estamos mucho m\u00e1s concienciados. <\/p>\n<p class=\"voc-paragraph\">Adem\u00e1s, tambi\u00e9n se han empezado a visibilizar y desestigmatizar <strong>enfermedades como la obesidad, <\/strong>que actualmente se ha convertido en uno de los problemas de salud p\u00fablica m\u00e1s relevantes. Sin embargo, sigue estando infradiagnosticada e infratratada y muchas de las personas que viven con la enfermedad cargan adem\u00e1s con el estigma.<\/p>\n<p class=\"voc-paragraph\">Con motivo del D\u00eda Mundial de la Obesidad,<strong> Novo Nordisk<\/strong>, compa\u00f1\u00eda pionera a nivel mundial en el abordaje de la obesidad, organiz\u00f3 el <strong>primer Summit \u00abHablemos de Peso\u00bb <\/strong>en Londres. Un evento que reuni\u00f3 a periodistas, investigadores y personas con obesidad para poner en com\u00fan informaci\u00f3n rigurosa y actualizada que permita hablar de forma transparente y responsable sobre esta enfermedad.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nTodos los detalles sobre el evento<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">El evento cont\u00f3 con un destacado<strong> panel de expertos<\/strong> que nos ayudaron a entender mejor como abordar esta enfermedad: <\/p>\n<p class=\"voc-paragraph\"><strong>-Dr. W. Scott Butsch,<\/strong> director m\u00e9dico internacional senior de Obesidad en Novo Nordisk. <\/p>\n<p class=\"voc-paragraph\">&#8211;<strong>Dr. Bruno Halpern, <\/strong>presidente electo de la Federaci\u00f3n Mundial de la Obesidad<\/p>\n<p class=\"voc-paragraph\">&#8211;<strong>Angela Hemsworth<\/strong>, paciente que comparti\u00f3 su experiencia personal <\/p>\n<p class=\"voc-paragraph\">&#8211;<strong>Dra. Stephanie Alice Baker<\/strong>, profesora de Sociolog\u00eda en la Universidad City-St. George de Londres, que ha profundizado en los factores socioculturales que influyen en la atenci\u00f3n sanitaria que se ofrece a las personas con obesidad <\/p>\n<div class=\"v-c-cmp \">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-783\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/dr-busch-director-medico-internacional-en-el-primer-summit-hablemos-de-peso-tratar-la-obesidad-requiere-empatia-y-compromiso-a-largo-plazo-1.jpg\" class=\"v-a-img\" width=\"748\" height=\"524\" alt=\"El panel de expertos\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nEl panel de expertos<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nCEDIDA<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-783\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-783\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/dr-busch-director-medico-internacional-en-el-primer-summit-hablemos-de-peso-tratar-la-obesidad-requiere-empatia-y-compromiso-a-largo-plazo-1.jpg\" class=\"v-mdl__img-z\" width=\"748\" height=\"524\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Los especialistas analizaron los distintos factores que influyen en esta patolog\u00eda y c\u00f3mo el <strong>entorno sociocultural<\/strong> puede afectar a las personas que viven con obesidad, quienes en muchos casos tambi\u00e9n enfrentan estigmatizaci\u00f3n. <\/p>\n<p class=\"voc-paragraph\">Pusieron el foco en la importancia de entender que la obesidad es una enfermedad que suele estar<strong> infradiagnosticada e infratratada <\/strong>lo que conlleva a ejercer una gran presi\u00f3n econ\u00f3mica sobre los pacientes, sus familias, y el sistema sanitario.<\/p>\n<p class=\"voc-paragraph\">Tal y como destac\u00f3 el Dr. W. Scott Butshc: \u00abes imprescindible conocer<strong> la historia de cada persona,<\/strong> c\u00f3mo ha desarrollado la enfermedad y c\u00f3mo afecta en su calidad de vida. As\u00ed, tratar la obesidad requiere empat\u00eda y compromiso a largo plazo\u00bb.<\/p>\n<p class=\"voc-paragraph\">En este contexto, y en sinton\u00eda con la <strong>Federaci\u00f3n Mundial de la Obesidad <\/strong>\u2014que celebra anualmente el D\u00eda Mundial de la Obesidad\u2014, Novo Nordisk destaca la importancia de impulsar una acci\u00f3n colectiva inmediata para hacer frente a esta enfermedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os la idea de seguir una vida saludable y de cuidarnos, no solo por fuera, si no tambi\u00e9n por dentro, ha cobrado importancia dentro de nuestra sociedad. Cuidar de nuestra alimentaci\u00f3n o hacer ejercicio se han convertido en clave de nuestro d\u00eda a d\u00eda, y todos estamos mucho m\u00e1s concienciados. Adem\u00e1s, tambi\u00e9n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":186780,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186779"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=186779"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/186780"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=186779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=186779"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=186779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}