{"id":186734,"date":"2026-03-12T23:06:13","date_gmt":"2026-03-12T23:06:13","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/golazo-joaquin-panichelli-triunfo-clave-racing-estrasburgo-croacia-conference-league_0_amRcmTrX9L.html"},"modified":"2026-03-12T23:06:13","modified_gmt":"2026-03-12T23:06:13","slug":"el-golazo-de-joaquin-panichelli-para-un-triunfo-clave-del-racing-de-estrasburgo-en-croacia-por-la-conference-league","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/12\/el-golazo-de-joaquin-panichelli-para-un-triunfo-clave-del-racing-de-estrasburgo-en-croacia-por-la-conference-league\/","title":{"rendered":"El golazo de Joaqu\u00edn Panichelli para un triunfo clave del Racing de Estrasburgo en Croacia por la Conference League"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/el-golazo-de-joaquin-panichelli-para-un-triunfo-clave-del-racing-de-estrasburgo-en-croacia-por-la-conference-league.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/el-golazo-de-joaquin-panichelli-para-un-triunfo-clave-del-racing-de-estrasburgo-en-croacia-por-la-conference-league-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"element-body-0\" readability=\"63\">\n<p><strong>Joaqu\u00edn Panichelli<\/strong>, uno de los tantos j\u00f3venes argentinos que revoluciona el f\u00fatbol europeo, atraviesa una temporada de ensue\u00f1o en Estrasburgo. Con apenas 36 partidos disputados, es el primer perseguidor de <strong>Mason Greenwood<\/strong> en la tabla de goleadores de la liga francesa y se abre camino gol a gol para ocupar un lugar en la ofensiva de la <strong>Selecci\u00f3n Argentina<\/strong> en la <strong>Copa del Mundo<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-1\" readability=\"65\">\n<p>Este jueves, el ex River volvi\u00f3 a dejar constancia de su buen momento y abri\u00f3 el marcador en la victoria 2 a 1 sobre el <strong>Rijeka<\/strong>, por el partido de ida de los octavos de final de la <strong>Conference League<\/strong>. El ex lateral de Boca Juniors, <strong>Valent\u00edn Barco<\/strong>, fue el encargado de armar la jugada desde el fondo para que <strong>Sebasti\u00e1n Nanasi <\/strong>asistiera al joven <strong>Panichelli<\/strong>,<strong> <\/strong>que enganch\u00f3 velozmente y lanz\u00f3 un remate cruzado al arco de <strong>Martin Zlomisli\u0107<\/strong> para marcar el 1 a 0.<\/p>\n<\/div>\n<div id=\"element-body-2\" readability=\"66\">\n<p>A los 27, del complemento, Panichelli tambi\u00e9n particip\u00f3 de la jugada en la que el ingl\u00e9s <strong>Martial Godo<\/strong>, ingresado en lugar de Nanasi, ampli\u00f3 la ventaja. A pesar de que el descuento lleg\u00f3 r\u00e1pido para el conjunto local gracias al croata <strong>Ante Majstorovic<\/strong>, esta impecable actuaci\u00f3n de los argentinos deja en ventaja a los blanquiazules de cara al duelo de vuelta, que ser\u00e1 el pr\u00f3ximo jueves en Estrasburgo.<\/p>\n<\/div>\n<div id=\"element-body-4\" readability=\"63\">\n<p>Mientras tanto, Panichelli contin\u00faa rompiendo obst\u00e1culos a nivel individual. <strong>Alcanz\u00f3 a Lautaro Mart\u00ednez<\/strong> como el argentino con m\u00e1s tantos entre quienes juegan en las cinco principales ligas de Europa (14) y est\u00e1 a un gol de posicionarse junto a <strong>Mason Greenwood<\/strong> como el m\u00e1ximo artillero de la liga francesa. Desde el arranque de la temporada, el cordob\u00e9s destaca entre los grandes: lleva 18 anotaciones y 4 asistencias, mantuvo una racha notable de nueve goles &#8211;<em>entre ellos dos dobletes-<\/em> en las primeras 10 fechas de la Ligue 1 y marc\u00f3 en cinco de los \u00faltimos seis partidos de su equipo.<\/p>\n<\/div>\n<div id=\"element-body-5\" readability=\"63\">\n<p>Su principal objetivo esta temporada es la <strong>Selecci\u00f3n<\/strong>. Si bien ya tuvo una peque\u00f1a primera participaci\u00f3n en el equipo de <strong>Lionel Scaloni <\/strong>(<em>ingres\u00f3 durante cuatro minutos durante la victoria por 2 a 0 sobre Angola en un amistoso<\/em>), demostr\u00f3 tener las condiciones para ser merecedor de un lugar en el plantel de cara al Mundial de Estados Unidos, M\u00e9xico y Canad\u00e1, y <strong>los n\u00fameros lo respaldan<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-6\" readability=\"24.948132780083\">\n<blockquote class=\"twitter-tweet\" readability=\"6.1410788381743\">\n<p lang=\"es\" dir=\"ltr\">\u00a1\u00a1\u00a1GOL TEMPRANERO EN CROACIA!!! Joaqu\u00edn Panichelli recibi\u00f3 y anot\u00f3 el 1-0 de Estrasburgo ante Rijeka a los 2&#8242; de juego.<\/p>\n<p>\ud83d\udcfa Toda la <a href=\"https:\/\/twitter.com\/hashtag\/UECL?src=hash&amp;ref_src=twsrc%5Etfw\">#UECL<\/a> por <a href=\"https:\/\/twitter.com\/hashtag\/DisneyPlus?src=hash&amp;ref_src=twsrc%5Etfw\">#DisneyPlus<\/a> Plan Premium <a href=\"https:\/\/t.co\/QER6hQi0pW\">pic.twitter.com\/QER6hQi0pW<\/a><\/p>\n<p>\u2014 SportsCenter (@SC_ESPN) <a href=\"https:\/\/twitter.com\/SC_ESPN\/status\/2032154716604359078?ref_src=twsrc%5Etfw\">March 12, 2026<\/a><\/p><\/blockquote><\/div>\n<div id=\"element-body-7\" readability=\"61\">\n<p>En la actualidad, corre con ventaja en la pelea por el puesto con el delantero de <strong>Palmeiras Jos\u00e9 <em>Flaco<\/em> L\u00f3pez<\/strong>, quien este domingo se consagr\u00f3 vencedor del <strong>Campeonato Paulista<\/strong> por 2-1 ante el <strong>Novorizontino<\/strong>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joaqu\u00edn Panichelli, uno de los tantos j\u00f3venes argentinos que revoluciona el f\u00fatbol europeo, atraviesa una temporada de ensue\u00f1o en Estrasburgo. Con apenas 36 partidos disputados, es el primer perseguidor de Mason Greenwood en la tabla de goleadores de la liga francesa y se abre camino gol a gol para ocupar un lugar en la ofensiva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":186735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186734"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=186734"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/186735"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=186734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=186734"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=186734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}