{"id":186726,"date":"2026-03-12T02:49:24","date_gmt":"2026-03-12T02:49:24","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/12\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china\/"},"modified":"2026-03-12T02:49:24","modified_gmt":"2026-03-12T02:49:24","slug":"ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/03\/12\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china\/","title":{"rendered":"EE.UU. inicia investigaciones comerciales contra la UE, India y China"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china.jpg\"><\/p>\n<p>Estados Unidos inici\u00f3 investigaciones comerciales sobre China, la Uni\u00f3n Europea y otras 14 econom\u00edas por presuntas pr\u00e1cticas relacionadas con <strong>\u00abexceso estructural de capacidad y producci\u00f3n\u00bb<\/strong> en sectores manufactureros, <a href=\"https:\/\/ustr.gov\/about\/policy-offices\/press-office\/press-releases\/2026\/march\/ustr-initiates-section-301-investigations-relating-structural-excess-capacity-and-production\">anunci\u00f3<\/a> el representante comercial de Estados Unidos, Jamieson Greer, en un comunicado difundido este mi\u00e9rcoles.<\/p>\n<p>Seg\u00fan la nota, las investigaciones determinar\u00e1n si \u00ablos actos, pol\u00edticas y pr\u00e1cticas\u00bb de esas econom\u00edas son <strong>\u00abirrazonables o discriminatorias\u00bb<\/strong> y si \u00abcargan o restringen el comercio de Estados Unidos\u00bb. La lista de econom\u00edas sujetas a investigaci\u00f3n incluye a China, la Uni\u00f3n Europea, Singapur, Suiza, Noruega, Indonesia, Malasia, Camboya, Tailandia, Corea del Sur, Vietnam, Taiw\u00e1n, Bangladesh, M\u00e9xico, Jap\u00f3n y la India.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 Card-default \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-2.jpg, https:\/\/actualidad.rt.com\/actualidad\/460, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"&quot;Demuestra la clase de psic\u00f3pata que es&quot;: Borrell carga contra Trump\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/03\/ee-uu-inicia-investigaciones-comerciales-contra-la-ue-india-y-china-3.jpg\" alt=\"&quot;Demuestra la clase de psic\u00f3pata que es&quot;: Borrell carga contra Trump\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>\u00abEstados Unidos ya no sacrificar\u00e1 su base industrial a otros pa\u00edses que podr\u00edan estar export\u00e1ndonos sus problemas&nbsp;mediante un exceso de capacidad y producci\u00f3n. Las investigaciones de hoy subrayan el compromiso del presidente [Donald] Trump de <strong>relocalizar cadenas de suministro cr\u00edticas<\/strong> y crear empleos bien remunerados para los trabajadores estadounidenses en nuestros sectores manufactureros\u00bb, afirm\u00f3 Greer.<\/p>\n<p>El comunicado indic\u00f3 que la oficina del representante comercial <strong>solicit\u00f3 consultas con los Gobiernos incluidos<\/strong>.&nbsp;<\/p>\n<p>Las investigaciones se llevan a cabo en virtud del art\u00edculo 301 de la Ley de Comercio de 1974. Este art\u00edculo otorga al presidente de los Estados Unidos la facultad de aplicar todas las medidas necesarias para contrarrestar las restricciones al comercio nacional que, en opini\u00f3n de la parte estadounidense, imponen otros pa\u00edses.<\/p>\n<ul>\n<li>El mes pasado, la Corte Suprema estadounidense <a href=\"https:\/\/actualidad.rt.com\/actualidad\/588096-corte-suprema-estados-unidos-invalida-aranceles-globales-impuestos-trump\" target=\"_blank\" rel=\"noopener noreferrer\">declar\u00f3<\/a> ilegales&nbsp;los fundamentos con los que la Administraci\u00f3n Trump impuso aranceles globales y&nbsp;<strong>anul\u00f3 su aplicaci\u00f3n<\/strong>.&nbsp;La sentencia invalid\u00f3 tanto los grav\u00e1menes supuestamente destinados a combatir&nbsp;el tr\u00e1fico de drogas&nbsp;como los llamados &#8216;aranceles rec\u00edprocos&#8217;, al considerar que excedieron las facultades legales otorgadas por el Congreso.<\/li>\n<li>En respuesta, el mandatario republicano anunci\u00f3 la&nbsp;<a href=\"https:\/\/esrt.space\/actualidad\/588262-trump-anuncia-aumento-inmediato-arancel\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">imposici\u00f3n<\/a>&nbsp;de <strong>un nuevo arancel global de 15 %<\/strong>, para reemplazar los que la Corte Suprema derog\u00f3. Al final, <a href=\"https:\/\/actualidad.rt.com\/actualidad\/588719-aranceles-globales-trump-entran-vigor\" target=\"_blank\" rel=\"noopener noreferrer\">entr\u00f3<\/a> en vigor una tarifa global de 10 %.<\/li>\n<li>A inicios de a\u00f1o, el propio Trump&nbsp;<a href=\"https:\/\/actualidad.rt.com\/actualidad\/581833-jodidos-trump-corte-suprema-falla\" target=\"_blank\" rel=\"noopener noreferrer\">advirti\u00f3<\/a> que estar\u00edan <strong>\u00abjodidos\u00bb<\/strong> si la Corte anulaba sus aranceles, por los enormes montos que tendr\u00edan que pagar, \u00absin incluir la cantidad que los pa\u00edses y las empresas requerir\u00edan\u00bb.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos inici\u00f3 investigaciones comerciales sobre China, la Uni\u00f3n Europea y otras 14 econom\u00edas por presuntas pr\u00e1cticas relacionadas con \u00abexceso estructural de capacidad y producci\u00f3n\u00bb en sectores manufactureros, anunci\u00f3 el representante comercial de Estados Unidos, Jamieson Greer, en un comunicado difundido este mi\u00e9rcoles. Seg\u00fan la nota, las investigaciones determinar\u00e1n si \u00ablos actos, pol\u00edticas y pr\u00e1cticas\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":186727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186726"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=186726"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/186726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/186727"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=186726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=186726"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=186726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}