{"id":184574,"date":"2026-02-09T16:20:08","date_gmt":"2026-02-09T16:20:08","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=85577"},"modified":"2026-02-09T16:20:08","modified_gmt":"2026-02-09T16:20:08","slug":"tres-nuevas-jornadas-de-ecocanje-y-kermes-ambiental-para-esta-semana-donde-seran","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/09\/tres-nuevas-jornadas-de-ecocanje-y-kermes-ambiental-para-esta-semana-donde-seran\/","title":{"rendered":"Tres nuevas jornadas de ecocanje y kerm\u00e9s ambiental para esta semana: d\u00f3nde ser\u00e1n"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/tres-nuevas-jornadas-de-ecocanje-y-kermes-ambiental-para-esta-semana-donde-seran.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>Los vecinos y vecinas podr\u00e1n acercarse a los barrios Parque Liceo III, Alto General Paz y Pueyrred\u00f3n.<\/strong><\/li>\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>All\u00ed encontrar\u00e1n juegos y productos de la Econom\u00eda Circular.<\/strong><\/li>\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>La actividad es libre y gratuita.<\/strong><\/li>\n<\/ul>\n<hr>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Esta semana, en el marco de la propuesta Verano Circular, la Municipalidad de C\u00f3rdoba ofrecer\u00e1 tres nuevas instancias de Ecocanje y kerm\u00e9s ambiental para los vecinos y vecinas de la ciudad de C\u00f3rdoba.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Ser\u00e1n los d\u00edas martes 10, jueves 12 y viernes 13 de febrero en los barrios Parque Liceo III secci\u00f3n, Alto General Paz y General Pueyrred\u00f3n, respectivamente. En los primeros dos, la invitaci\u00f3n tambi\u00e9n se extiende a la inauguraci\u00f3n de dos nuevos Polideportivos Sociales en la ciudad.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">En el tercero, la propuesta estar\u00e1 incluida en una nueva edici\u00f3n de La Pe\u00f1a en tu Ciudad, con m\u00fasica en vivo, baile y actividades para toda la familia. Todas estas experiencias ser\u00e1n ofrecidas a trav\u00e9s del Ente BioC\u00f3rdoba de manera libre y gratuita.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">A continuaci\u00f3n, se detallan los espacios donde se llevar\u00e1n a cabo estos encuentros:<\/p>\n<ul class=\"ak-ul\" data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"bulletList\" data-prosemirror-node-block=\"true\" readability=\"0.5\">\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"listItem\" data-prosemirror-node-block=\"true\" readability=\"4\">\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Martes 10 a las 18:00 \u2013 Plaza Jos\u00e9 Evaristo Fern\u00e1ndez (Bartolom\u00e9 Hidalgo esq. Juan Luis Orrego, Parque Liceo III)<br data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"hardBreak\" data-prosemirror-node-inline=\"true\">Jueves 12 a las 17:30 \u2013 Plaza del barrio (Catamarca esq. Achupallas, Alto General Paz)<br data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"hardBreak\" data-prosemirror-node-inline=\"true\">Viernes 13 a las 20:00 \u2013 Plaza Alem (David Luque esq. Potos\u00ed, Pueyrred\u00f3n)<\/p>\n<\/li>\n<\/ul>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Se invita a los vecinos a llevar sus residuos secos y limpios (papel, cart\u00f3n, pl\u00e1stico, telgopor, vidrios, telas, aluminio, tetra brik) para ser canjeados por un producto de la Econom\u00eda Circular y as\u00ed contribuir al reciclaje en la ciudad. Los materiales recuperados ser\u00e1n destinados a la Escuela Municipal de Econom\u00eda Circular.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"strong\">Las \u00faltimas jornadas del Verano Circular<\/strong><\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">La semana pasada, el \u00faltimo Ecocanje tuvo lugar durante el partido entre Instituto y Lan\u00fas, en Alta C\u00f3rdoba, donde los hinchas de \u201cLa Gloria\u201d acercaron sus residuos y se llevaron a cambio llaveros fabricados con material reciclado.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Esta actividad tambi\u00e9n se enmarc\u00f3 en el Programa F\u00fatbol Sostenible, con el objetivo de disminuir el impacto ambiental en eventos deportivos a trav\u00e9s de acciones educativas que promueven la recolecci\u00f3n, clasificaci\u00f3n y reciclado de los residuos que se generan en d\u00edas de partido, sensibilizando y comprometiendo a la familia deportiva.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Tambi\u00e9n se realiz\u00f3 una Kerm\u00e9s ambiental en el polideportivo municipal de Ruta 19, cercano al CPC Pueyrred\u00f3n. Este es un lugar de referencia para el deporte y la recreaci\u00f3n de los vecinos y vecinas del sector este de la ciudad, que viven en barrios como Pueyrred\u00f3n, Yapey\u00fa y Barranca Yaco.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">All\u00ed hubo juegos y actividades educativas tales como camino de recuperaci\u00f3n, juego de pesca, juego de separaci\u00f3n y jenga. Todos estos, fabricados a partir de material recuperado por el reciclaje, ayudan a crear conciencia sobre la importancia de estas acciones.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Tambi\u00e9n hubo instancias de Ecocanje en esta actividad, por las que los vecinos se llevaron en esta oportunidad piedras sanitarias para gatos y ecomacetas, productos de la Econom\u00eda Circular fabricados en nuestra ciudad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los vecinos y vecinas podr\u00e1n acercarse a los barrios Parque Liceo III, Alto General Paz y Pueyrred\u00f3n. All\u00ed encontrar\u00e1n juegos y productos de la Econom\u00eda Circular. La actividad es libre y gratuita. Esta semana, en el marco de la propuesta Verano Circular, la Municipalidad de C\u00f3rdoba ofrecer\u00e1 tres nuevas instancias de Ecocanje y kerm\u00e9s ambiental [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184574"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184574"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184575"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184574"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}