{"id":184413,"date":"2026-02-08T20:17:29","date_gmt":"2026-02-08T20:17:29","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/lautaro-martinez-leyenda-inter-milan-llego-171-goles-metio-top-3-maximos-goleadores-historia_0_aPR4aZhGGK.html"},"modified":"2026-02-08T20:17:29","modified_gmt":"2026-02-08T20:17:29","slug":"lautaro-martinez-ya-es-leyenda-en-el-inter-de-milan-llego-a-los-171-goles-y-se-metio-en-el-top-3-de-maximos-goleadores-de-la-historia","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/08\/lautaro-martinez-ya-es-leyenda-en-el-inter-de-milan-llego-a-los-171-goles-y-se-metio-en-el-top-3-de-maximos-goleadores-de-la-historia\/","title":{"rendered":"Lautaro Mart\u00ednez ya es leyenda en el Inter de Mil\u00e1n: lleg\u00f3 a los 171 goles y se meti\u00f3 en el top 3 de m\u00e1ximos goleadores de la historia"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/lautaro-martinez-ya-es-leyenda-en-el-inter-de-milan-llego-a-los-171-goles-y-se-metio-en-el-top-3-de-maximos-goleadores-de-la-historia.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/lautaro-martinez-ya-es-leyenda-en-el-inter-de-milan-llego-a-los-171-goles-y-se-metio-en-el-top-3-de-maximos-goleadores-de-la-historia-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"element-body-0\" readability=\"64\">\n<p><strong>Lautaro Mart\u00ednez ya es leyenda en el Inter de Mil\u00e1n. <\/strong>El capit\u00e1n del Nerazzurro volvi\u00f3 a a notar en la goleada ante el Sassuolo y alcanz\u00f3 los 171 goles, los mismos de una leyenda del club milan\u00e9s como <strong>Roberto Boninsegna<\/strong>, para convertirse en el tercer m\u00e1ximo goleador del club milan\u00e9s. Por delante solo tiene a <strong>Alessandro Altobelli<\/strong> (209) y la gran marca de <strong>Giuseppe Meazza<\/strong> (284), jugador que da nombre al estadio cuando juega el equipo del Toro y que es llamado San Siro cuando se presenta el Milan, su cl\u00e1sico rival.<\/p>\n<\/div>\n<div id=\"element-body-1\" readability=\"60\">\n<p><strong>Lautaro ya es el m\u00e1ximo goleador hist\u00f3rico de los &#8216;nerazzurri&#8217; en la Champions League<\/strong> y m\u00e1ximo goleador extranjero de la entidad interista. En noviembre hab\u00eda igualado con su gol al Kairat Almaty, los 25 en Liga de Campeones de otro argentinos: Hern\u00e1n Crespo.<\/p>\n<\/div>\n<div id=\"element-body-2\" readability=\"27.037542662116\">\n<blockquote class=\"twitter-tweet\" readability=\"8.7474402730375\">\n<p lang=\"es\" dir=\"ltr\">SI HAY GOLEADA, UNO DEL TORO NO PUEDE FALTAR<\/p>\n<p>Lautaro Mart\u00ednez aport\u00f3 con un remate cruzado en el parcial 3-0 del Inter ante Sassuolo por la Serie A.<\/p>\n<p>\u25b6\ufe0f Mir\u00e1 la \ud83c\uddee\ud83c\uddf9 <a href=\"https:\/\/twitter.com\/hashtag\/SerieA?src=hash&amp;ref_src=twsrc%5Etfw\">#SerieA<\/a> en el Plan Premium de <a href=\"https:\/\/twitter.com\/hashtag\/DisneyPlus?src=hash&amp;ref_src=twsrc%5Etfw\">#DisneyPlus<\/a><a href=\"https:\/\/t.co\/BzGRDIVmnk\">pic.twitter.com\/BzGRDIVmnk<\/a><\/p>\n<p>\u2014 ESPN Argentina (@ESPNArgentina) <a href=\"https:\/\/twitter.com\/ESPNArgentina\/status\/2020572428385100151?ref_src=twsrc%5Etfw\">February 8, 2026<\/a><\/p><\/blockquote><\/div>\n<div id=\"element-body-3\" readability=\"61\">\n<p>Se coloc\u00f3, por tanto, tambi\u00e9n en el tercer puesto de argentinos m\u00e1s prol\u00edficos de la &#8216;Champions&#8217;, solo superado por los 41 tantos de Sergio Ag\u00fcero y los 129 de Leo Messi<\/p>\n<\/div>\n<div id=\"element-body-4\" readability=\"63\">\n<p>Este domingo, el Inter aplast\u00f3 5-0 al Sassuolo por la fecha 24 de la Serie A para aumentar su ventaja al tope del torneo. El alem\u00e1n Yann Bisseck (11&#8242;), el franc\u00e9s Marcus Thuram (28&#8242;) anotaron antes que el argentino, que marc\u00f3 el tercero. El suizo Samuel Akanji (54&#8242;) y Lu\u00eds Henrique (89&#8242;) completaron la goleada en el Mapei Stadium de Reggio Emilia.<\/p>\n<\/div>\n<div id=\"element-body-5\" readability=\"62\">\n<p>Inter suma ahora 58 puntos, ocho m\u00e1s que Milan, que recibir\u00e1 al Como (41) el mi\u00e9rcoles 18 en un partido aplazado porque el pasado viernes 6 de febrero, el San Siro alberg\u00f3 la ceremonia inaugural de los Juegos Ol\u00edmpicos Invernales de Mil\u00e1n-Cortina 2026.<\/p>\n<\/div>\n<p><h2>Ordo\u00f1ez y el sue\u00f1o del pibe: hizo su primer gol en Italia para darle la victoria al Parma sobre la hora<\/h2>\n<\/p>\n<div id=\"element-body-7\" readability=\"62\">\n<p>El argentino <strong>Christian Ord\u00f3\u00f1ez<\/strong>, con un golazo desde fuera del \u00e1rea, regal\u00f3 este domingo una victoria fundamental para el <strong>Parma<\/strong> del espa\u00f1ol Carlos Cuesta ante el Bolonia (0-1) que aleja a su equipo de los puestos de descenso. El primer gol en la carrera profesional del ex V\u00e9lez Ord\u00f3\u00f1ez bien puede valer la salvaci\u00f3n al Parma. <\/p>\n<\/div>\n<div id=\"element-body-8\" readability=\"62\">\n<p>En el minuto 95 de un partido tremendamente disputado y ca\u00f3tico, con dos expulsiones y un gol anulado, el argentino criado en V\u00e9lez Sarsfield se invent\u00f3 un zapatazo desde fuera del \u00e1rea que agarr\u00f3 completamente desprevenido a Skorupski, meta del Bolonia.<\/p>\n<\/div>\n<div id=\"element-body-9\" readability=\"26.289808917197\">\n<blockquote class=\"twitter-tweet\" readability=\"6.4713375796178\">\n<p lang=\"es\" dir=\"ltr\">\u00a1TENEMOS EL GOLAZO DEL DOMINGO Y ES DE UN ARGENTINO! Christian Ord\u00f3\u00f1ez prob\u00f3 desde afuera del \u00e1rea y estamp\u00f3 esta hermosura para darle el 1-0 a Parma sobre Bologna en tiempo de descuento.<\/p>\n<p>\ud83d\udcfa Mir\u00e1 la <a href=\"https:\/\/twitter.com\/hashtag\/SerieA?src=hash&amp;ref_src=twsrc%5Etfw\">#SerieA<\/a> por <a href=\"https:\/\/twitter.com\/hashtag\/DisneyPlus?src=hash&amp;ref_src=twsrc%5Etfw\">#DisneyPlus<\/a> Plan Premium <a href=\"https:\/\/t.co\/wQ6EQCCRIU\">pic.twitter.com\/wQ6EQCCRIU<\/a><\/p>\n<p>\u2014 SportsCenter (@SC_ESPN) <a href=\"https:\/\/twitter.com\/SC_ESPN\/status\/2020490406190789018?ref_src=twsrc%5Etfw\">February 8, 2026<\/a><\/p><\/blockquote><\/div>\n<div id=\"element-body-10\" readability=\"64\">\n<p>Celebr\u00f3 a lo grande el Parma, con <strong>Carlos Cuesta <\/strong>a la cabeza, <strong>el entrenador m\u00e1s joven de la Serie A<\/strong>, consciente de que esta primera victoria tras cuatro jornadas sin ganar coloca al equipo en una buena situaci\u00f3n para otear la salvaci\u00f3n. Es decimocuarto con 26 puntos, ocho por encima de los puestos de descenso que marca la &#8216;Fiore&#8217;.<\/p>\n<\/div>\n<div id=\"element-body-11\" readability=\"58\">\n<p>Se quit\u00f3 un gran peso de encima el combinado parmesano despu\u00e9s de un partido con episodios que bien pudieron haber cambiado el duelo.<\/p>\n<\/div>\n<div id=\"element-body-12\" readability=\"20.637931034483\">\n<blockquote class=\"twitter-tweet\" readability=\"3.9310344827586\">\n<p lang=\"en\" dir=\"ltr\">SCENES! Ordo\u00f1ez might have just won it in the 95th minute for <a href=\"https:\/\/twitter.com\/ParmaCalcio_en?ref_src=twsrc%5Etfw\">@ParmaCalcio_en<\/a> with a long range strike! \ud83e\udd2f\ud83e\udd2f<a href=\"https:\/\/twitter.com\/hashtag\/BolognaParma?src=hash&amp;ref_src=twsrc%5Etfw\">#BolognaParma<\/a> 0-1 <a href=\"https:\/\/t.co\/A4pGAnsFQg\">pic.twitter.com\/A4pGAnsFQg<\/a><\/p>\n<p>\u2014 Lega Serie A (@SerieA_EN) <a href=\"https:\/\/twitter.com\/SerieA_EN\/status\/2020491556579353027?ref_src=twsrc%5Etfw\">February 8, 2026<\/a><\/p><\/blockquote><\/div>\n<div id=\"element-body-13\" readability=\"64\">\n<p>Jug\u00f3 con superioridad desde el 18 hasta el 79, cuando fue expulsado el argentino Mariano Troilo; celebr\u00f3 el tanto en contra del argentino Santiago Castro hasta que el VAR lo anul\u00f3 por posici\u00f3n antirreglamentaria de otro argentino, Mateo Pellegrino, al entender que interfiri\u00f3 en el remate de Castro hacia su propia meta; y sufri\u00f3 las acometidas de Orsolini en los minutos finales, con un palo y dos manos salvadoras del meta Edoardo Corvi que bien mantuvieron el resultado.<\/p>\n<\/div>\n<div id=\"element-body-14\" readability=\"57\">\n<p>Los tres puntos son fundamentales para un Parma que da un paso gigante a la salvaci\u00f3n.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lautaro Mart\u00ednez ya es leyenda en el Inter de Mil\u00e1n. El capit\u00e1n del Nerazzurro volvi\u00f3 a a notar en la goleada ante el Sassuolo y alcanz\u00f3 los 171 goles, los mismos de una leyenda del club milan\u00e9s como Roberto Boninsegna, para convertirse en el tercer m\u00e1ximo goleador del club milan\u00e9s. Por delante solo tiene a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184413"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184413"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184414"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184413"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}