{"id":184409,"date":"2026-02-08T08:42:42","date_gmt":"2026-02-08T08:42:42","guid":{"rendered":"https:\/\/somoscordobeses.com\/2026\/02\/08\/instituto-busca-su-primer-triunfo-ante-gimnasia-de-mendoza\/"},"modified":"2026-02-08T08:42:42","modified_gmt":"2026-02-08T08:42:42","slug":"instituto-busca-su-primer-triunfo-ante-gimnasia-de-mendoza","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/08\/instituto-busca-su-primer-triunfo-ante-gimnasia-de-mendoza\/","title":{"rendered":"Instituto busca su primer triunfo ante Gimnasia de Mendoza"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/instituto-busca-su-primer-triunfo-ante-gimnasia-de-mendoza.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Mendoza. Gimnasia de Mendoza e Instituto se enfrentar\u00e1n este domingo, desde las 22:15, en el Estadio V\u00edctor Antonio Legrotaglie por la cuarta fecha del Torneo Apertura 2026. El Lobo viene de perder 4-0 frente a Uni\u00f3n y otra derrota podr\u00eda desencadenar en la salida de su DT, mientras que la Gloria va por su primer triunfo. El encuentro ser\u00e1 televisado por ESPN Premium.<\/p>\n<p>El Lobo mendocino arranc\u00f3 el torneo con una gran victoria 1-0 visitando a Central C\u00f3rdoba pero luego perdi\u00f3 1-0 en su casa ante San Lorenzo y en la fecha pasada fue goleado 4-0 por Uni\u00f3n en Santa Fe. Este \u00faltimo resultado puso en duda la continuidad de Ariel Broggi como entrenador, y una ca\u00edda frente a Instituto podr\u00eda desencadenar en su salida del club.<\/p>\n<p>Por su parte, la Gloria tambi\u00e9n comenz\u00f3 el torneo de mala manera, y en la segunda fecha Daniel Oldr\u00e1 renunci\u00f3 como DT. Perdi\u00f3 1-0 con V\u00e9lez y 2-1 ante Platense, y en la tercera jornada rescat\u00f3 un empate ag\u00f3nico frente a Lan\u00fas en Alta C\u00f3rdoba. Ahora, en su visita a Mendoza intentar\u00e1 sumar de a tres por primera vez en el Apertura, con Bruno Martelotto y Daniel Jim\u00e9nez como dupla t\u00e9cnica interina mientras la dirigencia busca un nuevo entrenador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mendoza. Gimnasia de Mendoza e Instituto se enfrentar\u00e1n este domingo, desde las 22:15, en el Estadio V\u00edctor Antonio Legrotaglie por la cuarta fecha del Torneo Apertura 2026. El Lobo viene de perder 4-0 frente a Uni\u00f3n y otra derrota podr\u00eda desencadenar en la salida de su DT, mientras que la Gloria va por su primer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184410,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184409"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184409"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184410"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184409"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}