{"id":184368,"date":"2026-02-07T08:21:03","date_gmt":"2026-02-07T08:21:03","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/fitness\/como-hacer-bien-aleteo-piernas-pilates-tonificar-core-mejor-ejercicio-fuerza-a-los-50-20260207185909-nt.html"},"modified":"2026-02-07T08:21:03","modified_gmt":"2026-02-07T08:21:03","slug":"como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/07\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50\/","title":{"rendered":"C\u00f3mo hacer bien el aleteo de piernas de Pilates para tonificar el core con el mejor ejercicio de fuerza a los 50"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p><!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial \">\n<!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial__signature \">\n<!-- IMAGE AUTHOR -->\n<picture class=\"voc-image-signature\">\n<img class=\"voc-image-signature__img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50.jpg\" alt=\"Tamara Vila\">\n<\/picture>\n<!-- INFO AUTHOR --> <\/div><\/div>\n<p><!-- COMPONENTS --><\/p>\n<p class=\"voc-paragraph\">El aleteo de piernas de Pilates te permite trabajar varios m\u00fasculos de la zona abdominal y la espalda baja sin necesidad de equipo adicional. Vale contigo y tus ganas. Es un estupendo <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/ejercicio-fuerza-retrasar-perdida-muscular-mejorar-longevidad-20260104092648-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"ejercicio de fuerza\" data-mrf-link=\"www.mujerhoy.com\">ejercicio de fuerza<\/a> que la mayor\u00eda de mujeres pueden hacer. A los 50 y en adelante. Una gran opci\u00f3n para a\u00f1adir a tu rutina de ejercicios habitual para <a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/ejercicios-abdominales-core-fuerte-vientre-plano-funcionan-20251105160441-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\"fortalecer el core\" data-mrf-link=\"www.mujerhoy.com\">fortalecer el core<\/a>.<\/p>\n<p class=\"voc-paragraph\">Pero aunque tengas una idea de qu\u00e9 el aleteo de piernas de Pilates, es comprensible que tengas dudas sobre c\u00f3mo hacerlas correctamente y qu\u00e9 zonas espec\u00edficas trabajan. Adem\u00e1s, quiz\u00e1 hayas visto c\u00f3mo se hacen y te parezcan complicadas. Si aprendes <strong>c\u00f3mo realizar bien este ejercicio<\/strong>, seguro que ya no las ves tan dif\u00edciles de hacer.<\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/dead-hang-facil-ejercicio-viral-mejora-fuerza-movilidad-dos-semanas-20251220094343-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Dead Hang, el f\u00e1cil ejercicio viral que mejora la fuerza y movilidad en dos semanas\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-1.jpg\" alt=\"Dead Hang, el f\u00e1cil ejercicio viral que mejora la fuerza y movilidad en dos semanas\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/ejercicio-fuerza-retrasar-perdida-muscular-mejorar-longevidad-20260104092648-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Por qu\u00e9 hasta el m\u00e1s sencillo ejercicio de fuerza es fundamental para retrasar la p\u00e9rdida muscular y mejorar longevidad\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-2.jpg\" alt=\"Por qu\u00e9 hasta el m\u00e1s sencillo ejercicio de fuerza es fundamental para retrasar la p\u00e9rdida muscular y mejorar longevidad\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Est\u00e1s ante un ejercicio abdominal de fuerza que se realiza acostada boca arriba en el suelo. Levantas las piernas del suelo y, manteni\u00e9ndolas rectas, mueves los pies hacia arriba y hacia abajo. Hay gente que hace el aleteo en una piscina como parte de un entrenamiento de nataci\u00f3n.<\/p>\n<p class=\"voc-paragraph\">Si bien el aleteo de piernas de Pilates se suele hacer boca arriba, tambi\u00e9n puedes realizarlas boca abajo si quieres trabajar los m\u00fasculos de la espalda baja. Trabajan principalmente los <strong>m\u00fasculos de los abdominales inferiores<\/strong>, lo que las convierte en una buena alternativa a abdominales y sentadillas si estos ejercicios se te atragantan. <\/p>\n<p class=\"voc-paragraph\">Cuando se realizan correctamente, involucran los abdominales inferiores y los flexores de la cadera, adem\u00e1s de <strong>comprometer los cu\u00e1driceps<\/strong>. Tambi\u00e9n pueden activar los m\u00fasculos de la espalda baja. Y si los haces tumbada boca abajo, incluso pueden trabajar los gl\u00fateos superiores.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nC\u00f3mo hacer bien el aleteo de piernas de Pilates<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Para hacer bien las patadas de aleteo, se recomienda seguir cuidadosamente los siguientes pasos y realizar cada movimiento <strong>de forma lenta y controlada<\/strong>. <\/p>\n<p class=\"voc-paragraph\">\u2022 Acu\u00e9state boca arriba <strong>sobre una superficie plana y c\u00f3moda<\/strong>, como por ejemplo una esterilla de yoga. <\/p>\n<p class=\"voc-paragraph\">\u2022 Manteniendo las piernas rectas, haz un movimiento de tijera hacia arriba y hacia abajo separ\u00e1ndolas <strong>entre 15 y 20 cent\u00edmetros<\/strong> mientras presionas la parte baja de la espalda contra el suelo.<\/p>\n<p class=\"voc-paragraph\">\u2022 Algunas personas prefieren colocar las manos y los antebrazos debajo de los gl\u00fateos, mientras que otras <strong>mantienen los brazos a los costados<\/strong>.<\/p>\n<p class=\"voc-paragraph\">\u2022 <strong>Las piernas deben estar r\u00edgidas<\/strong> como una tabla.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nC\u00f3mo hacer el aleteo de Pilates a los 50<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Si eres principiante, se recomienda hacer el aleteo de piernas de Pilates con los talones tocando el suelo. Las mujeres con m\u00e1s experiencia deber\u00edan intentar mantener los talones a unos cent\u00edmetros del suelo. En cuanto a la velocidad, esto es algo que t\u00fa decides y que en \u00faltima instancia depende de ti. La velocidad no importa demasiado en este ejercicio. <strong>Lo importante es el tiempo que est\u00e1s<\/strong>. Procura ir a un ritmo que te resulte moderado y c\u00f3modo. Ni demasiado r\u00e1pido ni demasiado lento.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-809\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-3.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Mujer practicando Pilates sobre esterilla.\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nMujer practicando Pilates sobre esterilla.<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nUNPLASH<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-809\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-809\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-3.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Empezar despacio es una buena idea. Puedes variar la velocidad de las repeticiones, aunque se recomienda ir a ritmo lento pero constante al principio. Conc\u00e9ntrate en la t\u00e9cnica correcta, prestando especial atenci\u00f3n a la posici\u00f3n de la zona lumbar. A los 50, y m\u00e1s si eres nueva en el aleteo de piernas de Pilates, se sugiere intentar series y repeticiones <strong>asequibles y sostenibles<\/strong>.<\/p>\n<p class=\"voc-paragraph\">Por ejemplo, intenta hacer 10 segundos de actividad, seguidos de 30 segundos de descanso. Repite esto tres veces. A medida que te sientas m\u00e1s c\u00f3moda con los movimientos y desarrolles los m\u00fasculos del core, puedes aumentar gradualmente el tiempo de cada serie. <strong>Y recuerda:<\/strong> una velocidad mayor lo hace m\u00e1s dif\u00edcil y tampoco conviene ir ni demasiado lento ni demasiado r\u00e1pido. <\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/50-diarios-rutina-cuatro-ejercicios-clasicos-construir-fibra-musculo-menos-tiempo-20260104120115-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"'50 diarios' la demoledora rutina de cuatro ejercicios cl\u00e1sicos para construir fibra y m\u00fasculo en menos tiempo\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-4.jpg\" alt=\"'50 diarios' la demoledora rutina de cuatro ejercicios cl\u00e1sicos para construir fibra y m\u00fasculo en menos tiempo\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/vivir\/fitness\/postura-soga-pasasana-yoga-mejorar-flexibilidad-equilibrio-concentracion-respiracion-profunda-20260101113732-nt.html#vtm_modulosEngag=mod-rel:vivir:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Postura de la soga (Pasasana), yoga para mejorar flexibilidad, equilibrio, concentraci\u00f3n y respiraci\u00f3n profunda\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/como-hacer-bien-el-aleteo-de-piernas-de-pilates-para-tonificar-el-core-con-el-mejor-ejercicio-de-fuerza-a-los-50-5.jpg\" alt=\"Postura de la soga (Pasasana), yoga para mejorar flexibilidad, equilibrio, concentraci\u00f3n y respiraci\u00f3n profunda\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El aleteo de piernas de Pilates te permite trabajar varios m\u00fasculos de la zona abdominal y la espalda baja sin necesidad de equipo adicional. Vale contigo y tus ganas. Es un estupendo ejercicio de fuerza que la mayor\u00eda de mujeres pueden hacer. A los 50 y en adelante. Una gran opci\u00f3n para a\u00f1adir a tu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184368"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184368"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184369"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184368"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}