{"id":184298,"date":"2026-02-07T15:49:25","date_gmt":"2026-02-07T15:49:25","guid":{"rendered":"https:\/\/somoscordobeses.com\/2026\/02\/07\/moreno-lamenta-perdidas-millonarias-por-el-temporal-en-andalucia-en-otra-jornada-critica-no-bajemos-la-guardia\/"},"modified":"2026-02-07T15:49:25","modified_gmt":"2026-02-07T15:49:25","slug":"moreno-lamenta-perdidas-millonarias-por-el-temporal-en-andalucia-en-otra-jornada-critica-no-bajemos-la-guardia","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/07\/moreno-lamenta-perdidas-millonarias-por-el-temporal-en-andalucia-en-otra-jornada-critica-no-bajemos-la-guardia\/","title":{"rendered":"Moreno lamenta p\u00e9rdidas millonarias por el temporal en Andaluc\u00eda en otra jornada cr\u00edtica: \u00abNo bajemos la guardia\u00bb"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/moreno-lamenta-perdidas-millonarias-por-el-temporal-en-andalucia-en-otra-jornada-critica-no-bajemos-la-guardia.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>El presidente de la Junta de Andaluc\u00eda, <strong>Juanma Moreno<\/strong>, comparece este s\u00e1bado desde C\u00f3rdoba para valorar los efectos de la borrasca Marta en Andaluc\u00eda. Andaluc\u00eda supera los<strong> 11.000 desalojados <\/strong>en las provincias de C\u00e1diz, C\u00f3rdoba, Ja\u00e9n, Sevilla, Granada, Huelva y M\u00e1laga. De ese total, alrededor de<strong> 8.000 vecinos pertenecen a municipios gaditanos <\/strong>como Jerez de la Frontera, Arcos de la Frontera, Grazalema, El Puerto de Santa Mar\u00eda, Puerto Serrano, Los Barrios, San Mart\u00edn del Tesorillo, Jimena de la Frontera y Genalguacil. Desde el Puesto de Mando Avanzado de C\u00f3rdoba, se sigue la crecida del Guadalquivir. \u00abTodos los operativos est\u00e1n trabajando y en alerta\u00bb, comunic\u00f3 el presidente andaluz, que pide \u00abcautela\u00bb y \u00abno bajar la guardia\u00bb.<\/p>\n<p><strong>La \u201csituaci\u00f3n es l\u00edmite\u201d,<\/strong> admiti\u00f3 Moreno, que la calific\u00f3 de \u201ccompleja, singular y dif\u00edcil\u201d y estas circunstancias se alargar\u00e1n hasta el pr\u00f3ximo martes. Se elevan a <strong>casi 10.000 las incidencias <\/strong>gestionadas desde el pasado 27 de enero y el plan de emergencias se mantendr\u00e1 en <strong>nivel 2 afectando a toda Andaluc\u00eda.<\/strong> \u201cLa borrasca Marta ya est\u00e1 entrando y el lunes se espera otro frente, otro r\u00edo atmosf\u00e9rico que al parecer, seg\u00fan Aemet, es menos intenso de lo vivido hasta ahora\u201d, apunt\u00f3 el presidente, que admiti\u00f3 que cualquier lluvia pone a la comunidad \u201cen una situaci\u00f3n de aprieto\u201d. Se pide <strong>mucha prudencia y que los desalojados no intenten volver a sus casas.<\/strong><\/p>\n<p>El alcalde de C\u00f3rdoba, <strong>Jos\u00e9 Mar\u00eda Bellido<\/strong>, ha explicado que el caudal del r\u00edo Guadalquivir est\u00e1 bajando de ayer a hoy. \u201cEsa bajada, no obstante, desgraciadamente<strong> lo que nos transmite la Cuenca Hidrogr\u00e1fica es que la borrasca Marta afecta a toda la cuenca del Guadalquivir y es un d\u00eda de subida de nuevo de caudal y nivel de agua<\/strong>. Toca extremar la vigilancia y ver hasta qu\u00e9 punto llega\u201d, se\u00f1al\u00f3 el alcalde. Se har\u00e1 un<strong> seguimiento y vigilancia reforzada<\/strong> para evaluar la situaci\u00f3n. Aprovechando la bajada del r\u00edo se ha permitido que los vecinos que tengas necesidades excepcionales puedan volver a sus casas a recoger medicinas o documentaci\u00f3n, siempre acompa\u00f1ados. En estos momentos en C\u00f3rdoba hay<strong> unas 700 viviendas desalojadas, m\u00e1s de mil personas.<\/strong><\/p>\n<h2>Drama en muchas cosechas<\/h2>\n<p>El <strong>impacto econ\u00f3mico de este tren de borrascas \u00abva a ser millonario<\/strong>\u00bb en Andaluc\u00eda a la espera de que todo pase y se pueda hacer cuantificaci\u00f3n de da\u00f1os. El temporal ha golpeado muy duramente a agricultura, ganader\u00eda y pesca, amarrada desde diciembre. Solo en<strong> carreteras auton\u00f3micas el impacto es de 500 millones de euros<\/strong>. Moreno reclam\u00f3 al Estado que se movilice ya para poner en marcha el <strong>Fondo de Contingencia<\/strong>, con 3.964 millones de euros, reclam\u00e1ndole a la vicepresidenta y ministra de Hacienda, Mar\u00eda Jes\u00fas Montero, que active ya estos recursos. Adem\u00e1s el Gobierno debe movilizarse para reclamar el <strong>Fondo de Solidaridad de la Uni\u00f3n Europea<\/strong>. El desastre va a ser total para muchas cosechas. Desde el Gobierno andaluz se reprogramar\u00e1 el Presupuesto para destinar dinero de otras partidas a esta emergencia. \u00abDe manera inmediata hay que buscar los recursos econ\u00f3micos\u00bb, reclam\u00f3 el presidente andaluz.<\/p>\n<p>Moreno reclam\u00f3 \u00abla m\u00e1xima prudencia a todos y cada uno de los ciudadanos de Andaluc\u00eda\u00bb. \u00abNo podemos confiarnos nunca\u00bb, advirti\u00f3, \u00abel agua puede ser traicionera e imprevisible y quedan fen\u00f3meno de lluvias importantes desde hoy hasta el martes, cuatro d\u00edas\u00bb. Todo el dispositivo de emergencia sigue en marcha hasta el \u00faltimo minuto.<\/p>\n<h2>Zonas m\u00e1s castigadas<\/h2>\n<p>La comunidad andaluza ha registrado <strong>m\u00e1s de 5.300 incidencias (5.310) como consecuencia del paso de la borrasca Leonardo<\/strong>, mientras que el acumulado desde el pasado 27 de enero asciende a un total de 9.509 incidencias. Adem\u00e1s, las provincias de M\u00e1laga, Granada y C\u00e1diz presentan <strong>problemas en la red de abastecimiento de agua potable, y el n\u00famero de <\/strong>carreteras cortadas en la comunidad se sit\u00faa en 85.<\/p>\n<p>No hay tregua. La tierra ya no es capaz de absorber m\u00e1s agua en Andaluc\u00eda tras<strong>&nbsp;un mes de enero y parte de febrero encadenando borrascas<\/strong>.&nbsp;En muchos puntos de Andaluc\u00eda embalses r\u00edos y arroyos est\u00e1n al m\u00e1ximo. El&nbsp;balance hasta el momento es desolador: una mujer&nbsp;ha perdido la vida en M\u00e1laga&nbsp;y&nbsp;los geol\u00f3gos del CSIC&nbsp;estudian la Sierra de Grazalema para saber por qu\u00e9 cruje la tierra y si hay peligro de derrumbes de viviendas y deslizamientos de tierra, tras detectarse peque\u00f1os hidroseismos. A algunos vecinos ya se les ha comunicado que<strong>&nbsp;pasar\u00e1 al menos una semana hasta que puedan volver a sus casas<\/strong>. La situaci\u00f3n es especialmente preocupante en&nbsp;<strong>Grazalema, C\u00f3rdoba, Ja\u00e9n, Jerez o el Campo de Gibraltar<\/strong>&nbsp;que se agravar\u00e1 si hay precipitaciones intensas.El alcalde de C\u00f3rdoba, Jos\u00e9 Mar\u00eda Bellido, ya ha dejado claro que la ciudad entra desde este s\u00e1bado&nbsp;<strong>\u00aben zona de riesgo\u00bb.<\/strong><\/p>\n<p><strong>En Sevilla, la provincia tambi\u00e9n est\u00e1 en vilo.<\/strong>&nbsp;Hasta nueve municipios vigilan de cerca por&nbsp;el peligro inminente de inundaciones&nbsp;de sus n\u00facleos urbanos. Est\u00e1n&nbsp;en rojo los r\u00edos&nbsp;<strong>Genil, Corbones, Guada\u00edra, Genil y Gualdalquivir, as\u00ed como la Rivera del Huesna<\/strong>. Una situaci\u00f3n que amenaza a los municipios de \u00c9cija, Carmona, Alcal\u00e1 de Guada\u00edra , La Puebla de Cazalla, Guillena, Villanueva del R\u00edo y Minas, Cantillana , Arahal y Lora del R\u00edo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Junta de Andaluc\u00eda, Juanma Moreno, comparece este s\u00e1bado desde C\u00f3rdoba para valorar los efectos de la borrasca Marta en Andaluc\u00eda. Andaluc\u00eda supera los 11.000 desalojados en las provincias de C\u00e1diz, C\u00f3rdoba, Ja\u00e9n, Sevilla, Granada, Huelva y M\u00e1laga. De ese total, alrededor de 8.000 vecinos pertenecen a municipios gaditanos como Jerez de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184299,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184298"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184298"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184299"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184298"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}