{"id":184145,"date":"2026-02-05T22:43:02","date_gmt":"2026-02-05T22:43:02","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/05\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive\/"},"modified":"2026-02-05T22:43:02","modified_gmt":"2026-02-05T22:43:02","slug":"cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/05\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive\/","title":{"rendered":"Cae desde el d\u00e9cimo piso sobre un mont\u00edculo de nieve y sobrevive"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive.jpg\"><\/p>\n<p>Una adolescente de 16 a\u00f1os logr\u00f3 sobrevivir tras caer desde el d\u00e9cimo piso de un edificio en Mosc\u00fa,&nbsp;<a href=\"https:\/\/www.mk.ru\/incident\/2026\/02\/05\/v-moskve-16letnyaya-devushka-vyzhila-posle-padeniya-s-10-etazha.html\" target=\"_blank\" rel=\"noopener noreferrer\">informa<\/a> un medio local. &nbsp;<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 Card-default \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"> <picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-3.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-2.jpg, https:\/\/actualidad.rt.com\/actualidad\/460, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-3.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-2.jpg\" class=\"Picture-root Picture-default lazyload\" alt=\"VIDEOS, FOTOS: Mosc\u00fa lucha contra tormenta de nieve r\u00e9cord\"><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/cae-desde-el-decimo-piso-sobre-un-monticulo-de-nieve-y-sobrevive-3.jpg\" alt=\"VIDEOS, FOTOS: Mosc\u00fa lucha contra tormenta de nieve r\u00e9cord\"><\/noscript> <\/div><\/div>\n<\/article><\/div><\/div>\n<p>Seg\u00fan testigos, la v\u00edctima cay\u00f3 este mi\u00e9rcoles por la tarde <strong>desde gran altura directamente sobre un enorme mont\u00edculo de nieve<\/strong>&nbsp;acumulada junto a la fachada del edificio residencial. A pesar de la ca\u00edda, <strong>se mantuvo consciente<\/strong>, se levant\u00f3 por s\u00ed misma y camin\u00f3 hasta la planta baja del edificio, donde entr\u00f3 en un sal\u00f3n de belleza para pedir auxilio.&nbsp;<\/p>\n<p>Siguiendo instrucciones telef\u00f3nicas de personal m\u00e9dico, los empleados del local prestaron ayuda a la afectada y la cubrieron con una manta hasta la llegada de sus padres y los servicios de emergencia.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una adolescente de 16 a\u00f1os logr\u00f3 sobrevivir tras caer desde el d\u00e9cimo piso de un edificio en Mosc\u00fa,&nbsp;informa un medio local. &nbsp; Seg\u00fan testigos, la v\u00edctima cay\u00f3 este mi\u00e9rcoles por la tarde desde gran altura directamente sobre un enorme mont\u00edculo de nieve&nbsp;acumulada junto a la fachada del edificio residencial. A pesar de la ca\u00edda, se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":184146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184145"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=184145"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/184145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/184146"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=184145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=184145"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=184145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}