{"id":183848,"date":"2026-02-03T19:47:46","date_gmt":"2026-02-03T19:47:46","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/desgarrador-mensaje-novia-arbitro-murio-ruta-dirigir-final-torneo-regional-esperaba-casa_0_c4UW4OTPBr.html"},"modified":"2026-02-03T19:47:46","modified_gmt":"2026-02-03T19:47:46","slug":"el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/03\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa\/","title":{"rendered":"El desgarrador mensaje de la novia del \u00e1rbitro que muri\u00f3 en la ruta tras dirigir una final del Torneo Regional: \u00abTe esperaba en casa\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa.jpg\"><\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-0\" readability=\"65\">\n<p>Una vez m\u00e1s, la tragedia golpe\u00f3 al arbitraje argentino. <strong>Las rutas del pa\u00eds, escenario habitual de traslados extensos y silenciosos despu\u00e9s de cada fecha<\/strong>, volvieron a ser noticia por un accidente fatal que enlut\u00f3 al f\u00fatbol nacional. No se trata de un hecho aislado: en 2006, dos \u00e1rbitros murieron tras un choque en C\u00f3rdoba; en 2015, cuatro jueces de la Liga Cordobesa perdieron la vida en otro siniestro vial; y en los \u00faltimos a\u00f1os se repitieron episodios graves que dejaron heridos y v\u00edctimas fatales.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-1\" readability=\"61\">\n<p>Ese recorrido doloroso sum\u00f3 este lunes un nuevo nombre.<strong> Emanuel Leguizam\u00f3n, \u00e1rbitro pampeano de apenas 24 a\u00f1os, muri\u00f3 en un accidente de tr\u00e1nsito cuando regresaba de dirigir en el Sur del pa\u00eds. <\/strong><\/p>\n<\/div>\n<p><h2>El accidente en la Ruta Nacional 3<\/h2>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-3\" readability=\"64\">\n<p><strong>El accidente ocurri\u00f3 minutos antes del mediod\u00eda del lunes en la Ruta Nacional 3, en un tramo conocido como Ca\u00f1ad\u00f3n Minerales, a unos 30 kil\u00f3metros de Caleta Olivia, provincia de Santa Cruz<\/strong>. Leguizam\u00f3n viajaba junto a <strong>Cristian Rubiano<\/strong> (\u00e1rbitro principal y conductor del veh\u00edculo); y los asistentes <strong>Diego Pereyra <\/strong>y <strong>Yas\u00fa Mu\u00f1oz<\/strong>. Ven\u00edan de dirigir el encuentro entre Atl\u00e9tico Boxing Club de R\u00edo Gallegos y La Amistad de Cipolletti, correspondiente a la final patag\u00f3nica del Torneo Federal Regional Amateur.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-4\" readability=\"61\">\n<p>Por causas que son materia de investigaci\u00f3n, el veh\u00edculo perdi\u00f3 el control, impact\u00f3 contra un guardarrail y volc\u00f3 a lo largo de aproximadamente 200 metros, hasta quedar completamente destruido.<\/p>\n<\/div>\n<div class=\"sc-98b114a2-0 bkqiHH image-embed image-embed \" id=\"element-body-5\"><picture class=\"sc-98b114a2-1 jRUlDm\"><source media=\"(min-width: 975px)\" width=\"720\" height=\"480\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa-2.jpg\"><img alt=\"Accidente de Emanuel Leguizamon. Foto:@abcediarioar\" loading=\"eager\" width=\"720\" height=\"480\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa-2.jpg\"><span class=\"epigraphe\" aria-hidden=\"true\">Accidente de Emanuel Leguizamon. Foto:@abcediarioar<\/span><span class=\"picture-open\"><button class=\"open-image\" aria-label=\"Open Image\"><\/button><\/span><\/picture><\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-6\" readability=\"63\">\n<p>Seg\u00fan testigos presenciales, los primeros auxilios fueron brindados por automovilistas que circulaban por la zona hasta la llegada de los servicios de emergencia.<strong> El cuerpo de Leguizam\u00f3n, se encontraba sin signos vitales, mientras que los otros ocupantes estaban conscientes y fueron asistidos y trasladados a centros de salud.<\/strong><\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-7\" readability=\"61\">\n<p>La noticia gener\u00f3 un inmediato impacto en el f\u00fatbol argentino.<strong> La Liga Profesional de F\u00fatbol dispuso un minuto de silencio en los partidos del lunes y martes del Torneo Apertura de Primera Divisi\u00f3n<\/strong>, mientras que la Asociaci\u00f3n Argentina de \u00c1rbitros (AAA) y la AFA expresaron p\u00fablicamente su pesar.<\/p>\n<\/div>\n<div class=\"sc-106e49c0-0 dcVumd freeHtml-embed undefined\" id=\"element-body-8\" readability=\"31.803797468354\">\n<blockquote class=\"twitter-tweet\" readability=\"9.4936708860759\">\n<p lang=\"es\" dir=\"ltr\">La Asociaci\u00f3n Argentina de \u00c1rbitros lamenta profundamente el tr\u00e1gico accidente ocurrido hoy, en el que perdi\u00f3 la vida nuestro colega Emanuel Leguizam\u00f3n.<\/p>\n<p>Acompa\u00f1amos con dolor a su familia, seres queridos y compa\u00f1eros en este dif\u00edcil momento.<\/p>\n<p>\u2014 Asociaci\u00f3n Argentina de \u00c1rbitros (@aaaprensa) <a href=\"https:\/\/twitter.com\/aaaprensa\/status\/2018440766201151936?ref_src=twsrc%5Etfw\">February 2, 2026<\/a><\/p><\/blockquote><\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-9\" readability=\"60\">\n<p><strong>\u201cProfundo dolor por nuestro compa\u00f1ero. Mis m\u00e1s profundas condolencias para su familia<\/strong>\u201d, escribi\u00f3 Federico Beligoy, director nacional de arbitraje.<\/p>\n<\/div>\n<p><h2>Qui\u00e9n era Emanuel Leguizam\u00f3n<\/h2>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-11\" readability=\"64\">\n<p>Nacido en La Pampa, Emanuel Leguizam\u00f3n hab\u00eda iniciado su camino en el f\u00fatbol como jugador en Deportivo Penales, experiencia que siempre destac\u00f3 como formativa para comprender el juego desde adentro.<strong> En 2017 dio el paso hacia el arbitraje en el \u00e1mbito local y, con apenas 22 a\u00f1os, <\/strong>se incorpor\u00f3 en 2022 a la Asociaci\u00f3n Pampeana de \u00c1rbitros de F\u00fatbol (APAF).<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-12\" readability=\"61\">\n<p><strong>En 2023 obtuvo el t\u00edtulo de \u00e1rbitro federal y entre 2023 y 2024 dirigi\u00f3 partidos de la Liga Cultural, el Torneo Provincial y el Torneo Regional Amateur<\/strong>, consolid\u00e1ndose como uno de los \u00e1rbitros j\u00f3venes con mayor proyecci\u00f3n en el \u00e1mbito pampeano.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-13\" readability=\"59\">\n<p>\u201c<strong>Lleg\u00f3 el d\u00eda m\u00e1s esperado. Soy \u00e1rbitro profesional de la Asociaci\u00f3n del F\u00fatbol Argentino<\/strong>\u201d, celebraba entonces en sus redes sociales.<\/p>\n<\/div>\n<div class=\"sc-98b114a2-0 bkqiHH image-embed image-embed \" id=\"element-body-14\"><picture class=\"sc-98b114a2-1 jRUlDm\"><source media=\"(min-width: 975px)\" width=\"720\" height=\"480\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa-3.jpg\"><img alt=\"Emanuel leguizam\u00f3n.foto: pampadiario.ok\" loading=\"eager\" width=\"720\" height=\"480\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/el-desgarrador-mensaje-de-la-novia-del-arbitro-que-murio-en-la-ruta-tras-dirigir-una-final-del-torneo-regional-te-esperaba-en-casa-3.jpg\"><span class=\"epigraphe\" aria-hidden=\"true\">Emanuel leguizam\u00f3n.foto: pampadiario.ok<\/span><span class=\"picture-open\"><button class=\"open-image\" aria-label=\"Open Image\"><\/button><\/span><\/picture><\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-15\" readability=\"63\">\n<p>En 2024, fue designado en encuentros decisivos: la revancha entre All Boys de Santa Rosa y Campos de General Acha por el Torneo Oficial de la Liga Cultural, la semifinal del Regional de f\u00fatbol femenino entre Costa Brava y Villa Mitre, y la final del Torneo Provincial entre Alvear FBC y All Boys de Santa Rosa.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-16\" readability=\"62\">\n<p>Fuera del campo, Leguizam\u00f3n combinaba el arbitraje con su trabajo en el rubro inmobiliario, aunque su objetivo estaba claro. \u201c<strong>Alg\u00fan d\u00eda voy a dejar el trabajo para dedicarme de lleno al arbitraje<\/strong>\u201d, proyectaba. Su sue\u00f1o era a\u00fan m\u00e1s grande: <strong>\u201cSue\u00f1o dirigir un Mundial<\/strong>\u201d.<\/p>\n<\/div>\n<p><h2>El dolor \u00edntimo y los mensajes de despedida<\/h2>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-18\" readability=\"61\">\n<p>Horas antes del accidente, Emanuel hab\u00eda compartido im\u00e1genes de su paso por Santa Cruz. En una foto tomada durante una visita al Glaciar Perito Moreno, escribi\u00f3 una frase que hoy adquiere un peso especial: \u201c<strong>Ser \u00e1rbitro en mi hermoso pa\u00eds\u201d<\/strong>.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-19\" readability=\"63\">\n<p>Tras confirmarse su fallecimiento, el dolor se expres\u00f3 con crudeza en las redes sociales, especialmente a trav\u00e9s de los mensajes de su pareja,<strong> Micaela Palavecino<\/strong>, que reflejaron el impacto humano detr\u00e1s de la noticia deportiva.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-20\" readability=\"60\">\n<p><strong>\u201cMe arrancaste el alma con tu partida, me dejaste vac\u00eda y perdida\u201d<\/strong>, escribi\u00f3 en una de sus publicaciones.<\/p>\n<\/div>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-21\" readability=\"64\">\n<p>Las palabras, m\u00e1s all\u00e1 de la viralizaci\u00f3n, exponen la dimensi\u00f3n muda de una tragedia: la de quienes acompa\u00f1an carreras construidas con esfuerzo, viajes interminables y sue\u00f1os que muchas veces se viven lejos del hogar. La de quienes esperan: <strong>\u201cTe est\u00e1bamos esperando en casa\u2026 dame fuerzas mi amor, porque por ac\u00e1 no sabemos c\u00f3mo seguir sin vos<\/strong>\u201d.<\/p>\n<\/div>\n<p><h2>Otras tragedias que marcaron al arbitraje argentino<\/h2>\n<\/p>\n<p><h3>2006 \u2013 Ruta provincial 17 (C\u00f3rdoba):<\/h3>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-24\" readability=\"60\">\n<p>Los \u00e1rbitros <strong>Jos\u00e9 Lucero<\/strong> (32 a\u00f1os) y <strong>Miguel \u00c1ngel Altamirano <\/strong>(44) murieron tras un choque entre dos veh\u00edculos en cercan\u00edas de Balnearia, cuando regresaban de cumplir funciones. El accidente ocurri\u00f3 de madrugada y dej\u00f3 adem\u00e1s cuatro personas heridas.<\/p>\n<\/div>\n<p><h3>2015 \u2013 Provincia de C\u00f3rdoba:<\/h3>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-26\" readability=\"63\">\n<p>Un siniestro vial acab\u00f3 con la vida de <strong>Ignacio Bustos, Marcos Fabi\u00e1n, Diego Bravo <\/strong>y<strong> Juan Massa<\/strong>, integrantes de una terna arbitral de la Liga Cordobesa de F\u00fatbol. El hecho motiv\u00f3 la suspensi\u00f3n de toda la actividad del fin de semana, salvo el Supercl\u00e1sico.<\/p>\n<\/div>\n<p><h3>2024 \u2013 Ruta 14 (Santa Fe):<\/h3>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-28\" readability=\"61\">\n<p>Una terna arbitral que hab\u00eda dirigido un partido de la Copa Santa Fe sufri\u00f3 un grave accidente al chocar contra un acoplado cerca de Pi\u00f1ero. Hubo heridos de consideraci\u00f3n, entre ellos <strong>Maximiliano Gonz\u00e1lez<\/strong>, con traumatismo de cr\u00e1neo.<\/p>\n<\/div>\n<p><h3>2025 \u2013 Ruta Nacional 168 (Santa Fe):<\/h3>\n<\/p>\n<div class=\"sc-45461e9c-0 eqiBeF container-text text-embed \" id=\"element-body-30\" readability=\"61\">\n<p>El \u00e1rbitro <strong>Diego Armando Komenek<\/strong>, de 40 a\u00f1os, muri\u00f3 tras caer a la Laguna Set\u00fabal luego de ser embestido mientras regresaba de arbitrar un partido. Su cuerpo fue hallado tras un operativo de b\u00fasqueda de 12 horas.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una vez m\u00e1s, la tragedia golpe\u00f3 al arbitraje argentino. Las rutas del pa\u00eds, escenario habitual de traslados extensos y silenciosos despu\u00e9s de cada fecha, volvieron a ser noticia por un accidente fatal que enlut\u00f3 al f\u00fatbol nacional. No se trata de un hecho aislado: en 2006, dos \u00e1rbitros murieron tras un choque en C\u00f3rdoba; en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":183849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183848"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=183848"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/183849"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=183848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=183848"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=183848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}