{"id":183782,"date":"2026-02-02T20:55:46","date_gmt":"2026-02-02T20:55:46","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=85359"},"modified":"2026-02-02T20:55:46","modified_gmt":"2026-02-02T20:55:46","slug":"con-micelio-de-hongos-y-carton-reciclado-reemplazan-el-uso-de-telgopor-y-espumas-poluretanicas-para-produccion-de-paneles-aislantes-que-se-utilizan-en-la-construccion","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/02\/con-micelio-de-hongos-y-carton-reciclado-reemplazan-el-uso-de-telgopor-y-espumas-poluretanicas-para-produccion-de-paneles-aislantes-que-se-utilizan-en-la-construccion\/","title":{"rendered":"Con micelio de hongos y cart\u00f3n reciclado reemplazan el uso de telgopor y espumas poluret\u00e1nicas para producci\u00f3n de paneles aislantes que se utilizan en la construcci\u00f3n"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/con-micelio-de-hongos-y-carton-reciclado-reemplazan-el-uso-de-telgopor-y-espumas-poluretanicas-para-produccion-de-paneles-aislantes-que-se-utilizan-en-la-construccion.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>La Asociaci\u00f3n de Vivienda Econ\u00f3mica lleva adelante este emprendimiento con apoyo del programa municipal \u00abCiudad Activa\u00bb.<\/strong><\/li>\n<li data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>Se trata de una soluci\u00f3n constructiva de bajo costo, que reduce el uso de pl\u00e1sticos y fomenta la econom\u00eda circular.<\/strong><\/li>\n<\/ul>\n<hr>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Por medio del financiamiento del programa municipal Ciudad Activa, la Asociaci\u00f3n de Vivienda Econ\u00f3mica (AVE) se desarrolla el proyecto \u201cBiofabricaci\u00f3n de paneles aislantes con micelio de hongos y cart\u00f3n reciclado\u201d.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Tal como su nombre lo indica, tiene como objetivo principal producir paneles aislantes con micelio de hongos y cart\u00f3n reciclado, una alternativa sustentable que \u201creemplaza los materiales pl\u00e1sticos como telgopor o espumas poliuret\u00e1nicas utilizadas actualmente en la construcci\u00f3n\u201d, se\u00f1ala Juli\u00e1n Gonz\u00e1lez Laria, presidente de AVE.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">A trav\u00e9s de una alianza con la cooperativa La Esperanza adquieren el cart\u00f3n, el insumo principal para el sustrato, mientras que el proyecto ProFunga proporciona las semillas para el cultivo de los hongos. La combinaci\u00f3n del sustrato con los hongos permite obtener el material utilizado en la elaboraci\u00f3n de los paneles.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Tras quedar seleccionado en la convocatoria 2025 de la iniciativa municipal Ciudad Activa, AVE trabaja en el acondicionamiento de algunos aspectos de su planta de producci\u00f3n ubicada en barrio Villa Siburu, la instalaci\u00f3n de maquinaria y la fabricaci\u00f3n de 18 metros cuadrados, necesarios como material aislante para una casa; \u201cy as\u00ed por primera vez tener un prototipo completo del aislante, ya que hasta ahora solo eran peque\u00f1as piezas\u201d, agrega Juli\u00e1n.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">A su vez, con el apoyo econ\u00f3mico ofrecen formaci\u00f3n al resto del equipo de AVE, a personas involucradas en el \u00e1rea de la construcci\u00f3n y a quienes buscan edificar espacios desde una responsabilidad con el ambiente; como tambi\u00e9n a interesados en iniciar emprendimientos de fabricaci\u00f3n aplicando este tipo de materiales. Gonz\u00e1lez comenta que proyectan a largo plazo \u201cpoder capacitar a otras organizaciones y emprendimientos, y multiplicar el conocimiento sobre esta tecnolog\u00eda\u201d.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">En lo que respecta al impacto positivo en el ambiente del uso del biopanel en viviendas y espacios con otros fines, Juli\u00e1n explica que \u201creducir\u00eda la cantidad de residuos urbanos (cart\u00f3n y poda vegetal), disminuir\u00eda el uso de energ\u00eda necesaria para calefaccionar o enfriar esos espacios y por ende desalentar el uso de energ\u00edas no renovables. Como as\u00ed tambi\u00e9n, mejorar\u00eda la capacidad de la tierra de regenerarse y dejar de depender de energ\u00edas f\u00f3siles\u201d.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong>AVE<\/strong><\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">La Asociaci\u00f3n de Vivienda Econ\u00f3mica es una entidad civil sin fines de lucro que tiene por objetivo principal \u201cpromover el acceso al h\u00e1bitat para los sectores populares como un modo de contribuir a la materializaci\u00f3n de otros derechos y favorecer el desarrollo humano\u201d, afirma Juli\u00e1n.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Arquitectos, dise\u00f1adores, qu\u00edmicos, t\u00e9cnicos, comunicadores, forman parte del equipo al que tambi\u00e9n se suman estudiantes a realizar pr\u00e1cticas pre profesionales asistidas.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">AVE forma parte del instituto CEVE (Centro Experimental de la Vivienda Econ\u00f3mica), dependiente del Conicet. El desarrollo del biopanel es producto de la investigaci\u00f3n llevada a cabo por Natalia Fern\u00e1ndez, becaria de Conicet en el CEVE, y la alianza con AVE.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\"><strong data-prosemirror-content-type=\"mark\" data-prosemirror-mark-name=\"strong\">Programa Ciudad Activa<\/strong><\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Desde 2021, Ciudad Activa brinda apoyo econ\u00f3mico a proyectos desarrollados por organizaciones del tercer sector.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">El programa municipal es ejecutado a trav\u00e9s de la Secretar\u00eda de Pol\u00edticas Sociales y Desarrollo Humano de la Municipalidad de C\u00f3rdoba. Su financiamiento proviene del Fondo Solidario de la tarjeta Activa, con el objetivo de contribuir de manera directa a los proyectos sociales que beneficien a la comunidad.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Desde su inicio, ha respaldado m\u00e1s de 120 proyectos que abarcan \u00e1reas como gastronom\u00eda, ecolog\u00eda, salud, dise\u00f1o, tecnolog\u00eda y fortalecimiento de cooperativas, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n de Vivienda Econ\u00f3mica lleva adelante este emprendimiento con apoyo del programa municipal \u00abCiudad Activa\u00bb. Se trata de una soluci\u00f3n constructiva de bajo costo, que reduce el uso de pl\u00e1sticos y fomenta la econom\u00eda circular. Por medio del financiamiento del programa municipal Ciudad Activa, la Asociaci\u00f3n de Vivienda Econ\u00f3mica (AVE) se desarrolla el proyecto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":183783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183782"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=183782"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/183783"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=183782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=183782"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=183782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}