{"id":183693,"date":"2026-02-01T22:48:27","date_gmt":"2026-02-01T22:48:27","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/01\/excesiva-canciller-frances-se-sincera-sobre-la-dependencia-de-europa-en-energia-y-seguridad\/"},"modified":"2026-02-01T22:48:27","modified_gmt":"2026-02-01T22:48:27","slug":"excesiva-canciller-frances-se-sincera-sobre-la-dependencia-de-europa-en-energia-y-seguridad","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/01\/excesiva-canciller-frances-se-sincera-sobre-la-dependencia-de-europa-en-energia-y-seguridad\/","title":{"rendered":"\u00abExcesiva\u00bb: canciller franc\u00e9s se sincera sobre la dependencia de Europa en energ\u00eda y seguridad"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/excesiva-canciller-frances-se-sincera-sobre-la-dependencia-de-europa-en-energia-y-seguridad.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>El ministro de Exteriores de Francia, Jean-Noel Barrot, resalt\u00f3 en una <a href=\"https:\/\/www.liberation.fr\/international\/trump-iran-ukraine-pour-le-ministre-jean-noel-barrot-leurope-peut-resister-a-la-brutalisation-du-monde-20260201_Q536XJV7XRCYZFXERUORUF3FLQ\/\" target=\"_blank\" rel=\"noopener noreferrer\">entrevista<\/a> con el medio Lib\u00e9ration que la dependencia de Europa en materia de energ\u00eda, seguridad, sanidad y otros \u00e1mbitos clave&nbsp;sigue siendo demasiado elevada.<\/p>\n<p>Seg\u00fan Barrot, la pandemia del covid-19 y el conflicto ruso-ucraniano puso de manifiesto una dependencia europea \u00aben materia energ\u00e9tica, alimentaria y m\u00e9dica\u00bb que, si bien se ha reducido desde entonces, \u00absigue siendo excesiva\u00bb, destac\u00f3&nbsp;<\/p>\n<p>Adem\u00e1s, se\u00f1al\u00f3 que las pretensiones de Estados Unidos sobre Groenlandia \u00abrevelaron las dependencias de Europa en materia de seguridad\u00bb.&nbsp;En este contexto, considera que el Viejo Continente \u00abdebe seguir rearm\u00e1ndose y endureci\u00e9ndose para asumir\u00bb su propia seguridad. \u00abEuropa debe decir &#8216;no&#8217; a toda forma de intimidaci\u00f3n y coerci\u00f3n, venga de donde venga. Para ello, debe acelerar la implementaci\u00f3n de una idea que hemos defendido casi diez a\u00f1os: la idea de la autonom\u00eda estrat\u00e9gica\u00bb, declar\u00f3.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Exteriores de Francia, Jean-Noel Barrot, resalt\u00f3 en una entrevista con el medio Lib\u00e9ration que la dependencia de Europa en materia de energ\u00eda, seguridad, sanidad y otros \u00e1mbitos clave&nbsp;sigue siendo demasiado elevada. Seg\u00fan Barrot, la pandemia del covid-19 y el conflicto ruso-ucraniano puso de manifiesto una dependencia europea \u00aben materia energ\u00e9tica, alimentaria y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":183694,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183693"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=183693"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/183694"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=183693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=183693"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=183693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}