{"id":183675,"date":"2026-02-01T20:02:50","date_gmt":"2026-02-01T20:02:50","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/01\/mas-que-una-foto-juez-bornoroni-y-de-loredo-mostraron-una-senal-de-convergencia-opositora-en-laboulaye\/"},"modified":"2026-02-01T20:02:50","modified_gmt":"2026-02-01T20:02:50","slug":"mas-que-una-foto-juez-bornoroni-y-de-loredo-mostraron-una-senal-de-convergencia-opositora-en-laboulaye","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/02\/01\/mas-que-una-foto-juez-bornoroni-y-de-loredo-mostraron-una-senal-de-convergencia-opositora-en-laboulaye\/","title":{"rendered":"M\u00e1s que una foto: Juez, Bornoroni y De Loredo mostraron una se\u00f1al de convergencia opositora en Laboulaye"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p>No fue una postal casual ni un gesto aislado. En <strong>Laboulaye<\/strong>, los tres principales referentes de la oposici\u00f3n cordobesa coincidieron en una escena cargada de simbolismo pol\u00edtico, en una ciudad que por un d\u00eda se convirti\u00f3 <strong>en epicentro del tablero provincial.<\/strong> <strong>Luis Juez, Gabriel Bornoroni y Rodrigo de Loredo<\/strong> compartieron territorio, agenda y mensajes, en una se\u00f1al que alimenta expectativas de <strong>convergencia opositora rumbo a 2027.<\/strong><\/p>\n<p>Tal como lo adelant\u00f3 <em>Perfil C\u00f3rdoba<\/em>, el binomio <strong>Juez\u2013Bornoroni <\/strong>encabez\u00f3 un encuentro con dirigentes y militantes del sur provincial, convocado por el Frente C\u00edvico, en la previa de la apertura de sesiones ordinarias de la Legislatura. El c\u00f3nclave se realiz\u00f3 en el Club Restaurante y tuvo como eje <strong>el fortalecimiento territorial, el intercambio pol\u00edtico y la organizaci\u00f3n de cara a lo que viene.<\/strong><\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/la-oposicion-afila-el-discurso-y-desafia-el-relato-de-llaryora.phtml\" rel=\"noopener noreferrer\">La oposici\u00f3n afila el discurso y desaf\u00eda el relato de Llaryora<\/a><\/p>\n<p>Fue all\u00ed donde Juez dej\u00f3 definiciones sin rodeos. Ante los suyos, explicit\u00f3 la estrategia del t\u00e1ndem que conforma con La Libertad Avanza: \u201cNosotros ya empezamos a trabajar en el Frente C\u00edvico nuestra alianza con La Libertad Avanza por<strong> la reelecci\u00f3n del Presidente (Javier Milei)<\/strong>. Y a partir de hoy empezamos a trabajar en serio para <strong>terminar con el ciclo del peronismo en C\u00f3rdoba<\/strong>\u201d, lanz\u00f3 el senador, marcando los dos objetivos centrales del armado, y celebrado con un fuerte aplazo por el diputado Bornoroni. <\/p>\n<p>No obstante, la foto del binomio libertario junto al referente radical lleg\u00f3 despu\u00e9s cuando <strong>se encontraron en la Municipalidad de Laboulaye<\/strong>, gobernada por<strong> Luis Chiapello<\/strong>, intendente de Juntos por el Cambio.<\/p>\n<p><picture><source media=\"(max-width: 440px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2026\/02\/01\/440\/0\/juez-de-loredo-y-bornoroni-con-el-intendente-chiapello-2179210.jpeg?webp\"><source media=\"(max-width: 1019px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2026\/02\/01\/712\/0\/juez-de-loredo-y-bornoroni-con-el-intendente-chiapello-2179210.jpeg?webp\"><img alt=\"Juez, De Loredo y Bornoroni con el intendente Chiapello\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/02\/mas-que-una-foto-juez-bornoroni-y-de-loredo-mostraron-una-senal-de-convergencia-opositora-en-laboulaye.jpg\" loading=\"lazy\"><\/picture><\/p>\n<p>All\u00ed, Juez, Bornoroni y De Loredo compartieron <strong>una charla que deriv\u00f3 en la foto m\u00e1s comentada de la jornada<\/strong>: los tres principales dirigentes opositores juntos, en la previa del discurso del gobernador <strong>Mart\u00edn Llaryora<\/strong> para inaugurar el nuevo per\u00edodo de sesiones de la Unicameral.<\/p>\n<p>La imagen fue le\u00edda como <strong>una se\u00f1al promisoria para buena parte de la dirigencia opositora<\/strong>, que ve en esa coincidencia un primer paso hacia una eventual alianza electoral en 2027. Sin embargo, puertas adentro n<strong>adie apura definiciones.<\/strong> Las <strong>estrategias <\/strong>est\u00e1n sobre la mesa y, por ahora, transitan <strong>carriles paralelos.<\/strong><\/p>\n<p>El esquema <strong>Juez\u2013Bornoroni <\/strong>exhibe un rumbo claro, <strong>alineado con el proyecto nacional de Javier Milei y con la meta<\/strong> expl\u00edcita <strong>de disputar el poder provincial.<\/strong> De Loredo, en cambio, trabaja en l<strong>a reconstrucci\u00f3n del m\u00fasculo partidario radical<\/strong>, con el objetivo de reordenar la UCR cordobesa y recuperar centralidad pol\u00edtica desde la estructura.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/https:\/\/www.perfil.com\/noticias\/cordoba\/llaryora-vuelve-a-alambrar-cordoba-los-ejes-de-la-gestion-con-el-rumbo-en-2027.phtml\" rel=\"noopener noreferrer\">Llaryora vuelve a \u201calambrar\u201d C\u00f3rdoba: los ejes de la gesti\u00f3n con el rumbo en 2027<\/a><\/p>\n<p>Distintas t\u00e1cticas, pero un mismo objetivo: <strong>despojar al peronismo del control de la provincia despu\u00e9s de casi tres d\u00e9cadas<\/strong>. Aunque no se habl\u00f3 de acuerdos electorales ni de listas, el clima del encuentro dej\u00f3 en evidencia <strong>una voluntad pol\u00edtica de convergencia,<\/strong> al menos en el plano estrat\u00e9gico.<\/p>\n<p>En las reuniones con el intendente local y las espadas legislativas <strong>hubo llamados a la unidad opositora, expresiones que fueron celebradas <\/strong>y que refuerzan la idea de que, m\u00e1s all\u00e1 de los tiempos y los nombres, el escenario de alianzas ya empez\u00f3 a jugarse rumbo al 2027.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No fue una postal casual ni un gesto aislado. En Laboulaye, los tres principales referentes de la oposici\u00f3n cordobesa coincidieron en una escena cargada de simbolismo pol\u00edtico, en una ciudad que por un d\u00eda se convirti\u00f3 en epicentro del tablero provincial. Luis Juez, Gabriel Bornoroni y Rodrigo de Loredo compartieron territorio, agenda y mensajes, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":183676,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183675"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=183675"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/183676"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=183675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=183675"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=183675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}