{"id":183373,"date":"2026-01-30T18:26:33","date_gmt":"2026-01-30T18:26:33","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/murio-alfredo-davicce-historico-expresidente-river-festejo-titulos-club-rey-america-anos-noventa_0_VVtvuOqpFP.html"},"modified":"2026-01-30T18:26:33","modified_gmt":"2026-01-30T18:26:33","slug":"murio-alfredo-davicce-historico-expresidente-de-river-que-festejo-nueve-titulos-con-el-club-y-fue-rey-de-america-en-los-anos-noventa","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/30\/murio-alfredo-davicce-historico-expresidente-de-river-que-festejo-nueve-titulos-con-el-club-y-fue-rey-de-america-en-los-anos-noventa\/","title":{"rendered":"Muri\u00f3 Alfredo Davicce, hist\u00f3rico expresidente de River que festej\u00f3 nueve t\u00edtulos con el club y fue rey de Am\u00e9rica en los a\u00f1os noventa"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/murio-alfredo-davicce-historico-expresidente-de-river-que-festejo-nueve-titulos-con-el-club-y-fue-rey-de-america-en-los-anos-noventa.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/murio-alfredo-davicce-historico-expresidente-de-river-que-festejo-nueve-titulos-con-el-club-y-fue-rey-de-america-en-los-anos-noventa-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"element-body-0\" readability=\"62\">\n<p>El expresidente de <strong>River Alfredo Davicce<\/strong>, quien condujo los destinos del club entre 1989 y 1997, y luego fue vicepresidente de la instituci\u00f3n otros cuatro a\u00f1os, falleci\u00f3 este viernes a los 96 a\u00f1os en la Ciudad de Buenos Aires.<\/p>\n<\/div>\n<div id=\"element-body-1\" readability=\"63\">\n<p>Davicce, quien naci\u00f3 el 17 de noviembre de 1929 y se gradu\u00f3 como licenciado en Econom\u00eda y contador p\u00fablico, comenz\u00f3 a participar en la vida institucional de River a principios de la d\u00e9cada de 1960. Fue vocal, miembro del Consejo de F\u00fatbol y luego presidente del Departamento de F\u00fatbol durante la presidencia de Juli\u00e1n William Kent (1968-1973).<\/p>\n<\/div>\n<div id=\"element-body-2\" readability=\"64\">\n<p>En 1983 fue candidato a presidente, pero fue vencido por Hugo Santilli. Sin embargo, seis a\u00f1os m\u00e1s tarde tuvo revancha: al mando de la lista de la agrupaci\u00f3n Cruzada de Unidad Riverplatense, derrot\u00f3 al candidato oficialista Osvaldo Di Carlo y se convirti\u00f3 en el 20\u00b0 presidente en la historia del <em>Millonario<\/em>. <strong>Cuatro a\u00f1os despu\u00e9s, fue reelecto para un nuevo per\u00edodo<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-3\" readability=\"68\">\n<p>Durante sus ocho a\u00f1os de gesti\u00f3n, el equipo de f\u00fatbol de River obtuvo nueve t\u00edtulos: la Copa Libertadores 1996, la Supercopa 1997, el Campeonato Argentino 1989\/90, los torneos Apertura de 1991, 1993, 1994, 1996, y 1997, y el Clausura 1997.<\/p>\n<\/div>\n<div id=\"element-body-5\" readability=\"62\">\n<p>Davicce fue impulsor de un modelo empresarial aplicado al club e promovi\u00f3 un gerenciamiento al que se resist\u00edan muchos dirigentes y que finalmente no lleg\u00f3 a concretarse, pese a que hubo negociaciones avanzadas con la empresa Hicks, Muse, Tate &amp; Furst.<\/p>\n<\/div>\n<div id=\"element-body-6\" readability=\"65\">\n<p>\u201cHicimos lo posible (por convertir a River en una empresa). Siempre con un panel de ejecutivos muy importantes y luchando contra mis pares que creen que nosotros tenemos que ser protagonistas. Yo siempre sue\u00f1o con que seamos nada m\u00e1s que directores, que fijemos la pol\u00edtica. Hay que dejar a los ejecutivos trabajar y opinar, y que pongan el gancho a un costado antes de que lo ponga yo. Si es un contrato, el abogado; si es un jugador, el t\u00e9cnico\u201d, afirm\u00f3 en una entrevista publicada en P\u00e1gina\/12 en 1999.<\/p>\n<\/div>\n<div id=\"element-body-7\" readability=\"62\">\n<p>Despu\u00e9s de completar sus ocho a\u00f1os como presidente, Davicce ocup\u00f3 la vicepresidencia primera de la instituci\u00f3n durante el mandato de su sucesor, David Pintado (1997-2001), y tambi\u00e9n encabez\u00f3 otra vez el Consejo de F\u00fatbol.<\/p>\n<\/div>\n<div id=\"element-body-8\" readability=\"60\">\n<p>Fue una semana dif\u00edcil para el club de N\u00fa\u00f1ez en cuanto a p\u00e9rdidas. En estos d\u00edas tambi\u00e9n se dio a conocer el fallecimiento de otro hist\u00f3rico exdirigente de la instituci\u00f3n como M\u00e1ximo Sabbag, parte de la estructura riverplatense desde los a\u00f1os ochenta.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El expresidente de River Alfredo Davicce, quien condujo los destinos del club entre 1989 y 1997, y luego fue vicepresidente de la instituci\u00f3n otros cuatro a\u00f1os, falleci\u00f3 este viernes a los 96 a\u00f1os en la Ciudad de Buenos Aires. Davicce, quien naci\u00f3 el 17 de noviembre de 1929 y se gradu\u00f3 como licenciado en Econom\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":183374,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183373"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=183373"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/183373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/183374"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=183373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=183373"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=183373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}