{"id":182788,"date":"2026-01-25T14:43:51","date_gmt":"2026-01-25T14:43:51","guid":{"rendered":"https:\/\/somoscordobeses.com\/2026\/01\/25\/desarticularon-una-fiesta-clandestina-donde-habia-mas-de-500-personas\/"},"modified":"2026-01-25T14:43:51","modified_gmt":"2026-01-25T14:43:51","slug":"desarticularon-una-fiesta-clandestina-donde-habia-mas-de-500-personas","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/25\/desarticularon-una-fiesta-clandestina-donde-habia-mas-de-500-personas\/","title":{"rendered":"Desarticularon una fiesta clandestina donde hab\u00eda m\u00e1s de 500 personas"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/desarticularon-una-fiesta-clandestina-donde-habia-mas-de-500-personas.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><strong>Un fuerte operativo se despleg\u00f3 este domingo en horas de la madrugada para desarticular una fiesta clandestina que hab\u00eda congregado a&nbsp;m\u00e1s de 500 personas en un predio ubicado en Villa Esqui\u00fa, en la ciudad de C\u00f3rdoba.<\/strong><\/p>\n<p>El evento se realizaba en calle Las Chacras y Pasaje S\/N y se pudo constatar la presencia de una gran cantidad de personas.<\/p>\n<p>Los efectivos policiales, en colaboraci\u00f3n con personal municipal del \u00c1rea de Fiscalizaci\u00f3n y Control de la Municipalidad, constataron que el establecimiento no se encontraba con la habilitaci\u00f3n correspondiente para la realizaci\u00f3n del evento.&nbsp;<\/p>\n<p>Se dispuso la inmediata desarticulaci\u00f3n de la fiesta y al secuestro de equipos de comunicaci\u00f3n, consolas de sonido y la estructura de un escenario, entre otros elementos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un fuerte operativo se despleg\u00f3 este domingo en horas de la madrugada para desarticular una fiesta clandestina que hab\u00eda congregado a&nbsp;m\u00e1s de 500 personas en un predio ubicado en Villa Esqui\u00fa, en la ciudad de C\u00f3rdoba. El evento se realizaba en calle Las Chacras y Pasaje S\/N y se pudo constatar la presencia de una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":182789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/182788"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=182788"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/182788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/182789"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=182788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=182788"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=182788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}