{"id":182745,"date":"2026-01-24T21:30:02","date_gmt":"2026-01-24T21:30:02","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/24\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video\/"},"modified":"2026-01-24T21:30:02","modified_gmt":"2026-01-24T21:30:02","slug":"el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/24\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video\/","title":{"rendered":"El &#8216;\u00d1igre&#8217;, la curiosa escultura venezolana que pas\u00f3 de la burla a la viralidad (VIDEO)"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video.jpg\"><\/p>\n<p>Una peculiar escultura en el oriente de Venezuela ha provocado&nbsp;reacciones contradictorias en la poblaci\u00f3n desde su inauguraci\u00f3n: desde la burla por sus evidentes errores de proporci\u00f3n&nbsp;al reclamo de los habitantes de El Tigre, que se opusieron a su retiro.<\/p>\n<p>El monumento fue bautizado como&nbsp;&#8216;El Tigre&#8217;. La obra pretend\u00eda emular la figura de ese animal&nbsp;y <strong>fue inaugurada en 2010 en la ciudad de El Tigre<\/strong>, en el estado Anzo\u00e1tegui, a prop\u00f3sito del 77 aniversario&nbsp;de la urbe.<\/p>\n<p>Tras su inauguraci\u00f3n llegaron las burlas, puesto que la escultura es algo deforme: tiene las patas demasiado delgadas, la columna desviada y la cara ligeramente achatada. En tono de chanza, los<strong>&nbsp;pobladores la bautizaron como &#8216;El \u00d1igre&#8217;<\/strong>.<\/p>\n<p>En diciembre de 2022, el parador tur\u00edstico donde&nbsp;se encontraba el monumento fue reinaugurado y las autoridades pusieron en su lugar a otra escultura, la de un tigre m\u00e1s &#8216;realista&#8217;, con mejor acabado.&nbsp;Sin embargo, el cambio no fue del agrado de&nbsp;los ciudadanos, que exigieron el retorno de su&nbsp;&#8216;El \u00d1igre&#8217;.<\/p>\n<figure class=\"RTImage-root\">\n<div class=\"RTImage-image RTImage-original\"><picture class=\"Picture-root Picture-original\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg 850w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg 1960w\"><source srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg 460w, http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg 980w\"><!--[if IE 9]><\/video><![endif]--><img data-sizes=\"auto\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg\" class=\"Picture-root Picture-original lazyload\" alt><\/picture><!-- noscript pattern --><noscript><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-nigre-la-curiosa-escultura-venezolana-que-paso-de-la-burla-a-la-viralidad-video-2.jpg\" alt><\/noscript><\/div><figcaption class=\"RTImage-footer\"><span class=\"RTImage-caption\"><span class=\"RTImage-captionItem\">Estatua que sustituy\u00f3 a la de &#8216;El \u00d1igre&#8217;<\/span><\/span><span class=\"RTImage-source\"><span class=\"RTImage-captionItem\"> Redes sociales <\/span><\/span><\/figcaption><\/figure>\n<p>En mayo de 2024, el&nbsp;&nbsp;actual&nbsp;fiscal general de Venezuela, Tarek William Saab, reinaugur\u00f3 la controvertida estatua, a la que defini\u00f3 como un <strong>\u00abmonumento \u00edcono\u00bb y \u00abs\u00edmbolo\u00bb de la ciudad de El Tigre<\/strong>.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet\" data-twitter=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"es\" dir=\"ltr\"><a href=\"https:\/\/twitter.com\/hashtag\/HOY?src=hash&amp;ref_src=twsrc%5Etfw\">#HOY<\/a> 18 de mayo 2024 visitando a mi amado pueblo natal El Tigre ( Anzo\u00e1tegui)he tenido la oportunidad de reinaugurar bajo los auspicios de la FUNDACI\u00d3N NEMER SAAB el monumento mas ic\u00f3nico que construimos dentro del parador tur\u00edstico en honor a esta bella ciudad Se trata\u2026 <a href=\"https:\/\/t.co\/Px0QzEhfqp\">pic.twitter.com\/Px0QzEhfqp<\/a><\/p>\n<p>\u2014 Tarek William Saab (@TarekWiliamSaab) <a href=\"https:\/\/twitter.com\/TarekWiliamSaab\/status\/1791951576317190395?ref_src=twsrc%5Etfw\">May 18, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>En su cuenta en X, Saab agreg\u00f3 en esa oportunidad: \u00abQuedar\u00e1n en el desprecio y el olvido todo aquel micro grupo de odiadores que hicieron campa\u00f1as de guerra sucia para que el mismo fuera destruido y derribado por turbas violentas: haciendo rid\u00edculas mofas solo por el hecho de ser nosotros los creadores de ese legendario monumento. <strong>Ya los veremos aqu\u00ed a todos ellos haciendo &#8216;selfies&#8217;&nbsp; y grabando videos<\/strong>\u00ab.<\/p>\n<p>De hecho, la popularidad de la escultura se puede constatar en redes sociales, donde su aparici\u00f3n suele conquistar miles de likes por parte de los usuarios que &#8216;peregrinan&#8217; para conocer al singular felino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una peculiar escultura en el oriente de Venezuela ha provocado&nbsp;reacciones contradictorias en la poblaci\u00f3n desde su inauguraci\u00f3n: desde la burla por sus evidentes errores de proporci\u00f3n&nbsp;al reclamo de los habitantes de El Tigre, que se opusieron a su retiro. El monumento fue bautizado como&nbsp;&#8216;El Tigre&#8217;. La obra pretend\u00eda emular la figura de ese animal&nbsp;y fue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":182746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/182745"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=182745"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/182745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/182746"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=182745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=182745"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=182745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}