{"id":180454,"date":"2026-01-04T17:11:16","date_gmt":"2026-01-04T17:11:16","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/04\/el-ataque-de-estados-unidos-a-venezuela-adios-a-la-seguridad-regional\/"},"modified":"2026-01-04T17:11:16","modified_gmt":"2026-01-04T17:11:16","slug":"el-ataque-de-estados-unidos-a-venezuela-adios-a-la-seguridad-regional","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/04\/el-ataque-de-estados-unidos-a-venezuela-adios-a-la-seguridad-regional\/","title":{"rendered":"El ataque de Estados Unidos a Venezuela: \u00bfAdi\u00f3s a la seguridad regional?."},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/el-ataque-de-estados-unidos-a-venezuela-adios-a-la-seguridad-regional.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Termin\u00f3 el tiempo de las palabras. Ya no son s\u00f3lo amenazas. Ni gestos. Estados Unidos, bajo el mando del presidente Donald Trump, atac\u00f3 finalmente a Venezuela, bombardeando bases militares importantes (Fuerte Tiuna y La Carlota) y otros sectores de Caracas.<\/p>\n<p>Trump hab\u00eda avanzado demasiado y cerr\u00f3 ese ataque capturando y llev\u00e1ndose del pa\u00eds a Nicol\u00e1s Maduro. Las discrepancias sobre Venezuela, el tema de los Derechos Humanos, el grado en que se pueda juzgar a Maduro no logra tapar un escenario internacional cada vez m\u00e1s visible: La fuerza vuelve a regir en el mundo, incluso m\u00e1s que nunca.<\/p>\n<p>La Doctrina Monroe con sus cambios y posteriores interpretaciones, el Corolario Roosevelt o la pol\u00edtica exterior (\u201cBig Stick\u201d), todo eso sumado al \u201cAmerica First\u201d de Trump se convierten en grandes protagonistas del contexto global actual.<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<p>El derecho internacional, basti\u00f3n de defensa (o intento de la misma) para los pa\u00edses m\u00e1s d\u00e9biles, parece perder cada vez m\u00e1s peso cada d\u00eda y hubo una clar violaci\u00f3n de la Carta de Naciones Unidas, ya que Estados Unidos atac\u00f3 a Venezuela sin que mediara una situaci\u00f3n de \u201cleg\u00edtima defensa\u201d. No hubo ataques de Venezuela a EE.UU. y seguramente tampoco habr\u00e1 sanciones del Consejo de Seguridad a la administraci\u00f3n Trump.<\/p>\n<p>Incluso en el hip\u00f3tetico caso que los otros cuatro miembros permanentes del Consejo (Rusia, China, Francia e Inglaterra) votaran alg\u00fan tipo de cuestionamiento, Estados Unidos obviamente se opondr\u00eda y sin unanimidad no hay sanciones posibles. En consecuencia, si los organismos internacionales no pueden sancionar a potencias, a ra\u00edz de ese poder de veto que tienen todos, \u00bfqu\u00e9 pasar\u00e1 con pa\u00edses d\u00e9biles, o que osen &#8216;contrariar&#8217; a la Casa Blanca?.<\/p>\n<p>Cuando cambie el gobierno argentino, tal vez con otra pol\u00edtica econ\u00f3mica, o la diplomacia tenga otro rumbo, \u00bfcu\u00e1l ser\u00e1 el margen de maniobra de nuestro pa\u00eds?. \u00bfQu\u00e9 pasar\u00eda en ese cuadro con la deuda externa? Si el derecho internacional no es suficiente, la Doctrina Drago (que plantea la igualdad soberana y la imposibilidad del cobro de deuda mediante la fuerza) \u00bftendr\u00e1 alguna validez?<\/p>\n<p>El precedente que sienta el ataque estadounidense a Venezuela pone en peligro no s\u00f3lo a la regi\u00f3n misma, sino que deja en jaque a la diplomacia y el derecho internacional. Un mundo manejado de forma autoritaria por las grandes potencias se convierte en un escenario cada vez m\u00e1s visible. Rusia con Ucrania, China con Taiw\u00e1n y Estados Unidos con Am\u00e9rica Latina o el Caribe. La receta de la resoluci\u00f3n de conflictos tanto en Ucrania como en Venezuela ha sido la fuerza.<\/p>\n<p>Las declaraciones de Trump en su conferencia de ayer fueron impactantes: \u201cGobernaremos Venezuela hasta lograr una transici\u00f3n segura (&#8230;)\u201d y \u201cse mantendr\u00e1n en Venezuela el tiempo que sea necesario hasta conseguir una transici\u00f3n ordenada (\u2026) vamos a dirigir el pa\u00eds hasta lograr la transici\u00f3n ordenada\u201d . Agreg\u00f3 un sinceramiento feroz: la ambici\u00f3n por el petr\u00f3leo. \u201cEstados Unidos reconstruir\u00e1 la infraestructura de petr\u00f3leo para generar dinero para nuestro pa\u00eds\u201d, se\u00f1al\u00f3 sin medias tintas.<\/p>\n<p>Trump record\u00f3 que \u201cVenezuela ha expropiado los bienes de Estados Unidos (\u2026), plataformas que hab\u00edamos construido nosotros\u201d. Y adem\u00e1s anticip\u00f3 \u201cEstados Unidos est\u00e1 preparado para un segundo ataque incluso m\u00e1s fuerte de ser necesario\u201d. Fue una amenaza directa a lo que queda del chavismo en Venezuela: acceden a &#8216;colaborar&#8217; con la transici\u00f3n&#8230; o volver\u00e1n los helic\u00f3pteros y los cazas.<\/p>\n<p>\u00abLa alianza de Venezuela con Estados Unidos ser\u00e1 una alianza de las que lograr\u00e1 que el pueblo de Venezuela sea rico, independiente y seguro\u201d, areng\u00f3 Trump.<\/p>\n<p>Los cargos que presenta Estados Unidos contra Maduro son severos y anticipan pesada condena: \u201cTr\u00e1fico de drogas letales que \u201cingresan a Estados Unidos mediante el cartel de \u201cLos Soles\u201d. Trump menciona tener \u201cevidencias claras de delitos que ser\u00e1n presentadas ante un tribunal de justicia\u201d.<\/p>\n<p>\u201cMaduro ya no podr\u00e1 enviar a sus bandas bajo \u00f3rdenes del Tren de Aragua a amenazar a ciudadanos estadounidenses ni a venezolanos\u201d, dijo el l\u00edder republicano, \u201cmuchas veces Maduro vaci\u00f3 sus c\u00e1rceles para enviar a sus peores monstruos a robar vidas estadounidenses (\u2026), ya no permitiremos eso en nuestro propio hemisferio\u201d.<\/p>\n<p> La suerte de Maduro est\u00e1 echada, y la del continente, parece lejos del derecho y la paz.<\/p>\n<p><em><strong>* Lic. en Ciencias Pol\u00edticas<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Termin\u00f3 el tiempo de las palabras. Ya no son s\u00f3lo amenazas. Ni gestos. Estados Unidos, bajo el mando del presidente Donald Trump, atac\u00f3 finalmente a Venezuela, bombardeando bases militares importantes (Fuerte Tiuna y La Carlota) y otros sectores de Caracas. Trump hab\u00eda avanzado demasiado y cerr\u00f3 ese ataque capturando y llev\u00e1ndose del pa\u00eds a Nicol\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":180455,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/180454"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=180454"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/180454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/180455"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=180454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=180454"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=180454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}