{"id":180035,"date":"2026-01-01T16:41:34","date_gmt":"2026-01-01T16:41:34","guid":{"rendered":"https:\/\/www.clarin.com\/deportes\/llama-riquelme-firmamos-deseo-voz-alta-guino-lucas-torreira-llegar-boca_0_S6aVhc40c0.html"},"modified":"2026-01-01T16:41:34","modified_gmt":"2026-01-01T16:41:34","slug":"si-me-llama-riquelme-cuando-firmamos-el-deseo-en-voz-alta-y-el-guino-de-lucas-torreira-para-llegar-a-boca","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2026\/01\/01\/si-me-llama-riquelme-cuando-firmamos-el-deseo-en-voz-alta-y-el-guino-de-lucas-torreira-para-llegar-a-boca\/","title":{"rendered":"\u201c\u00bfSi me llama Riquelme?, \u00bfcu\u00e1ndo firmamos?\u201d: el deseo en voz alta y el gui\u00f1o de Lucas Torreira para llegar a Boca"},"content":{"rendered":"<p><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/si-me-llama-riquelme-cuando-firmamos-el-deseo-en-voz-alta-y-el-guino-de-lucas-torreira-para-llegar-a-boca.jpg\"><\/p>\n<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2026\/01\/si-me-llama-riquelme-cuando-firmamos-el-deseo-en-voz-alta-y-el-guino-de-lucas-torreira-para-llegar-a-boca-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<div id=\"element-body-0\" readability=\"66\">\n<p><strong>Boca <\/strong>vuelve este viernes a los trabajos tras las vacaciones que comenzaron luego de la eliminaci\u00f3n con Racing en las semifinales del Torneo Clausura. Ser\u00e1 con <strong>Claudio \u00dabeda<\/strong> al frente del plantel y, por ahora, sin refuerzos, ya que no termin\u00f3 de destrabarse la llegada del colombiano <strong>Marino Hinestroza<\/strong>. Mientras tanto, hay un futbolista que sali\u00f3 a postularse para llegar al club de La Ribera. Se trata del internacional uruguayo <strong>Lucas Torreira<\/strong>, quien volvi\u00f3 a manifestar p\u00fablicamente su deseo de ponerse la casaca azul y oro. Aunque hay un asterisco nada menor: aclar\u00f3 que su llegada no se concretar\u00e1 en el corto plazo debido a que tiene contrato vigente hasta mediados de 2028 con <strong>Galatasaray<\/strong>, donde es titular indiscutido.<\/p>\n<\/div>\n<div id=\"element-body-1\" readability=\"66\">\n<p>En una entrevista con el medio uruguayo <em>Somos Fix<\/em>, el mediocampista, que el 11 de febrero pr\u00f3ximo cumplir\u00e1 30 a\u00f1os, no anduvo con vueltas.<strong> \u201cEs el deseo m\u00e1s grande que tengo yo como jugador de f\u00fatbol. No hay un d\u00eda que no piense en ese momento\u201d,<\/strong> afirm\u00f3, y agreg\u00f3 en tono distendido: <strong>\u201c\u00bfSi me llama Riquelme?, \u00bfcu\u00e1ndo firmamos?\u201d.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\" readability=\"62\">\n<p>El futbolista nacido en Fray Bentos cont\u00f3 que recientemente mantuvo una charla clave con <strong>Edinson Cavani<\/strong> que lo hizo reflexionar sobre su futuro. \u201cHace poco tiempo habl\u00e9 con <em>Edi<\/em> y tuvimos una conversaci\u00f3n muy importante. Ojal\u00e1 se d\u00e9 jugar en Boca y despu\u00e9s ir a Uruguay a jugar en alg\u00fan equipo\u201d, se\u00f1al\u00f3, aunque reconoci\u00f3 que hoy su presente deportivo est\u00e1 enfocado en Europa.<\/p>\n<\/div>\n<div id=\"element-body-3\" readability=\"63\">\n<p>No es la primera vez que Torreira declara su simpat\u00eda por Boca. En entrevistas anteriores, cont\u00f3 que su v\u00ednculo emocional con el club naci\u00f3 en la infancia, influenciado por un entorno familiar atravesado por el f\u00fatbol y por el consumo habitual de transmisiones del f\u00fatbol argentino. Incluso record\u00f3 momentos emblem\u00e1ticos como la despedida de <strong>Mart\u00edn Palermo<\/strong>, el \u00faltimo partido de <strong>Juan Rom\u00e1n Riquelme<\/strong> y el regreso de <strong>Carlos Tevez<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-4\" readability=\"66\">\n<p>El grado de identificaci\u00f3n con el club de la Ribera fue tal que, tras la muerte de su madre, evalu\u00f3 seriamente dejar Europa para jugar en Boca. En ese contexto, tambi\u00e9n dej\u00f3 en claro que su idea es llegar en plenitud futbol\u00edstica y no en el cierre de su carrera. Hoy, adem\u00e1s de su buen presente en Galatasaray, integra el radar de Marcelo Bielsa en el armado definitivo de la lista de la selecci\u00f3n de Uruguay de cara al<strong> Mundial de Canad\u00e1, M\u00e9xico y Estados Unidos 2026.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-5\" readability=\"63\">\n<p>La carrera de Torreira se desarroll\u00f3 \u00edntegramente en Europa desde su salida de su pa\u00eds a los 17 a\u00f1os. Tras destacarse en <strong>Pescara <\/strong>y <strong>Sampdoria<\/strong>, fue transferido al Arsenal en 2018. Luego tuvo pasos por<strong> Atl\u00e9tico de Madrid<\/strong> y <strong>Fiorentina<\/strong>, antes de firmar con el todopoderoso club turco en 2022, donde actualmente transita su cuarta temporada.<\/p>\n<\/div>\n<div id=\"element-body-6\" readability=\"64\">\n<p>Torreira, tiempo atr\u00e1s, revel\u00f3 que mantiene di\u00e1logo frecuente con Riquelme y que incluso lo contact\u00f3 para brindarle apoyo tras la eliminaci\u00f3n de Boca en la Libertadores 2020. Rom\u00e1n lo considera una opci\u00f3n a largo plazo y, seg\u00fan su entorno, avanzar\u00e1 por su contrataci\u00f3n cuando las condiciones deportivas y contractuales lo permitan.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Boca vuelve este viernes a los trabajos tras las vacaciones que comenzaron luego de la eliminaci\u00f3n con Racing en las semifinales del Torneo Clausura. Ser\u00e1 con Claudio \u00dabeda al frente del plantel y, por ahora, sin refuerzos, ya que no termin\u00f3 de destrabarse la llegada del colombiano Marino Hinestroza. Mientras tanto, hay un futbolista que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":180036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/180035"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=180035"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/180035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/180036"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=180035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=180035"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=180035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}