{"id":177383,"date":"2025-12-09T15:42:37","date_gmt":"2025-12-09T15:42:37","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=84043"},"modified":"2025-12-09T15:42:37","modified_gmt":"2025-12-09T15:42:37","slug":"passerini-hoy-el-mundo-reconoce-lo-que-los-cordobeses-sentimos-desde-siempre-el-cuarteto-es-cultura-es-pueblo-y-es-corazon","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2025\/12\/09\/passerini-hoy-el-mundo-reconoce-lo-que-los-cordobeses-sentimos-desde-siempre-el-cuarteto-es-cultura-es-pueblo-y-es-corazon\/","title":{"rendered":"Passerini: \u201cHoy el mundo reconoce lo que los cordobeses sentimos desde siempre: el cuarteto es cultura, es pueblo y es coraz\u00f3n\u201d"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/12\/passerini-hoy-el-mundo-reconoce-lo-que-los-cordobeses-sentimos-desde-siempre-el-cuarteto-es-cultura-es-pueblo-y-es-corazon.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong>El intendente de C\u00f3rdoba expres\u00f3 su alegr\u00eda por la declaraci\u00f3n de la UNESCO del cuarteto como Patrimonio Cultural Inmaterial de la Humanidad.<\/strong><\/li>\n<\/ul>\n<hr>\n<p>El 9 de diciembre ser\u00e1 otra fecha importante en la historia de la ciudad de C\u00f3rdoba. Tras una candidatura impulsada desde 2022 por la Municipalidad de C\u00f3rdoba, este martes la UNESCO declar\u00f3 al cuarteto como Patrimonio Cultural Inmaterial de la Humanidad.<\/p>\n<p><em>\u201cHoy el mundo reconoce lo que los cordobeses sentimos desde siempre: el cuarteto es cultura, es pueblo y es coraz\u00f3n\u201d<\/em>, resalt\u00f3 con orgullo el intendente Passerini en la red social X, tras conocerse el dictamen de la comisi\u00f3n evaluadora que analiz\u00f3 la candidatura argentina.<\/p>\n<p><em>\u201cEl cuarteto es parte de nuestra identidad y de nuestra historia. Nos une, nos alegra y nos acompa\u00f1a siempre: en el colectivo, en el auto, en las fiestas, en los asados. Y tambi\u00e9n en las escuelas, donde ya lo transmitimos a las nuevas generaciones\u201d<\/em>, destac\u00f3 el intendente respecto al cuarteto, tan cordob\u00e9s que tambi\u00e9n forma parte de los contenidos curriculares en las escuelas y jardines municipales.<\/p>\n<p><em>\u201cComo dice La Mona, los cordobeses cuarteteamos hasta morir\u201d<\/em>, aprovech\u00f3 Passerini para citar a uno de los m\u00e1ximos representantes del g\u00e9nero: Carlos \u201cLa Mona\u201d Jim\u00e9nez.<\/p>\n<p>La noticia lleg\u00f3 temprano desde Nueva Delhi, India, a m\u00e1s de 16 mil kil\u00f3metros de C\u00f3rdoba, ahora Capital Mundial del Cuarteto.<\/p>\n<p>Vishal Sharma, presidente del Comit\u00e9 Intergubernamental para la Salvaguardia del Patrimonio Cultural Inmaterial de la UNESCO, cedi\u00f3 la palabra al representante del \u00f3rgano de evaluaci\u00f3n de la candidatura, denominada \u201cCuarteto, m\u00fasica, danza y letra en la ciudad de C\u00f3rdoba, Argentina\u201d.<\/p>\n<p><em>\u201cEl Cuarteto contribuye a reforzar el sentimiento de unidad y de identidad local. Es popular no solo en las comunidades obreras, sino tambi\u00e9n en otros grupos sociales, fomenta el di\u00e1logo intercultural y la apreciaci\u00f3n de la diversidad cultural, entre otros aspectos del desarrollo sostenible\u201d<\/em>, fueron algunas caracter\u00edsticas valoradas, previo a la declaraci\u00f3n tan esperada.<\/p>\n<p><em>\u201cEl \u00f3rgano de evaluaci\u00f3n recomienda la inscripci\u00f3n del elemento en la lista representativa del Patrimonio Cultural Inmaterial de la Humanidad\u201d<\/em>, dictaminaron desde el \u00f3rgano evaluador, felicitando a la Municipalidad de C\u00f3rdoba <em>\u201cpor haber integrado este elemento en el sistema educativo destinado a los ni\u00f1os\u201d<\/em>. La decisi\u00f3n qued\u00f3 grabada bajo el n\u00famero 20 COM 7.b.4<\/p>\n<p>Todo comenz\u00f3 en 2022 cuando el entonces intendente (hoy gobernador) Mart\u00edn Llaryora inici\u00f3 la candidatura ante la UNESCO. A mediados de 2024, el intendente Daniel Passerini anunci\u00f3 la admisi\u00f3n del Cuarteto para integrar la lista del Patrimonio Inmaterial de la Humanidad, paso preliminar al proceso de evaluaci\u00f3n que concluy\u00f3 este martes 9 de diciembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de C\u00f3rdoba expres\u00f3 su alegr\u00eda por la declaraci\u00f3n de la UNESCO del cuarteto como Patrimonio Cultural Inmaterial de la Humanidad. El 9 de diciembre ser\u00e1 otra fecha importante en la historia de la ciudad de C\u00f3rdoba. Tras una candidatura impulsada desde 2022 por la Municipalidad de C\u00f3rdoba, este martes la UNESCO declar\u00f3 al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":177384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/177383"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=177383"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/177383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/177384"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=177383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=177383"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=177383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}