{"id":176660,"date":"2025-12-03T13:43:22","date_gmt":"2025-12-03T13:43:22","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=83831"},"modified":"2025-12-03T13:43:22","modified_gmt":"2025-12-03T13:43:22","slug":"el-elenco-municipal-de-danza-teatro-celebra-20-anos-con-un-espectaculo-gratuito","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2025\/12\/03\/el-elenco-municipal-de-danza-teatro-celebra-20-anos-con-un-espectaculo-gratuito\/","title":{"rendered":"El Elenco Municipal de Danza Teatro celebra 20 a\u00f1os con un espect\u00e1culo gratuito"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/12\/el-elenco-municipal-de-danza-teatro-celebra-20-anos-con-un-espectaculo-gratuito.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong>Presenta la obra \u201cAscochinga \u2013 la vida todav\u00eda\u201d, los d\u00edas viernes y s\u00e1bado, desde las 20:00 en el Teatro Comedia.<\/strong><\/li>\n<\/ul>\n<hr>\n<p>Llega al Teatro Comedia la nueva creaci\u00f3n del Elenco Municipal de Danza Teatro. Se trata de la obra \u201cAsconchinga \u2013 la otra vida\u201d, una coproducci\u00f3n entre la Municipalidad de C\u00f3rdoba y el Instituto Italiano de Cultura para festejar las dos d\u00e9cadas del cuerpo art\u00edstico.<\/p>\n<p>Las funciones tendr\u00e1n lugar este viernes 5 y s\u00e1bado 6, a las 20:00, con entradas gratuitas hasta que sea ocupada la totalidad de la sala. Los boletos se pueden obtener desde una hora antes en Rivadavia 254.<\/p>\n<p>La producci\u00f3n conecta la inmigraci\u00f3n y el envejecer en una experiencia visual y l\u00fadica. Se proponen im\u00e1genes, movimiento y recuerdos con la intenci\u00f3n de edificar una po\u00e9tica de la ternura atravesada por el paso del tiempo, donde el Elenco Municipal de Danza Teatro har\u00e1 un trabajo pl\u00e1stico, actoral, y esc\u00e9nico con el uso de m\u00e1scaras.<\/p>\n<p>Seg\u00fan revelan sus responsables, se trata de un espect\u00e1culo que mixtura la profundidad de migrar y reconstruirse. Para lograr este cometido, la puesta en escena cuenta con la colaboraci\u00f3n de Luca Pacella, un core\u00f3grafo italiano que vive en C\u00f3rdoba desde hace muchos a\u00f1os.<\/p>\n<p>Elenco Municipal de Danza y Teatro<\/p>\n<p>Desde el 2005 recorre lugares que forman parte del patrimonio hist\u00f3rico y espacios barriales como plazas, centros vecinales y escuelas municipales, entre otros. En sus presentaciones contempla m\u00faltiples est\u00e9ticas, combinando actuaciones para infancias y personas adultas. Promueve las artes esc\u00e9nicas con calidad y acceso gratuito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presenta la obra \u201cAscochinga \u2013 la vida todav\u00eda\u201d, los d\u00edas viernes y s\u00e1bado, desde las 20:00 en el Teatro Comedia. Llega al Teatro Comedia la nueva creaci\u00f3n del Elenco Municipal de Danza Teatro. Se trata de la obra \u201cAsconchinga \u2013 la otra vida\u201d, una coproducci\u00f3n entre la Municipalidad de C\u00f3rdoba y el Instituto Italiano de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":176661,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/176660"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=176660"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/176660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/176661"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=176660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=176660"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=176660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}