{"id":176537,"date":"2025-12-02T14:29:20","date_gmt":"2025-12-02T14:29:20","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=83837"},"modified":"2025-12-02T14:29:20","modified_gmt":"2025-12-02T14:29:20","slug":"gran-convocatoria-de-aspirantes-para-el-ingreso-al-sistema-educativo-municipal","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2025\/12\/02\/gran-convocatoria-de-aspirantes-para-el-ingreso-al-sistema-educativo-municipal\/","title":{"rendered":"Gran convocatoria de aspirantes para el ingreso al Sistema Educativo Municipal"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/12\/gran-convocatoria-de-aspirantes-para-el-ingreso-al-sistema-educativo-municipal.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<ul>\n<li><strong>M\u00e1s de 600 profesionales participaron del Concurso Abierto para cubrir cargos docentes en los distintos niveles y modalidades.<\/strong><\/li>\n<\/ul>\n<hr>\n<p>La Municipalidad de C\u00f3rdoba, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n, informa que se registr\u00f3 una gran participaci\u00f3n en el Concurso Abierto para el ingreso al Sistema Educativo Municipal (SEM), destinado a cubrir espacios disponibles en los distintos niveles y modalidades que forman parte de la red educativa de la ciudad.<\/p>\n<p>M\u00e1s de 600 aspirantes presentaron sus carpetas para rendir el examen, reflejando el inter\u00e9s, la vocaci\u00f3n y el compromiso de docentes y profesionales por integrarse a las instituciones municipales.<\/p>\n<p>Entre ellos se encuentran postulantes para el nivel inicial y primario, as\u00ed como tambi\u00e9n para \u00e1reas especiales, como Educaci\u00f3n F\u00edsica, Artes Visuales, Ingl\u00e9s, M\u00fasica, Danza, Teatro y EDIPRO y la modalidad de J\u00f3venes y Adultos.<\/p>\n<p>Desde la Secretar\u00eda de Educaci\u00f3n se destac\u00f3 que la amplia convocatoria refuerza el objetivo de continuar fortaleciendo un sistema educativo s\u00f3lido, transparente y con oportunidades de formaci\u00f3n y desarrollo profesional para todos y todas, garantizando a su vez trayectorias educativas de calidad para ni\u00f1as, ni\u00f1os, j\u00f3venes y personas adultas de la ciudad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 600 profesionales participaron del Concurso Abierto para cubrir cargos docentes en los distintos niveles y modalidades. La Municipalidad de C\u00f3rdoba, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n, informa que se registr\u00f3 una gran participaci\u00f3n en el Concurso Abierto para el ingreso al Sistema Educativo Municipal (SEM), destinado a cubrir espacios disponibles en los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":176538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/176537"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=176537"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/176537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/176538"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=176537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=176537"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=176537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}