{"id":173811,"date":"2025-11-06T17:38:36","date_gmt":"2025-11-06T17:38:36","guid":{"rendered":"https:\/\/cordobabeat.com\/?p=13420"},"modified":"2025-11-06T17:38:36","modified_gmt":"2025-11-06T17:38:36","slug":"driving-time-el-track-debut-de-alejo-fochi-en-or-two-strangers-el-sello-de-antrim","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2025\/11\/06\/driving-time-el-track-debut-de-alejo-fochi-en-or-two-strangers-el-sello-de-antrim\/","title":{"rendered":"Driving Time, el track debut de Alejo Fochi en Or Two Strangers, el sello de Antrim"},"content":{"rendered":"<div><img src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/11\/driving-time-el-track-debut-de-alejo-fochi-en-or-two-strangers-el-sello-de-antrim.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p data-start=\"459\" data-end=\"1008\"><span>El s\u00e1bado <\/span><strong data-start=\"1020\" data-end=\"1038\">8 de noviembre<\/strong><span>, Fochi se presentar\u00e1 en <\/span><strong data-start=\"1069\" data-end=\"1100\">Fruta Bar (San Lorenzo 288)<\/strong><span>, con <\/span><strong data-start=\"1106\" data-end=\"1153\">entrada libre y gratuita desde las 12.30 hs<\/strong><span>. Ser\u00e1 su <\/span><strong data-start=\"1162\" data-end=\"1202\">cuarta fecha en C\u00f3rdoba durante 2025<\/strong><span>, en un a\u00f1o donde el artista hab\u00eda combinado lanzamientos, giras y nuevas experiencias internacionales.<\/span><\/p>\n<p data-start=\"1307\" data-end=\"1883\">Durante la temporada, el productor recorri\u00f3 escenarios de <strong data-start=\"1372\" data-end=\"1402\">Argentina, Brasil y Europa<\/strong>, con presentaciones en <strong data-start=\"1426\" data-end=\"1450\">MUTE (Mar del Plata)<\/strong>, <strong data-start=\"1452\" data-end=\"1474\">Ultra Buenos Aires<\/strong>, <strong data-start=\"1476\" data-end=\"1486\">Crobar<\/strong>, <strong data-start=\"1488\" data-end=\"1505\">Florian\u00f3polis<\/strong>, <strong data-start=\"1507\" data-end=\"1519\">Mallorca<\/strong>, <strong data-start=\"1521\" data-end=\"1530\">Ibiza<\/strong>, <strong data-start=\"1532\" data-end=\"1545\">Barcelona<\/strong>, <strong data-start=\"1547\" data-end=\"1558\">Ushuaia<\/strong> y <strong data-start=\"1561\" data-end=\"1573\">La Plata<\/strong>, entre otros destinos.<\/p>\n<p>El 2025 tambi\u00e9n hab\u00eda significado su <strong data-start=\"1636\" data-end=\"1653\">debut europeo<\/strong>, con actuaciones en clubes ic\u00f3nicos como <strong data-start=\"1695\" data-end=\"1726\">The Supermercat (Barcelona)<\/strong>, <strong data-start=\"1728\" data-end=\"1747\">Lemuria (Ibiza)<\/strong> y <strong data-start=\"1750\" data-end=\"1777\">Es Moli Club (Mallorca)<\/strong>, reafirmando su proyecci\u00f3n internacional y su b\u00fasqueda art\u00edstica dentro del <strong data-start=\"1854\" data-end=\"1882\">progressive house global<\/strong>.<\/p>\n<p data-start=\"1885\" data-end=\"2296\">Respaldado por figuras como <strong data-start=\"1913\" data-end=\"1932\">Hern\u00e1n Catt\u00e1neo<\/strong> y <strong data-start=\"1935\" data-end=\"1950\">Nick Warren<\/strong>, su m\u00fasica hab\u00eda sonado en festivales y en el m\u00edtico programa <strong data-start=\"2013\" data-end=\"2025\">Resident<\/strong>.<\/p>\n<p>De cara al 2026, Fochi se preparaba para concretar uno de los hitos m\u00e1s importantes de su carrera: su <strong data-start=\"2131\" data-end=\"2165\">lanzamiento en The Soundgarden<\/strong>, el sello de Nick Warren, que lo posicionar\u00eda entre los <strong data-start=\"2222\" data-end=\"2262\">talentos argentinos m\u00e1s prometedores<\/strong> de la escena electr\u00f3nica mundial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 8 de noviembre, Fochi se presentar\u00e1 en Fruta Bar (San Lorenzo 288), con entrada libre y gratuita desde las 12.30 hs. Ser\u00e1 su cuarta fecha en C\u00f3rdoba durante 2025, en un a\u00f1o donde el artista hab\u00eda combinado lanzamientos, giras y nuevas experiencias internacionales. Durante la temporada, el productor recorri\u00f3 escenarios de Argentina, Brasil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":173812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[24,1],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/173811"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=173811"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/173811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/173812"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=173811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=173811"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=173811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}