{"id":173631,"date":"2025-11-07T13:30:00","date_gmt":"2025-11-07T13:30:00","guid":{"rendered":"http:\/\/cordobainforma.info\/index.php\/2025\/11\/07\/mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico\/"},"modified":"2025-11-07T13:30:00","modified_gmt":"2025-11-07T13:30:00","slug":"mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico","status":"publish","type":"post","link":"http:\/\/cordobainforma.info\/index.php\/2025\/11\/07\/mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico\/","title":{"rendered":"Mar del Plata: el abismo de la separaci\u00f3n de pareja y la necesidad de soltar lo que resulta t\u00f3xico"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<p>El s\u00e1bado 4 de octubre subi\u00f3 a escena en <strong>N\u00fcn Teatro Bar<\/strong> (Juan Ram\u00edrez de Velasco 419, CABA) la obra <strong>Mar del Plata,<\/strong> una comedia que rompe con el molde de su g\u00e9nero. Escrita y dirigida por <strong>Bel Eiff, <\/strong>esta pieza teatral sumerge al espectador en una historia donde, lejos de enamorarse,<strong> los protagonistas est\u00e1n tratando de separarse.<\/strong> La obra presenta a Claudio (<strong>Jes\u00fas Catalino<\/strong>) y&nbsp;a Virginia (<strong>Roc\u00edo Ambrosoni)<\/strong> <strong>en el hall de un edificio de la ciudad balnearia,<\/strong> al atardecer de un d\u00eda de invierno. Lo que comienza como una simple despedida <strong>se transforma r\u00e1pidamente en un campo de batalla de reproches,<\/strong> recuerdos distorsionados y una intimidad tan densa que, por momentos, se ve interrumpida por otros personajes (<strong>Nazareno Gil y Violeta Brener<\/strong>) que intentan acceder al ascensor. Claudio y Virginia se pelean, se amigan y se vuelven a pelear. Quieren separarse y saben que ser\u00eda lo mejor, pero no pueden. En el fondo,<strong> este encuentro es una lucha por soltarse.<\/strong><\/p>\n<p><picture><source media=\"(max-width: 440px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2025\/10\/30\/440\/0\/1030mardelplata-2128474.jpg?webp\"><source media=\"(max-width: 1019px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2025\/10\/30\/712\/0\/1030mardelplata-2128474.jpg?webp\"><img alt=\"1030_mardelplata\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/11\/mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico.jpg\" loading=\"lazy\"><\/picture><\/p>\n<p>La autora y directora<strong> Bel Eiff <\/strong>explica en una entrevista exclusiva la g\u00e9nesis de esta propuesta que invierte el clich\u00e9: \u00ab<em>Es anticomedia en el sentido que en las comedias rom\u00e1nticas en general vemos c\u00f3mo los personajes se encuentran, \u00bfviste de d\u00f3nde vienen y c\u00f3mo van a empezar su historia de amor? Y ac\u00e1 vemos justamente el momento apuesto: c\u00f3mo se separan<\/em>\u00ab. Ella<strong> busc\u00f3 explorar la dificultad de soltar aquello que se cree querer <\/strong>o que se piensa que hace bien, i<strong>ncluso cuando es t\u00f3xico<\/strong>. \u201c<em>Ten\u00eda ganas de hablar justamente de separarse, de la situaci\u00f3n de separarse de algo que quer\u00e9s mucho, pens\u00e1s que te hace bien cuando quiz\u00e1s no te hace bien. Uno se aferra a esa idea, a esa fantas\u00eda, a algo conocido\u201d<\/em>, comenta la directora, quien concibi\u00f3 este texto tras su trabajo en<strong> Ah\u00ed, lectura perform\u00e1tica para 6 actores.<\/strong><br \/>Adem\u00e1s<strong>, la obra sit\u00faa al amor en un plano m\u00e1s complejo:<\/strong> \u201c<em>Quise escribir una comedia rom\u00e1ntica donde el amor tambi\u00e9n puede ser violencia y donde la intimidad, de tan cercana, resulta inc\u00f3moda. El v\u00ednculo entre los personajes no est\u00e1 en lo que dicen, sino en lo que se puede ver y sentir\u201d<\/em>. Aqu\u00ed la entrevista completa:<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<h2>El peso de la ciudad y el texto vivo<\/h2>\n<p>La elecci\u00f3n de Mar del Plata como escenario no es casual, sino<strong> un motor de resonancia emocional para el p\u00fablico.<\/strong> \u00ab<em>Me parec\u00eda interesante para situarte como espectador en un lugar y que eso te traiga tus propios recuerdos que se mezclan con lo que ves en escena\u00bb,<\/em> explica. Al haber escrito el texto ya con la puesta en escena en mente, la directora prioriz\u00f3 el ritmo y la acci\u00f3n de los int\u00e9rpretes. \u201c<em>Me preocup\u00e9 en que textos que los actores dicen sean f\u00e1ciles de expresar, que no se les enreden, que sean cortitos, que tenga ritmo, que sean como m\u00e1s cercanos\u201d<\/em>, comenta la autora, quien destaca la ventaja del teatro para seguir \u00ab<em>imaginando posibilidades dentro de la obra ya est\u00e1 hecha\u00bb,<\/em> ajustando r\u00e9plicas y transiciones durante los ensayos.<\/p>\n<p><picture><source media=\"(max-width: 440px)\" srcset=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/11\/mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico.webp\"><source media=\"(max-width: 1019px)\" srcset=\"https:\/\/fotos.perfil.com\/\/2025\/10\/30\/712\/0\/1030mardelplata-2128472.jpg?webp\"><img alt=\"1030_mardelplata\" src=\"http:\/\/cordobainforma.info\/wp-content\/uploads\/2025\/11\/mar-del-plata-el-abismo-de-la-separacion-de-pareja-y-la-necesidad-de-soltar-lo-que-resulta-toxico-1.jpg\" loading=\"lazy\"><\/picture><\/p>\n<p>Aunque la directora (que tiene 39 a\u00f1os) pens\u00f3 inicialmente que la obra hablar\u00eda a la franja de 30 a 40, <strong>descubri\u00f3 una conexi\u00f3n generacional m\u00e1s amplia:<\/strong> <em>\u00abLa gente de 20 y pico que se reengancha, y los m\u00e1s grandes me ha dicho: &#8216;Me hizo acordar a cuando era joven&#8217; o que se emocionan. La obra tiene condimentos de relaciones m\u00e1s nuevas, pero con los mismos dolores de siempre\u00bb<\/em>. La puesta tiene escenograf\u00eda y vestuario de<strong> Sof\u00eda Innocenti, <\/strong>dise\u00f1o de iluminaci\u00f3n de<strong> Jessica Tortul <\/strong>y producci\u00f3n de <strong>Brenda Kreizerman.<\/strong> Las funciones son los<strong> s\u00e1bados a las 22.30. <\/strong>Encontr\u00e1 <a target=\"_blank\" href=\"https:\/\/www.alternativateatral.com\/obra97112-mar-del-plata\" rel=\"noopener noreferrer\">ac\u00e1 <\/a>m\u00e1s info sobre las entradas.<\/p>\n<div class=\"article__tags\">\n<p>En esta Nota<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El s\u00e1bado 4 de octubre subi\u00f3 a escena en N\u00fcn Teatro Bar (Juan Ram\u00edrez de Velasco 419, CABA) la obra Mar del Plata, una comedia que rompe con el molde de su g\u00e9nero. Escrita y dirigida por Bel Eiff, esta pieza teatral sumerge al espectador en una historia donde, lejos de enamorarse, los protagonistas est\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":173632,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/173631"}],"collection":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/comments?post=173631"}],"version-history":[{"count":0,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/posts\/173631\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media\/173632"}],"wp:attachment":[{"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/media?parent=173631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/categories?post=173631"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobainforma.info\/index.php\/wp-json\/wp\/v2\/tags?post=173631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}